{"id":62282,"date":"2023-11-27T19:41:22","date_gmt":"2023-11-27T10:41:22","guid":{"rendered":"https:\/\/monolith.law\/ko\/?p=62282"},"modified":"2024-03-15T19:47:33","modified_gmt":"2024-03-15T10:47:33","slug":"delete-false-positive-arrest","status":"publish","type":"post","link":"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest","title":{"rendered":"\uc798\ubabb\ub41c \uccb4\ud3ec\uc5d0 \ub300\ud55c \uccb4\ud3ec \uc774\ub825\uc758 \uc0ad\uc81c\ub294 \uac00\ub2a5\ud55c\uac00?"},"content":{"rendered":"\n<p>\uc2e0\ubb38\uc744 \ube44\ub86f\ud55c \ub9ce\uc740 \ub274\uc2a4 \uc0ac\uc774\ud2b8\uc5d0\uc11c\ub294 \ud2b9\uc815 \uac1c\uc778\uc774 \uccb4\ud3ec\ub418\uc5c8\ub2e4\ub294 \ub274\uc2a4\uac00 \uc790\uc8fc \uac8c\uc7ac\ub429\ub2c8\ub2e4. \uadf8\ub7ec\ub098 \uadf8 \uc0ac\ub78c\uc774 \ud6c4\uc5d0 \uae30\uc18c\ub418\uc5c8\ub294\uc9c0, \uc7ac\ud310\uc5d0\uc11c \uc720\uc8c4 \ud310\uacb0\uc744 \ubc1b\uc558\ub294\uc9c0 \ub4f1\uc758 \ub274\uc2a4\ub294 \uc798 \uac8c\uc7ac\ub418\uc9c0 \uc54a\uc2b5\ub2c8\ub2e4. \uc774\uac83\uc740 \uccb4\ud3ec\ub41c \uc0ac\ub78c\uc5d0\uac8c \ub9e4\uc6b0 \uc2ec\uac01\ud55c \ubb38\uc81c\uc785\ub2c8\ub2e4. \uc989,<\/p>\n\n\n\n<ul>\n<li>\ud655\uc2e4\ud788 \uccb4\ud3ec\ub294 \ub418\uc5c8\uc9c0\ub9cc, \uba85\ud655\ud55c \uc624\uc778 \uccb4\ud3ec\ub85c \uae30\uc18c\ub418\uc9c0 \uc54a\uc558\ub2e4<\/li>\n\n\n\n<li>\ud655\uc2e4\ud788 \uccb4\ud3ec\ub294 \ub418\uc5c8\uc9c0\ub9cc, \uacb0\uad6d \uc758\ud639\uc774 \ubd80\uc871\ud558\uc5ec \uae30\uc18c\ub418\uc9c0 \uc54a\uc558\ub2e4<\/li>\n\n\n\n<li>\uccb4\ud3ec\ub418\uace0 \uae30\uc18c\uae4c\uc9c0 \ub418\uc5c8\uc9c0\ub9cc, \uc7ac\ud310\uc5d0\uc11c \uc624\uc778 \uccb4\ud3ec\uc600\uc74c\uc774 \ubd84\uba85\ud574\uc9c0\uace0 \ubb34\uc8c4 \ud310\uacb0\uc744 \ubc1b\uc558\ub2e4<\/li>\n<\/ul>\n\n\n\n<p>\uc640 \uac19\uc740 \uacbd\uc6b0\uc5d0\ub3c4,<\/p>\n\n\n\n<ol>\n<li>\uccb4\ud3ec \ub2f9\uc2dc\uc758 \ub274\uc2a4\uac00 \uc778\ud130\ub137\uc5d0 \uac8c\uc7ac\ub418\uace0<\/li>\n\n\n\n<li>\uadf8\uac83\uc774 5\ucc44\ub110\uc774\ub098 2\ucc44\ub110 \ub4f1\uc758 \uac8c\uc2dc\ud310 \uc0ac\uc774\ud2b8, \uac1c\uc778 \ube14\ub85c\uadf8 \ub4f1\uc5d0 \uc804\uc7ac\ub418\uace0<\/li>\n\n\n\n<li>\ubd88\uae30\uc18c \ucc98\ubd84\uc774\ub098 \ubb34\uc8c4 \ud310\uacb0 \uc2dc\uc5d0\ub3c4 \uc815\uc815 \ub4f1\uc774 \uc774\ub8e8\uc5b4\uc9c0\uc9c0 \uc54a\uace0, \uc778\ud130\ub137\uc5d0 \uadf8\ub300\ub85c \ub0a8\uc544\uc788\uac8c \ub41c\ub2e4<\/li>\n<\/ol>\n\n\n\n<p>\ub294 \uacbd\uc6b0\uac00 \uc788\uae30 \ub54c\ubb38\uc785\ub2c8\ub2e4. \uacb0\uacfc\uc801\uc73c\ub85c \uc624\uc778 \uccb4\ud3ec\uc600\ub354\ub77c\ub3c4 &#8216;\uccb4\ud3ec\ub418\uc5c8\ub2e4&#8217;\ub294 \uc0ac\uc2e4\uc774 \uc778\ud130\ub137\uc5d0 \uacc4\uc18d \ub0a8\uc544\uc788\uc73c\uba74, \uadf8\uac83\uc744 \ubcf8 \uc0ac\ub78c\uc740 &#8216;\uadf8 \uc0ac\ub78c\uc774 \ubc94\uc8c4\ub97c \uc800\uc9c8\ub800\ub2e4&#8217;\uace0 \uc0dd\uac01\ud558\uac8c \ub420 \uac83\uc785\ub2c8\ub2e4. \uc608\ub97c \ub4e4\uc5b4, \uc774\ub984 \uac80\uc0c9\uc5d0\uc11c \uc704\uc640 \uac19\uc740 \uccb4\ud3ec \uae30\uc0ac\uac00 \uac80\uc0c9\ub418\uba74, \uc77c\ubc18 \uc9c1\uc6d0\uc758 \uacbd\uc6b0 \uc774\uc9c1 \ub4f1\uc758 \uc0c1\ud669, \uae30\uc5c5 \uacbd\uc601\uc790\ub77c\uba74 \uc0ac\uc5c5 \uc81c\ud734 \ub4f1\uc758 \uacc4\uc57d \uccb4\uacb0 \uc0c1\ud669, \uc790\uae08 \uc870\ub2ec \uc0c1\ud669 \ub4f1\uc5d0\uc11c \uc911\ub300\ud55c \ubd88\uc774\uc775\uc774 \ubc1c\uc0dd\ud558\uac8c \ub429\ub2c8\ub2e4.<\/p>\n\n\n\n<p>\uc774\ub7f0 \uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc5d0 \uad00\ud55c \uc778\ud130\ub137 \uae30\uc0ac\ub97c \uc0ad\uc81c\ud560 \uc218 \uc788\uc744\uae4c\uc694?<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EC%B2%98%EC%9D%8C%EB%B6%80%ED%84%B0_%EC%B2%B4%ED%8F%AC_%EA%B8%B0%EC%82%AC%EC%9D%98_%EC%82%AD%EC%A0%9C%EA%B0%80_%EA%B0%80%EB%8A%A5%ED%95%9C_%EA%B2%83%EC%9D%B8%EA%B0%80\" title=\"\ucc98\uc74c\ubd80\ud130 \uccb4\ud3ec \uae30\uc0ac\uc758 \uc0ad\uc81c\uac00 \uac00\ub2a5\ud55c \uac83\uc778\uac00\">\ucc98\uc74c\ubd80\ud130 \uccb4\ud3ec \uae30\uc0ac\uc758 \uc0ad\uc81c\uac00 \uac00\ub2a5\ud55c \uac83\uc778\uac00<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EC%9E%98%EB%AA%BB%EB%90%9C_%EC%B2%B4%ED%8F%AC%EC%9D%98_%EA%B2%BD%EC%9A%B0_%EC%96%B4%EB%96%BB%EA%B2%8C_%EC%83%9D%EA%B0%81%ED%95%B4%EC%95%BC_%ED%95%A0%EA%B9%8C\" title=\"\uc798\ubabb\ub41c \uccb4\ud3ec\uc758 \uacbd\uc6b0 \uc5b4\ub5bb\uac8c \uc0dd\uac01\ud574\uc57c \ud560\uae4c?\">\uc798\ubabb\ub41c \uccb4\ud3ec\uc758 \uacbd\uc6b0 \uc5b4\ub5bb\uac8c \uc0dd\uac01\ud574\uc57c \ud560\uae4c?<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%E2%80%98%EC%A0%84%EA%B3%BC_%EB%93%B1%EC%9D%84_%ED%95%A8%EB%B6%80%EB%A1%9C_%EA%B3%B5%EA%B0%9C%ED%95%98%EC%A7%80_%EC%95%8A%EB%8A%94_%EC%9D%B4%EC%9D%B5%E2%80%99%EC%9D%98_%EA%B3%A0%EB%A0%A4_%EC%9A%94%EC%86%8C\" title=\"&#8216;\uc804\uacfc \ub4f1\uc744 \ud568\ubd80\ub85c \uacf5\uac1c\ud558\uc9c0 \uc54a\ub294 \uc774\uc775&#8217;\uc758 \uace0\ub824 \uc694\uc18c\">&#8216;\uc804\uacfc \ub4f1\uc744 \ud568\ubd80\ub85c \uacf5\uac1c\ud558\uc9c0 \uc54a\ub294 \uc774\uc775&#8217;\uc758 \uace0\ub824 \uc694\uc18c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%ED%98%90%EC%9D%98_%EB%B6%80%EC%A1%B1%EC%9D%B4%EB%82%98_%ED%83%80%ED%98%91%EC%97%90_%EC%9D%98%ED%95%9C_%EB%B6%88%EA%B8%B0%EC%86%8C%EC%9D%98_%EA%B2%BD%EC%9A%B0%EB%8A%94\" title=\"\ud610\uc758 \ubd80\uc871\uc774\ub098 \ud0c0\ud611\uc5d0 \uc758\ud55c \ubd88\uae30\uc18c\uc758 \uacbd\uc6b0\ub294?\">\ud610\uc758 \ubd80\uc871\uc774\ub098 \ud0c0\ud611\uc5d0 \uc758\ud55c \ubd88\uae30\uc18c\uc758 \uacbd\uc6b0\ub294?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EC%9E%98%EB%AA%BB%EB%90%9C_%EC%B2%B4%ED%8F%AC%EC%97%90%EC%84%9C_%ED%95%AD%EC%83%81_%E2%80%98%EA%B3%B5%EA%B0%9C%EC%9D%98_%EC%9D%98%EB%AF%B8%E2%80%99%EA%B0%80_%EC%97%86%EB%8B%A4%EA%B3%A0_%EB%A7%90%ED%95%A0_%EC%88%98_%EC%9E%88%EB%8A%94%EA%B0%80\" title=\"\uc798\ubabb\ub41c \uccb4\ud3ec\uc5d0\uc11c \ud56d\uc0c1 &#8216;\uacf5\uac1c\uc758 \uc758\ubbf8&#8217;\uac00 \uc5c6\ub2e4\uace0 \ub9d0\ud560 \uc218 \uc788\ub294\uac00\">\uc798\ubabb\ub41c \uccb4\ud3ec\uc5d0\uc11c \ud56d\uc0c1 &#8216;\uacf5\uac1c\uc758 \uc758\ubbf8&#8217;\uac00 \uc5c6\ub2e4\uace0 \ub9d0\ud560 \uc218 \uc788\ub294\uac00<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EC%98%A4%EC%9D%B8_%EC%B2%B4%ED%8F%AC%EC%9D%98_%EC%B2%B4%ED%8F%AC_%EC%9D%B4%EB%A0%A5_%EA%B2%8C%EC%8B%9C%EB%8A%94_%EB%AA%85%EC%98%88%ED%9B%BC%EC%86%90%EC%9D%B4_%EB%90%98%EC%A7%80_%EC%95%8A%EB%8A%94%EA%B0%80\" title=\"\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825 \uac8c\uc2dc\ub294 \uba85\uc608\ud6fc\uc190\uc774 \ub418\uc9c0 \uc54a\ub294\uac00\">\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825 \uac8c\uc2dc\ub294 \uba85\uc608\ud6fc\uc190\uc774 \ub418\uc9c0 \uc54a\ub294\uac00<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EC%98%A4%EC%9D%B8_%EC%B2%B4%ED%8F%AC%EC%9D%98_%EC%B2%B4%ED%8F%AC_%EC%9D%B4%EB%A0%A5_%EC%82%AD%EC%A0%9C%EB%8A%94_%EA%B8%B0%EB%B3%B8%EC%A0%81%EC%9C%BC%EB%A1%9C_%EC%9D%B8%EC%A0%95%EB%90%9C%EB%8B%A4\" title=\"\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825 \uc0ad\uc81c\ub294 \uae30\ubcf8\uc801\uc73c\ub85c \uc778\uc815\ub41c\ub2e4\">\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825 \uc0ad\uc81c\ub294 \uae30\ubcf8\uc801\uc73c\ub85c \uc778\uc815\ub41c\ub2e4<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EC%A2%85%ED%95%A9%EC%A0%81_%EA%B3%A0%EB%A0%A4%EC%97%90%EC%84%9C%EB%8A%94_%ED%8C%A8%EB%B0%B0%ED%95%A0_%EA%B0%80%EB%8A%A5%EC%84%B1%EB%8F%84_%EC%9E%88%EB%8B%A4\" title=\"\uc885\ud569\uc801 \uace0\ub824\uc5d0\uc11c\ub294 \ud328\ubc30\ud560 \uac00\ub2a5\uc131\ub3c4 \uc788\ub2e4\">\uc885\ud569\uc801 \uace0\ub824\uc5d0\uc11c\ub294 \ud328\ubc30\ud560 \uac00\ub2a5\uc131\ub3c4 \uc788\ub2e4<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EB%B2%94%EC%A3%84%EB%A5%BC_%EC%A0%80%EC%A7%80%EB%A5%B8_%EA%B2%83%EC%9C%BC%EB%A1%9C_%ED%95%B4%EC%84%9D%EB%90%98%EB%8A%94_%EA%B2%83%EC%9D%B4_%EB%AC%B8%EC%A0%9C%EC%9D%98_%EB%B3%B8%EC%A7%88\" title=\"\ubc94\uc8c4\ub97c \uc800\uc9c0\ub978 \uac83\uc73c\ub85c \ud574\uc11d\ub418\ub294 \uac83\uc774 \ubb38\uc81c\uc758 \ubcf8\uc9c8\">\ubc94\uc8c4\ub97c \uc800\uc9c0\ub978 \uac83\uc73c\ub85c \ud574\uc11d\ub418\ub294 \uac83\uc774 \ubb38\uc81c\uc758 \ubcf8\uc9c8<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EA%B1%B0%EC%A7%93_%EC%82%AC%EC%8B%A4%EC%97%90_%EC%9D%98%ED%95%9C_%EC%82%AC%ED%9A%8C%EC%A0%81_%EB%B6%88%EC%9D%B4%EC%9D%B5%EC%9D%80_%EB%AA%85%EC%98%88%ED%9B%BC%EC%86%90_%EB%AC%B8%EC%A0%9C\" title=\"\uac70\uc9d3 \uc0ac\uc2e4\uc5d0 \uc758\ud55c \uc0ac\ud68c\uc801 \ubd88\uc774\uc775\uc740 \uba85\uc608\ud6fc\uc190 \ubb38\uc81c\">\uac70\uc9d3 \uc0ac\uc2e4\uc5d0 \uc758\ud55c \uc0ac\ud68c\uc801 \ubd88\uc774\uc775\uc740 \uba85\uc608\ud6fc\uc190 \ubb38\uc81c<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EB%AA%85%EC%98%88%ED%9B%BC%EC%86%90_%EC%9A%94%EA%B1%B4%EC%9D%B4_%EC%B6%A9%EC%A1%B1%EB%90%98%EB%A9%B4_%EC%82%AD%EC%A0%9C%EA%B0%80_%ED%99%95%EC%8B%A4%ED%9E%88_%EC%9D%B8%EC%A0%95%EB%90%A8\" title=\"\uba85\uc608\ud6fc\uc190 \uc694\uac74\uc774 \ucda9\uc871\ub418\uba74 \uc0ad\uc81c\uac00 \ud655\uc2e4\ud788 \uc778\uc815\ub428\">\uba85\uc608\ud6fc\uc190 \uc694\uac74\uc774 \ucda9\uc871\ub418\uba74 \uc0ad\uc81c\uac00 \ud655\uc2e4\ud788 \uc778\uc815\ub428<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EC%98%A4%EC%9D%B8_%EC%B2%B4%ED%8F%AC%EC%9D%98_%EC%B2%B4%ED%8F%AC_%EC%9D%B4%EB%A0%A5%EC%9D%80_%ED%95%AD%EC%83%81_%EC%82%AD%EC%A0%9C%EB%90%98%EC%96%B4%EC%95%BC_%ED%95%A8\" title=\"\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc740 \ud56d\uc0c1 \uc0ad\uc81c\ub418\uc5b4\uc57c \ud568\">\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc740 \ud56d\uc0c1 \uc0ad\uc81c\ub418\uc5b4\uc57c \ud568<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/monolith.law\/ko\/internet\/delete-false-positive-arrest\/#%EC%9A%94%EC%95%BD\" title=\"\uc694\uc57d\">\uc694\uc57d<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EC%B2%98%EC%9D%8C%EB%B6%80%ED%84%B0_%EC%B2%B4%ED%8F%AC_%EA%B8%B0%EC%82%AC%EC%9D%98_%EC%82%AD%EC%A0%9C%EA%B0%80_%EA%B0%80%EB%8A%A5%ED%95%9C_%EA%B2%83%EC%9D%B8%EA%B0%80\"><\/span>\ucc98\uc74c\ubd80\ud130 \uccb4\ud3ec \uae30\uc0ac\uc758 \uc0ad\uc81c\uac00 \uac00\ub2a5\ud55c \uac83\uc778\uac00<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\uc774 \ubb38\uc81c\uc5d0 \ub300\ud574 \uc0dd\uac01\ud574\ubcf4\uae30 \uc704\ud574\uc11c\ub294, \uba3c\uc800, \uc624\uc778 \uccb4\ud3ec\uc774\ub358, \uacb0\uacfc\uc801\uc73c\ub85c \uc720\uc8c4 \ud310\uacb0\uc774 \ub0b4\ub824\uc9c4 \uacbd\uc6b0\uc774\ub358, \uc77c\ubc18\uc801\uc73c\ub85c \uccb4\ud3ec \uc774\ub825\uc758 \uc0ad\uc81c\uc5d0 \ub300\ud55c \uad00\uc810\uc744 \uc774\ud574\ud558\ub294 \uac83\uc774 \ud544\uc694\ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<p>\uc5b4\ub5a4 \uac1c\uc778\uc774 \uccb4\ud3ec\ub418\uc5c8\ub2e4\ub294 \uc0ac\uc2e4\uc740, \uadf8 \uac1c\uc778\uc5d0\uac8c\ub294 \ud504\ub77c\uc774\ubc84\uc2dc \ubb38\uc81c\uc785\ub2c8\ub2e4. \uadf8\ub9ac\uace0 \uae30\ubcf8\uc801\uc778 \uad00\uc810\uc73c\ub85c\uc11c\ub294,<\/p>\n\n\n\n<ol>\n<li>\uccb4\ud3ec \uc774\ub825\uc5d0 \uad00\ud55c \uc815\ubcf4\ub294 \uadf8 \uac1c\uc778\uc758 \ud504\ub77c\uc774\ubc84\uc2dc\uc5d0 \uad00\ub828\ub41c\ub2e4<\/li>\n\n\n\n<li>\uadf8\ub7ec\ub098 \ud504\ub77c\uc774\ubc84\uc2dc\ub294 \ubb34\uc81c\ud55c \uad8c\ub9ac\uac00 \uc544\ub2c8\uba70, \uacf5\uacf5\uc801\uc778 \uc815\ubcf4\uc778 \uacbd\uc6b0, \uc77c\uc815\ud55c \uc81c\uc57d\uc744 \ubc1b\ub294 \uac83\uc740 \ubd88\uac00\ud53c\ud558\ub2e4<\/li>\n\n\n\n<li>\uadf8\ub807\uc9c0\ub9cc, \uacbd\ubbf8\ud55c \ubc94\uc8c4 \ub4f1\uc758 \uacbd\uc6b0, \uc2e4\uba85\uc744 \uc5b8\uae09\ud558\uba70 \uccb4\ud3ec \uc774\ub825\uc744 \uc778\ud130\ub137\uc5d0 \uac8c\uc2dc\ud558\ub294 \ud544\uc694\uc131\uc740 \uc560\ub9e4\ud558\ub2e4<\/li>\n\n\n\n<li>\ud2b9\ud788, \uccb4\ud3ec \uc774\ud6c4 \uc77c\uc815 \uae30\uac04\uc774 \uacbd\uacfc\ud55c \uacbd\uc6b0, \uc704\uc758 \ud544\uc694\uc131\uc740 \uc774\ubbf8 \uc0c1\uc2e4\ub418\uc5c8\uc744 \uc218\ub3c4 \uc788\ub2e4<\/li>\n<\/ol>\n\n\n\n<p>\ub77c\ub294 \ud615\ud0dc\uac00 \ub429\ub2c8\ub2e4. \ud310\ub840\ub294 \uc774\ub7ec\ud55c \uccb4\ud3ec \uc774\ub825\uc774\ub098 \uc804\uacfc\uc5d0 \uad00\ud55c \ud504\ub77c\uc774\ubc84\uc2dc\ub97c &#8216;\uc804\uacfc \ub4f1\uc744 \ud568\ubd80\ub85c \uacf5\ud45c\ub418\uc9c0 \uc54a\ub294 \uc774\uc775&#8217;\uc774\ub77c\uace0 \ubd80\ub985\ub2c8\ub2e4.<\/p>\n\n\n\n<p>\uadf8\ub9ac\uace0 &#8216;\uccb4\ud3ec \uc774\ub825\uc758 \uc0ad\uc81c&#8217;\ub77c\ub294 \ubb38\uc81c\uc5d0 \ub300\ud55c &#8216;\uccb4\ud3ec \uc774\ud6c4 \uacbd\uacfc \uc2dc\uac04&#8217;\uc5d0 \ub300\ud55c \uc124\uba85\uc740 \uc544\ub798 \uae30\uc0ac\uc5d0\uc11c \uc9c4\ud589\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/necessaryperiod-of-deletion-arrestarticle\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/necessaryperiod-of-deletion-arrestarticle[ja]<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EC%9E%98%EB%AA%BB%EB%90%9C_%EC%B2%B4%ED%8F%AC%EC%9D%98_%EA%B2%BD%EC%9A%B0_%EC%96%B4%EB%96%BB%EA%B2%8C_%EC%83%9D%EA%B0%81%ED%95%B4%EC%95%BC_%ED%95%A0%EA%B9%8C\"><\/span>\uc798\ubabb\ub41c \uccb4\ud3ec\uc758 \uacbd\uc6b0 \uc5b4\ub5bb\uac8c \uc0dd\uac01\ud574\uc57c \ud560\uae4c?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E2%80%98%EC%A0%84%EA%B3%BC_%EB%93%B1%EC%9D%84_%ED%95%A8%EB%B6%80%EB%A1%9C_%EA%B3%B5%EA%B0%9C%ED%95%98%EC%A7%80_%EC%95%8A%EB%8A%94_%EC%9D%B4%EC%9D%B5%E2%80%99%EC%9D%98_%EA%B3%A0%EB%A0%A4_%EC%9A%94%EC%86%8C\"><\/span>&#8216;\uc804\uacfc \ub4f1\uc744 \ud568\ubd80\ub85c \uacf5\uac1c\ud558\uc9c0 \uc54a\ub294 \uc774\uc775&#8217;\uc758 \uace0\ub824 \uc694\uc18c<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\uccb4\ud3ec \uc774\ub825\uc758 \uc0ad\uc81c\uc640 \ud504\ub77c\uc774\ubc84\uc2dc \uce68\ud574\ub77c\ub294 \uc8fc\uc81c\uc5d0\uc11c, \ud310\ub840\ub294 &#8216;\uc804\uacfc \ub4f1\uc744 \ud568\ubd80\ub85c \uacf5\uac1c\ud558\uc9c0 \uc54a\ub294 \uc774\uc775&#8217;\uc5d0 \ub300\ud574 \ub2e4\uc74c\uacfc \uac19\uc740 \uc694\uc18c\ub97c \uace0\ub824\ud574\uc57c \ud560 \uc0ac\ud56d\uc73c\ub85c \uc9c0\uc815\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<ol>\n<li>\ub300\uc0c1\uc790\uc758 \uc18d\uc131\uc5d0 \uad00\ud55c \uc0ac\ud56d<\/li>\n\n\n\n<li>\ub300\uc0c1\uc774 \ub41c \uc0ac\uac74\uc758 \ub0b4\uc6a9\uc5d0 \uad00\ud55c \uc0ac\ud56d<\/li>\n\n\n\n<li>\uacf5\uac1c\uc758 \ubaa9\uc801 \ubc0f \uc758\ubbf8\uc5d0 \uad00\ud55c \uc0ac\ud56d<\/li>\n<\/ol>\n\n\n\n<p>\uc774 \uc810\uc5d0 \ub300\ud574\uc11c\ub294, \uccb4\ud3ec \uc774\ub825\uc758 \uc0ad\uc81c\uc5d0 \uad00\ud55c \uc77c\ubc18\ub860\uc73c\ub85c\uc11c, \uc544\ub798 \uae30\uc0ac\uc5d0\uc11c \uc790\uc138\ud788 \uc124\uba85\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/delete-arrest-history\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/delete-arrest-history[ja]<\/a><\/p>\n\n\n\n<p>\uc798\ubabb\ub41c \uccb4\ud3ec\uc758 \uacbd\uc6b0, \ud2b9\ud788 \ubb38\uc81c\uac00 \ub418\ub294 \uac83\uc740 3\ubc88\uc785\ub2c8\ub2e4. \uacb0\ub860\uc801\uc73c\ub85c, \uadf8 \uc0ac\ub78c\uc774 \ubc94\uc8c4\ub97c \uc800\uc9c0\ub974\uc9c0 \uc54a\uc558\ub2e4\ub294 \uac83\uc774\ubbc0\ub85c, &#8216;\uadf8 \uc0ac\ub78c\uc774 \uccb4\ud3ec\ub418\uc5c8\ub2e4&#8217;\ub294 \uc0ac\uc2e4\uc744 \uacf5\uac1c\ud558\ub294 \uac83\uc5d0 \uc758\ubbf8\uac00 \uc788\ub294\uc9c0\uc5d0 \ub300\ud55c \ubb38\uc81c\uc785\ub2c8\ub2e4.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%ED%98%90%EC%9D%98_%EB%B6%80%EC%A1%B1%EC%9D%B4%EB%82%98_%ED%83%80%ED%98%91%EC%97%90_%EC%9D%98%ED%95%9C_%EB%B6%88%EA%B8%B0%EC%86%8C%EC%9D%98_%EA%B2%BD%EC%9A%B0%EB%8A%94\"><\/span>\ud610\uc758 \ubd80\uc871\uc774\ub098 \ud0c0\ud611\uc5d0 \uc758\ud55c \ubd88\uae30\uc18c\uc758 \uacbd\uc6b0\ub294?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\uadf8\ub7ec\ub098, \uba85\ud655\ud55c \uc798\ubabb\ub41c \uccb4\ud3ec\ub77c\uba74 &#8216;\uacf5\uac1c\uc758 \uc758\ubbf8\ub294 \uc804\ud600 \uc5c6\ub2e4&#8217;\uace0 \ub9d0\ud560 \uc218 \uc788\uc744\uc9c0\ub3c4 \ubaa8\ub974\uc9c0\ub9cc, \ud610\uc758 \ubd80\uc871, \uc774\ubbf8 \ud0c0\ud611\uc774 \uc774\ub8e8\uc5b4\uc9c4 \ub4f1\uc758 \uc774\uc720\ub85c \ubd88\uae30\uc18c \ucc98\ubd84\uc774 \uc774\ub8e8\uc5b4\uc9c4 \uacbd\uc6b0\uc5d0\ub294 &#8216;\uacf5\uac1c\uc758 \uc758\ubbf8\uac00 \uba85\ud655\ud788 \uc874\uc7ac\ud558\uc9c0 \uc54a\ub294\ub2e4&#8217;\uace0\ub294 \ub9d0\ud560 \uc218 \uc5c6\uc744\uc9c0\ub3c4 \ubaa8\ub985\ub2c8\ub2e4. \uc774\ub7f0 \uacbd\uc6b0\uc5d0\ub294, \ubc95\uc815 \uc678 \ud611\uc0c1\uc5d0 \uc758\ud55c \uc0ad\uc81c\ub098 \uac00\ucc98\ubd84\uc5d0 \uc758\ud55c \uc0ad\uc81c \ub4f1\uc758 \uc0c1\ud669\uc5d0\uc11c &#8216;\uad6c\uccb4\uc801\uc778 \ud574\ub2f9 \uc0ac\uac74\uc5d0\uc11c \uacf5\uac1c\uc758 \uc758\ubbf8\uac00 \uc5c6\ub2e4\ub294 \uac83&#8217;\uc744 \uc5b4\ub5bb\uac8c \uc124\ub4dd\ub825 \uc788\uac8c \uc8fc\uc7a5\ud558\ub294\uc9c0\uac00 \uacb0\ub860\uc744 \ub098\ub204\ub294 \uc694\uc18c\uac00 \ub420 \uac83\uc73c\ub85c \uc0dd\uac01\ub429\ub2c8\ub2e4.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EC%9E%98%EB%AA%BB%EB%90%9C_%EC%B2%B4%ED%8F%AC%EC%97%90%EC%84%9C_%ED%95%AD%EC%83%81_%E2%80%98%EA%B3%B5%EA%B0%9C%EC%9D%98_%EC%9D%98%EB%AF%B8%E2%80%99%EA%B0%80_%EC%97%86%EB%8B%A4%EA%B3%A0_%EB%A7%90%ED%95%A0_%EC%88%98_%EC%9E%88%EB%8A%94%EA%B0%80\"><\/span>\uc798\ubabb\ub41c \uccb4\ud3ec\uc5d0\uc11c \ud56d\uc0c1 &#8216;\uacf5\uac1c\uc758 \uc758\ubbf8&#8217;\uac00 \uc5c6\ub2e4\uace0 \ub9d0\ud560 \uc218 \uc788\ub294\uac00<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\ub610\ud55c, \uc774 \uc810\uc5d0 \ub300\ud574 \uae4a\uc774 \ud30c\uace0\ub4e0 \ud310\ub840\ub294 \uc800\ud76c \uc0ac\ubb34\uc18c\uac00 \ud30c\uc545\ud558\uae30\ub85c\ub294 \uc544\uc9c1 \uc874\uc7ac\ud558\uc9c0 \uc54a\ub294 \uac83\uc73c\ub85c \ubcf4\uc785\ub2c8\ub2e4\ub9cc, \uc644\uc804\ud55c \uc758\ubbf8\uc5d0\uc11c\uc758 &#8216;\uc798\ubabb\ub41c \uccb4\ud3ec&#8217;\ub77c \ud574\ub3c4, \ubc14\ub85c 3\ubc88\uc758 \uc758\ubbf8\uc5d0\uc11c &#8216;\uc758\ubbf8&#8217;\uac00 \ud56d\uc0c1 \uc644\uc804\ud788 \uc5c6\ub2e4\uace0 \ub9d0\ud560 \uc218 \uc788\ub294\uc9c0\uc5d0 \ub300\ud574\uc11c\ub294 \ud655\uc2e4\ud558\uc9c0 \uc54a\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<p>\uc608\ub97c \ub4e4\uc5b4, \uc18c\uc704 \uacf5\ubc94\uc758 \uc0ac\ub840\uc5d0\uc11c, \uc8fc\ubc94\uc5d0 \uc758\ud55c \ubc94\uc8c4 \ud589\uc704\uc758 \uc77c\ubd80\ub9cc \uacb0\uacfc\uc801\uc73c\ub85c \uad00\uc5ec\ud558\uac8c \ub41c \uacbd\uc6b0\ub098, \uace0\uc758 \ub4f1\uc774 \ubd80\uc871\ud55c \uacbd\uc6b0, \uadf9\ub2e8\uc801\uc73c\ub85c \ub9d0\ud558\uba74, \uc0b4\uc778\ubc94\uc5d0\uac8c \uce7c\uc744 \ud310\ub9e4\ud55c \uc0c1\uc810 \uc8fc\uc778\uc758 \uacbd\uc6b0\uc785\ub2c8\ub2e4.<\/p>\n\n\n\n<ol>\n<li>\uc0c1\uc810 \uc8fc\uc778\uc774 \uacf5\ubc94\uc73c\ub85c \uccb4\ud3ec\ub41c \uc0ac\uc2e4\uc774<\/li>\n\n\n\n<li>\uadf8 \ud6c4 &#8216;\uc0c1\uc810 \uc8fc\uc778\uc740 \uce7c\uc758 \uc0ac\uc6a9 \ubc29\ubc95\uc5d0 \ub300\ud574 \uc804\ud600 \uc778\uc2dd\ud558\uc9c0 \uc54a\uc558\ub2e4&#8217;\uace0, \uccb4\ud3ec\uac00 \uc798\ubabb\ub418\uc5c8\uc74c\uc774 \ubc1d\ud600\uc838\ub3c4<\/li>\n\n\n\n<li>&#8216;\uce7c\uc774 \uc5b4\ub514\uc5d0\uc11c \uad6c\uc785\ub418\uc5c8\ub294\uc9c0\uc5d0 \ub300\ud55c \uc0ac\uc2e4\uc758 \uacf5\uac1c\uc5d0\ub294 \uc758\ubbf8\uac00 \uc788\ub2e4&#8217;\ub294 \uc774\uc720\ub85c, \ud504\ub77c\uc774\ubc84\uc2dc \uce68\ud574\ub97c \ubd80\uc778\ub2f9\ud558\uac8c \ub420 \uc218 \uc788\ub2e4<\/li>\n<\/ol>\n\n\n\n<p>\ub77c\ub294 \uacbd\uc6b0\ub3c4, \uc77c\ub2e8\uc740 \uc788\uc744 \uc218 \uc788\ub2e4\uace0 \uc0dd\uac01\ub429\ub2c8\ub2e4.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EC%98%A4%EC%9D%B8_%EC%B2%B4%ED%8F%AC%EC%9D%98_%EC%B2%B4%ED%8F%AC_%EC%9D%B4%EB%A0%A5_%EA%B2%8C%EC%8B%9C%EB%8A%94_%EB%AA%85%EC%98%88%ED%9B%BC%EC%86%90%EC%9D%B4_%EB%90%98%EC%A7%80_%EC%95%8A%EB%8A%94%EA%B0%80\"><\/span>\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825 \uac8c\uc2dc\ub294 \uba85\uc608\ud6fc\uc190\uc774 \ub418\uc9c0 \uc54a\ub294\uac00<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\uc704\uc640 \uac19\uc774, \uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\ub3c4 &#8216;\uac1c\uc778\uc815\ubcf4&#8217;\uc640 \uad00\ub828\ub41c \ubb38\uc81c\uc774\uba70, &#8216;\uc804\uacfc \ub4f1\uc744 \ud568\ubd80\ub85c \uacf5\uac1c\ub418\uc9c0 \uc54a\ub294 \uc774\uc775&#8217;\uc774\ub77c\ub294 \ud0a4\uc6cc\ub4dc \ud558\uc5d0\uc11c \uc0dd\uac01\ud558\ub294 \uac83\uc774 \ud604\uc7ac\uc758 \ucd5c\uace0\ubc95\uc6d0\uc758 \uc0dd\uac01\uc785\ub2c8\ub2e4.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EC%98%A4%EC%9D%B8_%EC%B2%B4%ED%8F%AC%EC%9D%98_%EC%B2%B4%ED%8F%AC_%EC%9D%B4%EB%A0%A5_%EC%82%AD%EC%A0%9C%EB%8A%94_%EA%B8%B0%EB%B3%B8%EC%A0%81%EC%9C%BC%EB%A1%9C_%EC%9D%B8%EC%A0%95%EB%90%9C%EB%8B%A4\"><\/span>\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825 \uc0ad\uc81c\ub294 \uae30\ubcf8\uc801\uc73c\ub85c \uc778\uc815\ub41c\ub2e4<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\uadf8\ub9ac\uace0 \uba3c\uc800 \uc5b8\uae09\ud558\uba74, \uc774\ub7f0 \uc0dd\uac01\uc774\ub77c \ud574\ub3c4, \uc2e4\uc81c \ubb38\uc81c\ub85c\uc11c\ub294 \uadf8\ub9ac \uc911\ub300\ud55c \ubb38\uc81c\ub294 \uc5c6\uc2b5\ub2c8\ub2e4. \uc0c1\uc2dd\uc801\uc73c\ub85c \uc0dd\uac01\ud574, \uc624\uc778 \uccb4\ud3ec\ub2f9\ud55c \uc0ac\ub78c\uc774 \uadf8 \uccb4\ud3ec \uc774\ub825\uc758 \uc0ad\uc81c\ub97c \uc694\uad6c\ud558\uace0, \uadf8\ub7ec\ub098 \uc0ad\uc81c\uac00 \uc778\uc815\ub418\uc9c0 \uc54a\ub294\ub2e4\ub294 \uac83\uc740 &#8216;\uc2ec\ud55c&#8217; \uc774\uc57c\uae30\uc774\uba70, \ubc95\uc6d0\uc740 \uacb0\uacfc\uc801\uc73c\ub85c \uc0ad\uc81c\ub97c \uc778\uc815\ud558\ub294 \uacbd\uc6b0\uac00 \ub9ce\uae30 \ub54c\ubb38\uc785\ub2c8\ub2e4. \uc704\uc758 \uc77c\ubcf8\ub3c4\uc758 \uc0ac\ub840\ub294, \uacb0\uad6d &#8216;\ucd94\uc0c1\uc801\uc73c\ub85c\ub294 \uadf8\ub7f0 \uacbd\uc6b0\ub3c4 \uc788\uc744 \uc218 \uc788\uc9c0 \uc54a\uc744\uae4c&#8217;\ub77c\ub294 &#8216;\uc6b0\ub824&#8217;\uc5d0 \ubd88\uacfc\ud569\ub2c8\ub2e4.<\/p>\n\n\n\n<p>\uae30\uc0ac\uc758 \uc0ad\uc81c\ub294, \uc77c\ubc18\ub860\uc73c\ub85c\uc11c, \ubc95\uc815 \uc678 \ud611\uc0c1\uc5d0\uc11c \ud611\uc0c1\uc774 \ub9de\ucdb0\uc9c0\uc9c0 \uc54a\uace0, \ubc95\uc6d0\uc744 \uc774\uc6a9\ud558\ub294 \uc808\ucc28\uac00 \ub41c \uacbd\uc6b0\uc5d0\ub3c4, \uc2ec\ud310\uc774 \uc544\ub2c8\ub77c, &#8216;\uc784\uc2dc \ucc98\ubd84&#8217;\uc774\ub77c\ub294, \uc2e0\uc18d\ud55c \uc808\ucc28\ub85c \uc774\ub8e8\uc5b4\uc9c8 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uc774 \uc810\uc5d0 \ub300\ud574\uc11c\ub294 \uc544\ub798 \uae30\uc0ac\uc5d0\uc11c \uc790\uc138\ud788 \uc124\uba85\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/provisional-disposition\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/provisional-disposition[ja]<\/a><\/p>\n\n\n\n<p>\uadf8\ub9ac\uace0 \uc801\uc5b4\ub3c4 \ubcf8 \uae30\uc0ac \uc791\uc131 \ud604\uc7ac\uae4c\uc9c0, \uc800\ud76c \uc0ac\ubb34\uc18c\uac00 \ubc1b\uc740 \uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc758 \uc784\uc2dc \ucc98\ubd84 \uc0ac\uac74\uc740, \ubaa8\ub450 \uc0ad\uc81c\uac00 \uc778\uc815\ub418\uc5c8\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2019\/08\/shutterstock_1388691593-1024x647.jpg\" alt=\"\" class=\"wp-image-3751\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EC%A2%85%ED%95%A9%EC%A0%81_%EA%B3%A0%EB%A0%A4%EC%97%90%EC%84%9C%EB%8A%94_%ED%8C%A8%EB%B0%B0%ED%95%A0_%EA%B0%80%EB%8A%A5%EC%84%B1%EB%8F%84_%EC%9E%88%EB%8B%A4\"><\/span>\uc885\ud569\uc801 \uace0\ub824\uc5d0\uc11c\ub294 \ud328\ubc30\ud560 \uac00\ub2a5\uc131\ub3c4 \uc788\ub2e4<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\uadf8\ub7ec\ub098, \uc704\uc640 \uac19\uc740 \uc0dd\uac01\uc740, \uacb0\uad6d,<\/p>\n\n\n\n<ol>\n<li>\uc624\uc778 \uccb4\ud3ec\ub4e0 \uc720\uc8c4 \ud310\uacb0\ub41c \uacbd\uc6b0\ub4e0, \uccb4\ud3ec \uc774\ub825\uc758 \uc0ad\uc81c\ub294 \uac1c\uc778\uc815\ubcf4 \uce68\ud574 \ubb38\uc81c<\/li>\n\n\n\n<li>\uac1c\uc778\uc815\ubcf4 \uce68\ud574\uc758 \uacbd\uc6b0\ub294, \ub2e4\uc591\ud55c \uc694\uc18c\ub97c \uc885\ud569\uc801\uc73c\ub85c \uace0\ub824\ud558\uc5ec \uacb0\ub860\uc744 \ub0b4\ub824\uc57c \ud55c\ub2e4<\/li>\n\n\n\n<li>\uc624\uc778 \uccb4\ud3ec\uc758 \uacbd\uc6b0\ub294, \uacf5\ud45c\uc758 \uc758\ubbf8\uac00 \uc5c6\uac70\ub098\/\ud76c\ubc15\ud55c \uacbd\uc6b0\uac00 \ub9ce\uc544, \uacb0\uacfc\uc801\uc73c\ub85c \uc0ad\uc81c\uac00 \uc778\uc815\ub418\ub294 \uacbd\uc6b0\uac00 \ub9ce\ub2e4<\/li>\n<\/ol>\n\n\n\n<p>\ub77c\ub294 \uac83\uc785\ub2c8\ub2e4. \ub530\ub77c\uc11c, &#8216;\uc885\ud569\uc801\uc73c\ub85c \uace0\ub824&#8217;\ub418\ub294 \ub2e4\ub978 \uace0\ub824 \uc694\uc18c\uc5d0 \ub530\ub77c, \ud328\ubc30\ud560 \uac00\ub2a5\uc131\uc774 \uc788\uc2b5\ub2c8\ub2e4. \uadf8 \uc758\ubbf8\uc5d0\uc11c, \ub9c8\uce58 &#8216;\uc544\ub0a0\ub85c\uadf8&#8217;\uc801\uc778 \ud310\ub2e8\uc785\ub2c8\ub2e4. &#8216;\uc800\ud76c \uc0ac\ubb34\uc18c\uac00 \ubc1b\uc740 \uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc758 \uc784\uc2dc \ucc98\ubd84 \uc0ac\uac74\uc740, \ubaa8\ub450 \uc0ad\uc81c\uac00 \uc778\uc815\ub418\uc5c8\uc2b5\ub2c8\ub2e4&#8217;\ub77c\ub294 \uac83\ub3c4, \uacb0\uad6d &#8216;\ubcf8 \uae30\uc0ac \uc791\uc131 \ud604\uc7ac\uae4c\uc9c0&#8217;\ub77c\ub294 \uc608\uc678 \ubd80\uc5ec\uc758 \uac83\uc785\ub2c8\ub2e4. \uadf8\ub798\uc11c, \uc704\uc758 \uc77c\ubcf8\ub3c4\uc640 \uac19\uc740 \uc0ac\ub840\ub3c4, \uacb0\uad6d &#8216;\ucd94\uc0c1\uc801\uc73c\ub85c\ub294 \uadf8\ub7f0 \uacbd\uc6b0\ub3c4 \uc788\uc744 \uc218 \uc788\uc9c0 \uc54a\uc744\uae4c&#8217;\ub77c\ub294 &#8216;\uc6b0\ub824&#8217;\ub85c\uc11c, \uac00\ub2a5\ud558\ub2e4\ub294 \uac83\uc785\ub2c8\ub2e4. <\/p>\n\n\n\n<p>\uadf8\ub7ec\ub098, \uc624\uc778 \uccb4\ud3ec\ub2f9\ud55c \uacbd\uc6b0, \uc624\uc778 \uccb4\ud3ec\ub2f9\ud55c \uc0ac\ub78c\uc5d0\uac8c\ub294 &#8216;\uacfc\uc2e4&#8217;\uc774 \uc5c6\uc2b5\ub2c8\ub2e4. \uadf8\ub7fc\uc5d0\ub3c4 \ubd88\uad6c\ud558\uace0, \uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc774 \uc778\ud130\ub137\uc5d0 \uacc4\uc18d \ub0a8\uc544\uc788\ub294 \uc0c1\ud669\uc740, \uc5b4\ub5a4 \uc758\ubbf8\uc5d0\uc11c\ub3c4 \uc6a9\ub0a9\ud558\uae30 \uc5b4\ub824\uc6b4 \uac83\uc774\ub77c\uace0 \ud560 \uc218 \uc788\uc744 \uac83\uc785\ub2c8\ub2e4.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EB%B2%94%EC%A3%84%EB%A5%BC_%EC%A0%80%EC%A7%80%EB%A5%B8_%EA%B2%83%EC%9C%BC%EB%A1%9C_%ED%95%B4%EC%84%9D%EB%90%98%EB%8A%94_%EA%B2%83%EC%9D%B4_%EB%AC%B8%EC%A0%9C%EC%9D%98_%EB%B3%B8%EC%A7%88\"><\/span>\ubc94\uc8c4\ub97c \uc800\uc9c0\ub978 \uac83\uc73c\ub85c \ud574\uc11d\ub418\ub294 \uac83\uc774 \ubb38\uc81c\uc758 \ubcf8\uc9c8<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc774 \uc778\ud130\ub137\uc5d0 \uacc4\uc18d \ub0a8\uc544\uc788\ub294 \uac83\uc774 \ub2f9\uc0ac\uc790\uc5d0\uac8c &#8216;\uc6a9\ub0a9\ud558\uae30 \uc5b4\ub824\uc6b4&#8217; \uac83\uc778 \uac00\uc7a5 \ud070 \uc774\uc720\ub294, \uacb0\uad6d, &#8216;\uccb4\ud3ec\ub418\uc5c8\ub2e4&#8217;\ub294 \uc0ac\uc2e4, \uccb4\ud3ec \uc774\ub825\uc774 \uc778\ud130\ub137\uc5d0 \ub0a8\uc544\uc788\uc73c\uba74, \uadf8\uac83\uc744 \uc77d\uc740 \uc0ac\ub78c\uc740, \uadf8 \uc0ac\ub78c\uc774 \ubc94\uc8c4\ub97c \uc800\uc9c8\ub800\ub2e4\uace0 \uc0dd\uac01\ud558\uac8c \ub418\ub294, \uadf8 \uc810\uc5d0 \uc788\ub2e4\uace0 \uc0dd\uac01\ub429\ub2c8\ub2e4. \uc790\uc8fc \uc5b8\uae09\ub418\ub294 \uc774\uc57c\uae30\uc9c0\ub9cc, \uc77c\ubcf8\uc758 \ud615\uc0ac \uc7ac\ud310\uc740 \uc720\uc8c4\uc728\uc774 99.9%\ub77c\uace0 \ub9d0\ud558\uace0 \uc788\uc73c\uba70, \ub610\ud55c, \uc801\uc5b4\ub3c4 \uc77c\ubc18 \uc2dc\ubbfc\uc758 \uac10\uac01\uc73c\ub85c\uc11c, &#8216;\uccb4\ud3ec\ub418\uc5c8\ub2e4&#8217;\uba74 &#8216;\uacb0\uad6d \uae30\uc18c\ub420 \uac83&#8217;\uc774\uace0, \uacb0\uad6d, &#8216;\uccb4\ud3ec\ub418\uc5c8\ub2e4&#8217;\uba74 &#8216;\uadf8 \uc0ac\ub78c\uc740 \ubc94\uc8c4\ub97c \uc800\uc9c8\ub800\ub2e4&#8217;\ub294 \uc778\uc0c1\uc774 \ub429\ub2c8\ub2e4. \uc774\uac83\uc740 &#8216;\uac1c\uc778\uc815\ubcf4&#8217;\uc758 \ubb38\uc81c\ubcf4\ub2e4, \uc21c\uc218\ud558\uac8c<\/p>\n\n\n\n<ol>\n<li>\ubc94\uc8c4\ub97c \uc800\uc9c0\ub974\uc9c0 \uc54a\uc558\uc74c\uc5d0\ub3c4 \ubd88\uad6c\ud558\uace0<\/li>\n\n\n\n<li>\ubc94\uc8c4\ub97c \uc800\uc9c8\ub800\ub2e4(\ubc16\uc5d0 \uc77d\ud788\uc9c0 \uc54a\ub294)\ub77c\ub294 \uac70\uc9d3 \uc0ac\uc2e4\uc744 \uc4f0\uc5ec\uc838 \ubc84\ub9ac\ub294<\/li>\n<\/ol>\n\n\n\n<p>\ub77c\ub294 \ubb38\uc81c\uc77c \uac83\uc785\ub2c8\ub2e4.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EA%B1%B0%EC%A7%93_%EC%82%AC%EC%8B%A4%EC%97%90_%EC%9D%98%ED%95%9C_%EC%82%AC%ED%9A%8C%EC%A0%81_%EB%B6%88%EC%9D%B4%EC%9D%B5%EC%9D%80_%EB%AA%85%EC%98%88%ED%9B%BC%EC%86%90_%EB%AC%B8%EC%A0%9C\"><\/span>\uac70\uc9d3 \uc0ac\uc2e4\uc5d0 \uc758\ud55c \uc0ac\ud68c\uc801 \ubd88\uc774\uc775\uc740 \uba85\uc608\ud6fc\uc190 \ubb38\uc81c<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2019\/08\/shutterstock_1101216494-1024x684.jpg\" alt=\"\" class=\"wp-image-3753\" \/><\/figure>\n\n\n\n<p>\ubc95\uc801\uc73c\ub85c \ubcf4\uba74, \uac70\uc9d3 \uc0ac\uc2e4\uc744 \uae30\uc7ac\ud558\uc5ec \uc0ac\ud68c\uc801 \ubd88\uc774\uc775\uc744 \ubc1b\ub294 \ubb38\uc81c\ub294 \uba85\uc608\ud6fc\uc190\uc73c\ub85c \uc815\ub9ac\ub429\ub2c8\ub2e4. \uba85\uc608\ud6fc\uc190\uc740 \uac04\ub2e8\ud788 \ub9d0\ud558\uba74<\/p>\n\n\n\n<ul>\n<li>\ud2b9\uc815\ud55c \uc0ac\uac74(\u2018\uc5b4\ub5a4 \uc0ac\ub78c\uc774 \uccb4\ud3ec\ub418\uc5c8\ub2e4\u2019\ub294 \uc0ac\uc2e4 \ud3ec\ud568)\uc774 \uae30\uc7ac\ub418\uace0<\/li>\n\n\n\n<li> \uadf8\uac83\uc774 \ud574\ub2f9 \uc0ac\ub78c\uc5d0\uac8c \uc0ac\ud68c\uc801 \ubd88\uc774\uc775\uc744 \ucd08\ub798\ud558\uc9c0\ub9cc<\/li>\n\n\n\n<li> \uadf8 \uc0ac\uc2e4\uc740 \uc9c4\uc2e4\uc774 \uc544\ub2c8\ub77c \uac70\uc9d3\uc778 \uacbd\uc6b0<\/li>\n<\/ul>\n\n\n\n<p>\uc5d0 \ud574\ub2f9\ud569\ub2c8\ub2e4. \uc774 \uc810\uc5d0 \ub300\ud574\uc11c\ub294 \uc544\ub798 \uae30\uc0ac\uc5d0\uc11c \uc790\uc138\ud788 \uc124\uba85\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/defamation\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/defamation[ja]<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EB%AA%85%EC%98%88%ED%9B%BC%EC%86%90_%EC%9A%94%EA%B1%B4%EC%9D%B4_%EC%B6%A9%EC%A1%B1%EB%90%98%EB%A9%B4_%EC%82%AD%EC%A0%9C%EA%B0%80_%ED%99%95%EC%8B%A4%ED%9E%88_%EC%9D%B8%EC%A0%95%EB%90%A8\"><\/span>\uba85\uc608\ud6fc\uc190 \uc694\uac74\uc774 \ucda9\uc871\ub418\uba74 \uc0ad\uc81c\uac00 \ud655\uc2e4\ud788 \uc778\uc815\ub428<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\uba85\uc608\ud6fc\uc190\uc740 \uc704\uc640 \uac19\uc740 \uc870\uac74\uc774 \ucda9\uc871\ub418\ub294 \ud55c, &#8216;\uc885\ud569\uc801 \uace0\ub824&#8217; \ub4f1\uc774 \uc544\ub2c8\ub77c \uba85\ud655\ud558\uac8c, \uc5b4\ub5a4 \uc758\ubbf8\uc5d0\uc11c\ub294 &#8216;\ub514\uc9c0\ud138&#8217;\uc801\uc778 \ud310\ub2e8\uc73c\ub85c \uc778\uc815\ub429\ub2c8\ub2e4. \ub530\ub77c\uc11c, \uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc744 \uba85\uc608\ud6fc\uc190 \ubb38\uc81c\ub85c \ub2e4\ub8f0 \uc218 \uc788\ub2e4\uba74, &#8216;\uc885\ud569\uc801\uc73c\ub85c \uace0\ub824\ud55c \uacb0\uacfc, \uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825 \uac8c\uc2dc\ub3c4, \ubd88\ubc95\uc774 \uc544\ub2c8\ub2e4&#8217;\ub77c\ub294 \uc5ec\uc9c0\uac00 \uc5c6\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<p>\ubc95\uc815 \uc678 \ud611\uc0c1 \uc218\uc900\uc5d0\uc11c\ub294, \uc704\uc640 \uac19\uc740 \ub17c\ub9ac\ub85c \uc0ad\uc81c\uac00 \uc778\uc815\ub418\ub294 \uacbd\uc6b0\ub3c4 \uc2e4\uc81c\ub85c \uc788\uc2b5\ub2c8\ub2e4. \uadf8\ub7ec\ub098 \ud604\uc7ac\uae4c\uc9c0, \uc800\ud76c \uc0ac\ubb34\uc18c\uac00 \uc54c\uace0 \uc788\ub294 \ud55c, \ubc95\uc815\uc774\ub098 \uc784\uc2dc \ucc98\ubd84\uc5d0\uc11c \uc704\uc640 \uac19\uc740 \ub17c\ub9ac\uac00 \uc778\uc815\ub41c \uacbd\uc6b0\ub294 \uc5c6\uc2b5\ub2c8\ub2e4. \ubc95\uc6d0\uc740,<\/p>\n\n\n\n<ol>\n<li>\ub2e8\uc21c\ud788 \uccb4\ud3ec\ub418\uc5c8\ub2e4\ub294 \uac83\ub9cc\uc73c\ub85c\ub294, \uadf8 \uc0ac\ub78c\uc774 \ubc94\uc8c4\ub97c \uc800\uc9c8\ub800\ub2e4\uace0 \ub9d0\ud558\uace0 \uc788\uc9c0 \uc54a\uc73c\uba70<\/li>\n\n\n\n<li> \uadf8 \uc0ac\ub78c\uc5d0\uac8c \uc0ac\ud68c\uc801 \ubd88\uc774\uc775\uc744 \ucd08\ub798\ud558\ub294 \uc815\ubcf4\uc778\uc9c0\ub3c4 \uc758\uc2ec\uc2a4\ub7fd\uace0<\/li>\n\n\n\n<li> \ubb34\uc5c7\ubcf4\ub2e4 &#8216;\uccb4\ud3ec\ub418\uc5c8\ub2e4&#8217;\ub294 \uac83\uc740 \uc9c4\uc2e4\uc774\ubbc0\ub85c, &#8216;\uc9c4\uc2e4&#8217;\uc774\ub77c\ub294 \ud310\ub2e8\uc744 \ub0b4\ub9ac\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/li>\n<\/ol>\n\n\n\n<p>\ub77c\uace0 \ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EC%98%A4%EC%9D%B8_%EC%B2%B4%ED%8F%AC%EC%9D%98_%EC%B2%B4%ED%8F%AC_%EC%9D%B4%EB%A0%A5%EC%9D%80_%ED%95%AD%EC%83%81_%EC%82%AD%EC%A0%9C%EB%90%98%EC%96%B4%EC%95%BC_%ED%95%A8\"><\/span>\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc740 \ud56d\uc0c1 \uc0ad\uc81c\ub418\uc5b4\uc57c \ud568<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\uadf8\ub7ec\ub098, \ubc18\ubcf5\ub418\uc9c0\ub9cc, \uacb0\uacfc\uc801\uc73c\ub85c \uc624\uc778 \uccb4\ud3ec\uc600\ub354\ub77c\ub3c4, \uccb4\ud3ec \uc774\ub825\uc774 \uc778\ud130\ub137\uc5d0 \uacc4\uc18d \ub0a8\uc544\uc788\ub294 \uac83\uc740, \uae30\uc5c5 \uacbd\uc601\uc790\ub098 \ud68c\uc0ac\uc6d0 \ub4f1\uc5d0\uac8c \uba85\ubc31\ud55c \ubd88\uc774\uc775\uc774\uba70, \uadf8 \uc774\uc720\ub294 \uadf8\uac83\uc744 \uc77d\ub294 \uc0ac\ub78c\uc774 &#8216;\uadf8 \uc0ac\ub78c\uc740 \ubc94\uc8c4\ub97c \uc800\uc9c8\ub800\ub2e4&#8217;\uace0 \ud574\uc11d\ud558\uae30 \ub54c\ubb38\uc785\ub2c8\ub2e4. \uc774\ub7f0 \uc758\ubbf8\uc5d0\uc11c, \uc774\uac83\uc740 \ubc14\ub85c &#8216;\ub514\uc9c0\ud138 \ud0c0\ud22c&#8217; \ubb38\uc81c\uc785\ub2c8\ub2e4.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/nhkdrama-degitaltatoo-01\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/nhkdrama-degitaltatoo-01[ja]<\/a><\/p>\n\n\n\n<p>\uc624\uc778 \uccb4\ud3ec\uc758 \uccb4\ud3ec \uc774\ub825\uc744 &#8216;\uac1c\uc778\uc815\ubcf4 \ubb38\uc81c&#8217;\ub85c \ub2e4\ub8e8\uace0 \uc788\ub294 \ud604\uc7ac\uc758 \ubc95\uc6d0 \uc6b4\uc601\uc5d0\ub294 \ubb38\uc81c\uac00 \uc788\ub2e4\uace0 \uc0dd\uac01\ub429\ub2c8\ub2e4.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%EC%9A%94%EC%95%BD\"><\/span>\uc694\uc57d<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\uc798\ubabb\ub41c \uccb4\ud3ec\ub85c \uc778\ud55c \uccb4\ud3ec \uae30\ub85d\uc774 \uc778\ud130\ub137\uc5d0 \uacc4\uc18d \ub0a8\uc544\uc788\ub294 \uac83\uc740 \ucc38\uc744 \uc218 \uc5c6\ub294 \uc77c\uc77c \uac83\uc785\ub2c8\ub2e4. \uc774\uac83\uc774 &#8216;\uc804\uacfc \ub4f1\uc744 \ud568\ubd80\ub85c \uacf5\uac1c\ud558\uc9c0 \uc54a\ub294 \uc774\uc775&#8217;\uc774\ub77c\ub294 \ud070 \uac1c\ub150\uc73c\ub85c \ubcfc \uc218 \uc788\uace0, \ub354 \ud06c\uac8c \ubcf4\uba74 \ud504\ub77c\uc774\ubc84\uc2dc \uce68\ud574 \ubb38\uc81c\ub77c \ud560\uc9c0\ub77c\ub3c4, \uc801\uc5b4\ub3c4 \uc778\ud130\ub137 \uc0c1\uc758 \ud48d\ud3c9 \ud53c\ud574 \ub300\ucc45\uc5d0 \uac15\ud55c \ubcc0\ud638\uc0ac\uc5d0\uac8c \uc758\ub8b0\ub97c \ud558\uba74, \uc0ad\uc81c\uc5d0 \uc131\uacf5\ud560 \uac00\ub2a5\uc131\uc740 \ub9e4\uc6b0 \ub192\ub2e4\uace0 \uc0dd\uac01\ub429\ub2c8\ub2e4.<\/p>\n\n\n\n<p>\uadf8\ub7ec\ub098, &#8216;\ub9e4\uc6b0 \ub192\ub2e4&#8217;\ub85c \ub05d\ub098\ub294 \uac83\uc774 \uc544\ub2c8\ub77c, &#8216;\ud56d\uc0c1 \uc0ad\uc81c\uac00 \uc778\uc815\ub418\ub294&#8217; \uc138\uc0c1\uc774 \ub418\uc5b4\uc57c \ud55c\ub2e4\uace0, \uc800\ud76c \uc0ac\ubb34\uc18c\ub294 \uc0dd\uac01\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\uc2e0\ubb38\uc744 \ube44\ub86f\ud55c \ub9ce\uc740 \ub274\uc2a4 \uc0ac\uc774\ud2b8\uc5d0\uc11c\ub294 \ud2b9\uc815 \uac1c\uc778\uc774 \uccb4\ud3ec\ub418\uc5c8\ub2e4\ub294 \ub274\uc2a4\uac00 \uc790\uc8fc \uac8c\uc7ac\ub429\ub2c8\ub2e4. \uadf8\ub7ec\ub098 \uadf8 \uc0ac\ub78c\uc774 \ud6c4\uc5d0 \uae30\uc18c\ub418\uc5c8\ub294\uc9c0, \uc7ac\ud310\uc5d0\uc11c \uc720\uc8c4 \ud310\uacb0\uc744 \ubc1b\uc558\ub294\uc9c0 \ub4f1\uc758 \ub274\uc2a4\ub294 \uc798 \uac8c\uc7ac\ub418\uc9c0 \uc54a\uc2b5\ub2c8\ub2e4. \uc774\uac83\uc740 \uccb4\ud3ec\ub41c \uc0ac\ub78c\uc5d0\uac8c \ub9e4\uc6b0 \uc2ec\uac01\ud55c \ubb38\uc81c\uc785\ub2c8\ub2e4. \uc989, \uc640 \uac19\uc740 \uacbd\uc6b0\uc5d0\ub3c4, \ub294 \uacbd\uc6b0\uac00 \uc788\uae30 \ub54c\ubb38\uc785\ub2c8\ub2e4. \uacb0\uacfc\uc801\uc73c\ub85c \uc624\uc778 \uccb4\ud3ec\uc600\ub354\ub77c\ub3c4 &#8216;\uccb4\ud3ec\ub418\uc5c8\ub2e4&#8217;\ub294 [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":63492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[39,21],"acf":[],"_links":{"self":[{"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/posts\/62282"}],"collection":[{"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/comments?post=62282"}],"version-history":[{"count":1,"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/posts\/62282\/revisions"}],"predecessor-version":[{"id":63493,"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/posts\/62282\/revisions\/63493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/media\/63492"}],"wp:attachment":[{"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/media?parent=62282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/categories?post=62282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monolith.law\/ko\/wp-json\/wp\/v2\/tags?post=62282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}