{"id":58126,"date":"2023-10-05T15:30:21","date_gmt":"2023-10-05T06:30:21","guid":{"rendered":"https:\/\/monolith.law\/pt\/?p=58126"},"modified":"2024-04-21T16:28:31","modified_gmt":"2024-04-21T07:28:31","slug":"building-image-use-illegal","status":"publish","type":"post","link":"https:\/\/monolith.law\/pt\/general-corporate\/building-image-use-illegal","title":{"rendered":"O uso de imagens de edif\u00edcios \u00e9 uma viola\u00e7\u00e3o da lei? Sobre direitos autorais e marcas registadas"},"content":{"rendered":"\n<p>Fotografias, filmes, animes, jogos, VR (Realidade Virtual) e AR (Realidade Aumentada), bem como mercadorias, s\u00e3o formas atrav\u00e9s das quais os edif\u00edcios t\u00eam vindo a ser utilizados em v\u00e1rios conte\u00fados.<\/p>\n\n\n\n<p>Os edif\u00edcios est\u00e3o protegidos por v\u00e1rios direitos, e \u00e9 necess\u00e1rio ter cuidado para n\u00e3o infringir esses direitos ao utilizar imagens, por exemplo.<\/p>\n\n\n\n<p>Neste artigo, explicaremos a rela\u00e7\u00e3o entre os edif\u00edcios e os direitos de autor e marcas registadas.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/youtuber-vtuber\/fotografando-propriedade-alheia\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/youtuber-vtuber\/fotografando-propriedade-alheia[ja]<\/a><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/building-image-use-illegal\/#Direitos_de_Autor\" title=\"Direitos de Autor\">Direitos de Autor<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/building-image-use-illegal\/#Arquitetura_e_Direitos_de_Autor\" title=\"Arquitetura e Direitos de Autor\">Arquitetura e Direitos de Autor<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/building-image-use-illegal\/#Julgamento_sobre_a_natureza_da_obra\" title=\"Julgamento sobre a natureza da obra\">Julgamento sobre a natureza da obra<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/building-image-use-illegal\/#Edificios_que_nao_foram_reconhecidos_como_obras\" title=\"Edif\u00edcios que n\u00e3o foram reconhecidos como obras\">Edif\u00edcios que n\u00e3o foram reconhecidos como obras<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/building-image-use-illegal\/#Edificios_que_foram_reconhecidos_como_obras\" title=\"Edif\u00edcios que foram reconhecidos como obras\">Edif\u00edcios que foram reconhecidos como obras<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/building-image-use-illegal\/#Edificios_e_Direitos_de_Marca\" title=\"Edif\u00edcios e Direitos de Marca\">Edif\u00edcios e Direitos de Marca<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/building-image-use-illegal\/#Direitos_de_gestao_de_instalacoes_e_direitos_de_autor_e_marcas_comerciais_nos_termos_de_uso\" title=\"Direitos de gest\u00e3o de instala\u00e7\u00f5es e direitos de autor e marcas comerciais nos termos de uso\">Direitos de gest\u00e3o de instala\u00e7\u00f5es e direitos de autor e marcas comerciais nos termos de uso<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/building-image-use-illegal\/#Resumo\" title=\"Resumo\">Resumo<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Direitos_de_Autor\"><\/span>Direitos de Autor<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Direitos de autor referem-se aos direitos para proteger as obras. <br><\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>&#8220;Refere-se a algo que expressa criativamente pensamentos ou sentimentos e pertence ao campo da literatura, ci\u00eancia, arte ou m\u00fasica&#8221;, e no par\u00e1grafo 1 do artigo 10, &#8220;exemplos de obras&#8221; s\u00e3o apresentados, e neste n\u00famero 5, &#8220;obras de arquitetura&#8221; s\u00e3o mencionadas.<\/p>\n<cite>Artigo 2, par\u00e1grafo 1, n\u00famero 1 da Lei Japonesa de Direitos de Autor<\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Arquitetura_e_Direitos_de_Autor\"><\/span>Arquitetura e Direitos de Autor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Arquitetura n\u00e3o se refere apenas a casas e edif\u00edcios, mas tamb\u00e9m a teatros, santu\u00e1rios, templos, pontes, jardins, parques, torres, etc., e entre estes, &#8220;obras de arquitetura que expressam criativamente pensamentos ou sentimentos&#8221; s\u00e3o reconhecidas como obras de arquitetura sob a lei de direitos de autor.<\/p>\n\n\n\n<p>No artigo 46 da Lei Japonesa de Direitos de Autor, diz:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>Uso de obras de arte p\u00fablicas, etc.<\/p>\n\n\n\n<p>As obras de arte cujo original est\u00e1 permanentemente instalado num local ao ar livre conforme definido no par\u00e1grafo 2 do artigo anterior, ou as obras de arquitetura, podem ser utilizadas de qualquer forma, exceto nos casos a seguir.<\/p>\n\n\n\n<p>1. Reproduzir uma escultura e oferec\u00ea-la ao p\u00fablico atrav\u00e9s da transfer\u00eancia da sua reprodu\u00e7\u00e3o<\/p>\n\n\n\n<p>2. Reproduzir uma obra de arquitetura atrav\u00e9s da arquitetura e oferec\u00ea-la ao p\u00fablico atrav\u00e9s da transfer\u00eancia da sua reprodu\u00e7\u00e3o<\/p>\n\n\n\n<p>3. Reproduzir para instala\u00e7\u00e3o permanente num local ao ar livre conforme definido no par\u00e1grafo 2 do artigo anterior<\/p>\n\n\n\n<p>4. Reproduzir exclusivamente para a venda de reprodu\u00e7\u00f5es de obras de arte, ou vender essas reprodu\u00e7\u00f5es<\/p>\n<cite>Artigo 46 da Lei Japonesa de Direitos de Autor<\/cite><\/blockquote>\n\n\n\n<p>Portanto, a constru\u00e7\u00e3o de um edif\u00edcio semelhante (reprodu\u00e7\u00e3o) \u00e9 proibida, mas outras a\u00e7\u00f5es, como fotografar e usar comercialmente, s\u00e3o permitidas.<\/p>\n\n\n\n<p>Em outras palavras, sob a lei de direitos de autor, as obras de arquitetura podem ser usadas em fotografias, filmes, animes, jogos e mercadorias, mesmo sem a permiss\u00e3o do detentor dos direitos de autor.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2021\/01\/building-image-use-illegal1.jpg\" alt=\"\" class=\"wp-image-27481\" \/><\/figure>\n\n\n\n<p>Al\u00e9m disso, ao contr\u00e1rio das obras de arte, as obras de arquitetura n\u00e3o t\u00eam a limita\u00e7\u00e3o de &#8220;estar instaladas ao ar livre&#8221;, por isso, teoricamente, partes de um edif\u00edcio, como o interior e as escadas, tamb\u00e9m podem ser usadas.<\/p>\n\n\n\n<p>No entanto, de acordo com o n\u00famero 4 do mesmo artigo, o alcance do uso livre \u00e9 limitado para edif\u00edcios que t\u00eam alta criatividade e tamb\u00e9m se enquadram como &#8220;obras de arte&#8221;, como a &#8220;Torre do Sol&#8221; de Taro Okamoto.<\/p>\n\n\n\n<p>\u00c9 poss\u00edvel tirar fotografias para fins privados ou distribui\u00e7\u00e3o gratuita, ou mesmo para fins de venda se for apenas como parte do fundo, mas para tirar fotografias para fins de venda, como postais ou cartazes que se concentram no edif\u00edcio, ou para fazer outras reprodu\u00e7\u00f5es ou vendas, \u00e9 necess\u00e1rio o consentimento do detentor dos direitos de autor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Julgamento_sobre_a_natureza_da_obra\"><\/span>Julgamento sobre a natureza da obra<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A determina\u00e7\u00e3o de se um edif\u00edcio em quest\u00e3o se qualifica como uma obra \u00e9 na realidade um problema bastante dif\u00edcil, e pode ser objeto de disputa em casos judiciais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Edificios_que_nao_foram_reconhecidos_como_obras\"><\/span>Edif\u00edcios que n\u00e3o foram reconhecidos como obras<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>H\u00e1 um caso em que o autor que criou os planos de um edif\u00edcio alegou que a constru\u00e7\u00e3o do edif\u00edcio de acordo com esses planos violava os seus direitos de autor (direito de reprodu\u00e7\u00e3o), e solicitou uma medida provis\u00f3ria para impedir a constru\u00e7\u00e3o do edif\u00edcio.<\/p>\n\n\n\n<p>O tribunal decidiu que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>Ap\u00f3s considerar se o edif\u00edcio conceitual expresso nos planos em quest\u00e3o se qualifica como uma &#8220;obra arquitet\u00f3nica&#8221;, e n\u00e3o com base na sua utilidade ou funcionalidade, mas principalmente na apar\u00eancia do edif\u00edcio como uma express\u00e3o da sua espiritualidade cultural, o edif\u00edcio em quest\u00e3o n\u00e3o foi reconhecido como possuindo a arte que permitiria ao p\u00fablico em geral perceber a espiritualidade cultural do designer, e ainda n\u00e3o ultrapassou o \u00e2mbito de uma resid\u00eancia comum, e n\u00e3o pode ser avaliado como elevado \u00e0 arte arquitet\u00f3nica, e portanto, n\u00e3o se qualifica como uma &#8220;obra arquitet\u00f3nica&#8221;, e consequentemente, o ato de constru\u00e7\u00e3o em quest\u00e3o n\u00e3o constitui uma viola\u00e7\u00e3o do &#8220;direito de reprodu\u00e7\u00e3o&#8221;, e o pedido foi rejeitado.<\/p>\n<cite>Decis\u00e3o do Tribunal Distrital de Fukushima, 9 de abril de 1991 (Ano 3 da Era Heisei)<\/cite><\/blockquote>\n\n\n\n<p>Um julgamento semelhante pode ser visto mesmo em casas de luxo personalizadas que ganharam o Pr\u00eamio de Bom Design. A Sekisui House, Ltd. projetou e construiu uma s\u00e9rie de casas de luxo personalizadas e as exibiu em exposi\u00e7\u00f5es de habita\u00e7\u00e3o em todo o pa\u00eds. Por outro lado, a empresa de constru\u00e7\u00e3o r\u00e9 construiu uma casa modelo e a exibiu em exposi\u00e7\u00f5es em todo o pa\u00eds, mas a Sekisui House, Ltd. alegou que este edif\u00edcio era uma reprodu\u00e7\u00e3o ou adapta\u00e7\u00e3o de seus pr\u00f3prios edif\u00edcios, e que violava os direitos de autor, e solicitou uma medida para impedir a constru\u00e7\u00e3o da casa modelo da empresa r\u00e9.<\/p>\n\n\n\n<p>O tribunal decidiu que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>O edif\u00edcio do autor tem elementos que evocam a beleza da arquitetura japonesa e elementos da arquitetura ocidental, que foram dispostos e organizados atrav\u00e9s de tentativa e erro, e \u00e9 um edif\u00edcio que possui uma certa criatividade n\u00e3o s\u00f3 em termos de utilidade e funcionalidade, mas tamb\u00e9m em termos est\u00e9ticos, e tamb\u00e9m \u00e9 indubitavelmente o resultado de atividades intelectuais, pois foi decidido o design exterior atrav\u00e9s de tentativa e erro com a participa\u00e7\u00e3o de v\u00e1rias pessoas com conhecimento e experi\u00eancia especializados. Al\u00e9m disso, na sele\u00e7\u00e3o do Pr\u00eamio de Bom Design, s\u00e3o considerados elementos relacionados \u00e0 est\u00e9tica e \u00e0 arte, como beleza, novidade e originalidade, e \u00e9 reconhecido que h\u00e1 elementos \u00fanicos que n\u00e3o s\u00e3o nem puramente arquitetura japonesa nem arquitetura ocidental em compara\u00e7\u00e3o com os estilos arquitet\u00f4nicos tradicionais.<\/p>\n<\/blockquote>\n\n\n\n<p>Contudo, o tribunal decidiu que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>Quando o edif\u00edcio conclu\u00eddo do autor \u00e9 comparado com a arquitetura residencial existente e comum, n\u00e3o pode ser reconhecido que o edif\u00edcio do autor possui est\u00e9tica e arte que s\u00e3o diferentes das delas, portanto, mesmo que se considere que o design foi feito com as considera\u00e7\u00f5es acima, n\u00e3o se pode reconhecer que o edif\u00edcio do autor possui est\u00e9tica e arte, e n\u00e3o se qualifica como uma obra arquitet\u00f4nica sob a Lei de Direitos Autorais.<\/p>\n<cite>Decis\u00e3o do Tribunal Distrital de Osaka, 30 de outubro de 2003 (Ano 15 da Era Heisei)<\/cite><\/blockquote>\n\n\n\n<p>Portanto, mesmo que um edif\u00edcio tenha &#8220;uma certa criatividade&#8221;, seja &#8220;o resultado de atividades intelectuais&#8221;, e tenha &#8220;elementos \u00fanicos&#8221;, \u00e9 dif\u00edcil ser julgado como possuindo criatividade est\u00e9tica que ultrapassa os elementos est\u00e9ticos que as resid\u00eancias e edif\u00edcios comuns possuem, e como possuindo est\u00e9tica e arte que podem ser chamadas de arte arquitet\u00f4nica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Edificios_que_foram_reconhecidos_como_obras\"><\/span>Edif\u00edcios que foram reconhecidos como obras<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2021\/01\/building-image-use-illegal2.jpg\" alt=\"\" class=\"wp-image-27483\" \/><\/figure>\n\n\n\n<p>No campus de Mita da Universidade Keio,<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>O ato de realizar obras para mover uma parte do edif\u00edcio e o jardim adjacente ao edif\u00edcio e duas esculturas instaladas no jardim, que foram projetados pelo escultor Isamu Noguchi e outros, a fim de construir um novo edif\u00edcio para a Faculdade de Direito, viola o direito moral do autor de Isamu Noguchi (direito de preservar a integridade).<\/p>\n<\/blockquote>\n\n\n\n<p>H\u00e1 um caso em que a Funda\u00e7\u00e3o Isamu Noguchi, que alega ter sucedido a todos os direitos sobre as obras de Isamu Noguchi, solicitou uma ordem de medida provis\u00f3ria para impedir a demoli\u00e7\u00e3o e a movimenta\u00e7\u00e3o do edif\u00edcio e outros. (Decis\u00e3o do Tribunal Distrital de T\u00f3quio, 11 de junho de 2003 (Ano 15 da Era Heisei))<\/p>\n\n\n\n<p>O tribunal decidiu que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>O edif\u00edcio em quest\u00e3o, incluindo a Sala Noguchi, \u00e9 uma obra como um todo, e o jardim foi projetado para ser uma parte integrante do edif\u00edcio em quest\u00e3o, e \u00e9 organicamente integrado ao edif\u00edcio em quest\u00e3o.<\/p>\n<\/blockquote>\n\n\n\n<p>E sobre as esculturas, o tribunal decidiu que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>Como a estrutura da Sala Noguchi no edif\u00edcio em quest\u00e3o foi projetada levando em considera\u00e7\u00e3o a localiza\u00e7\u00e3o e a forma das esculturas instaladas no jardim, enquanto estiverem localizadas no local onde foram instaladas, elas constituem uma parte da obra arquitet\u00f4nica \u00fanica mencionada acima como parte dos elementos do jardim, e ao mesmo tempo, podem ser um objeto de aprecia\u00e7\u00e3o independente, e s\u00e3o tamb\u00e9m uma &#8220;obra de arte&#8221; independente.<\/p>\n<\/blockquote>\n\n\n\n<p>Contudo, o tribunal decidiu que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>As obras s\u00e3o para a constru\u00e7\u00e3o de um novo edif\u00edcio com a \u00e1rea necess\u00e1ria calculada a partir do n\u00famero previsto de estudantes para o estabelecimento da Faculdade de Direito, para um prop\u00f3sito p\u00fablico, em um espa\u00e7o limitado dentro do campus da universidade, e o plano final foi decidido levando em considera\u00e7\u00e3o as opini\u00f5es do Grupo de Trabalho de Preserva\u00e7\u00e3o, entre outros, para preservar a inten\u00e7\u00e3o do criador o m\u00e1ximo poss\u00edvel, enquanto o prazo para o estabelecimento da Faculdade de Direito se aproxima. Embora o conte\u00fado seja a demoli\u00e7\u00e3o e a movimenta\u00e7\u00e3o do edif\u00edcio em quest\u00e3o, incluindo a Sala Noguchi e o jardim, ap\u00f3s a demoli\u00e7\u00e3o, \u00e9 para restaur\u00e1-los o mais pr\u00f3ximo poss\u00edvel do estado atual, e n\u00e3o se aplica ao &#8220;direito de preservar a integridade&#8221; porque \u00e9 considerado uma &#8220;altera\u00e7\u00e3o por adi\u00e7\u00e3o, modifica\u00e7\u00e3o, repara\u00e7\u00e3o ou remodela\u00e7\u00e3o de um edif\u00edcio&#8221; (Artigo 20, par\u00e1grafo 2, item 2 da Lei de Direitos Autorais).<\/p>\n<\/blockquote>\n\n\n\n<p>E rejeitou o pedido de uma ordem de medida provis\u00f3ria para impedir a demoli\u00e7\u00e3o e a movimenta\u00e7\u00e3o do edif\u00edcio e outros.<\/p>\n\n\n\n<p>Os edif\u00edcios que foram reconhecidos como obras em julgamentos incluem a &#8220;Nova Cidade Umeda&#8221; e a &#8220;Loja Stella McCartney Aoyama&#8221;, entre outros, mas n\u00e3o s\u00e3o muitos.<\/p>\n\n\n\n<p>Edif\u00edcios como santu\u00e1rios, templos e castelos tamb\u00e9m podem ser obras, mas muitos deles j\u00e1 ultrapassaram o per\u00edodo de prote\u00e7\u00e3o. No entanto, os direitos morais do autor podem continuar a existir mesmo ap\u00f3s o t\u00e9rmino do per\u00edodo de prote\u00e7\u00e3o.<\/p>\n\n\n\n<p>Se o autor estiver vivo, atos que possam violar os direitos morais do autor s\u00e3o proibidos (Artigo 60 da Lei de Direitos Autorais), e o uso de obras que possam prejudicar a honra ou a reputa\u00e7\u00e3o do autor pode ser considerado uma viola\u00e7\u00e3o dos direitos morais do autor (Artigo 113, par\u00e1grafo 7 da Lei de Direitos Autorais), por isso \u00e9 necess\u00e1rio ter cuidado.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-\u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09 wp-block-embed-\u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"RVmwKNhEsL\"><a href=\"https:\/\/monolith.law\/pt\/internet\/protection-author-moral-rights\">O que \u00e9 a prote\u00e7\u00e3o dos direitos de personalidade do autor e da honra ou reputa\u00e7\u00e3o?<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;O que \u00e9 a prote\u00e7\u00e3o dos direitos de personalidade do autor e da honra ou reputa\u00e7\u00e3o?&#8221; &#8212; \u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09\" src=\"https:\/\/monolith.law\/pt\/internet\/protection-author-moral-rights\/embed#?secret=78l0zE46Yp#?secret=RVmwKNhEsL\" data-secret=\"RVmwKNhEsL\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Edificios_e_Direitos_de_Marca\"><\/span>Edif\u00edcios e Direitos de Marca<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2021\/01\/building-image-use-illegal3.jpg\" alt=\"\" class=\"wp-image-27484\" \/><\/figure>\n\n\n\n<p>A Torre de T\u00f3quio e a Skytree n\u00e3o s\u00f3 t\u00eam os seus nomes registados como marcas, mas tamb\u00e9m a silhueta dos edif\u00edcios. Al\u00e9m disso, se a apar\u00eancia externa tiver um poder de identifica\u00e7\u00e3o, \u00e9 poss\u00edvel regist\u00e1-la como uma marca tridimensional. Portanto, edif\u00edcios emblem\u00e1ticos como a Torre de T\u00f3quio e a Skytree t\u00eam a sua forma registada como marca tridimensional devido ao seu poder de identifica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m disso, a apar\u00eancia externa das lojas, como a Komeda Coffee, tamb\u00e9m est\u00e1 registada como uma marca tridimensional.<\/p>\n\n\n\n<p>O titular da marca pode solicitar uma ordem de cessa\u00e7\u00e3o (Artigo 36 da Lei Japonesa de Marcas) ou uma reivindica\u00e7\u00e3o de indemniza\u00e7\u00e3o por danos (Artigo 38 da Lei Japonesa de Marcas) contra o utilizador n\u00e3o autorizado.<\/p>\n\n\n\n<p>No entanto, nem todos os usos da marca podem ser restringidos. O direito de marca \u00e9 um sistema para proteger a &#8220;credibilidade comercial&#8221; contida na marca, por isso o objeto do direito de marca \u00e9 limitado ao uso que tem um poder de auto-identifica\u00e7\u00e3o, como o free-riding da credibilidade comercial (chamado de &#8220;uso de marca&#8221;) (Artigo 26, par\u00e1grafo 1, item 6 da Lei Japonesa de Marcas).<\/p>\n\n\n\n<p>Por outro lado, pode n\u00e3o ser uma viola\u00e7\u00e3o do direito de marca fazer com que um edif\u00edcio registado como marca apare\u00e7a como parte de um conte\u00fado, simplesmente como uma express\u00e3o, pois isso n\u00e3o se qualifica como uso de marca.<\/p>\n\n\n\n<p>Mesmo que um edif\u00edcio registado como marca seja exibido em filmes ou jogos, pode n\u00e3o ser uma viola\u00e7\u00e3o do direito de marca se n\u00e3o for particularmente enfatizado, mas \u00e9 necess\u00e1ria uma avalia\u00e7\u00e3o delicada e dif\u00edcil.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2021\/01\/building-image-use-illegal4.jpg\" alt=\"\" class=\"wp-image-27485\" \/><\/figure>\n\n\n\n<p>\u00c9 necess\u00e1rio ter cuidado com a viola\u00e7\u00e3o dos direitos autorais, mas a viola\u00e7\u00e3o dos direitos de marca tamb\u00e9m pode ser um problema s\u00e9rio.<\/p>\n\n\n\n<p>Al\u00e9m disso, a partir de abril de 2020, os edif\u00edcios tamb\u00e9m se tornaram objeto de registo de design, e h\u00e1 exemplos de registo como a loja &#8220;Uniqlo PARK Yokohama Bayside&#8221; com um parque no telhado e a &#8220;Esta\u00e7\u00e3o Ueno Park Exit&#8221;. No entanto, embora haja um per\u00edodo de car\u00eancia de um ano, o objeto de registo de design \u00e9 um novo design, por isso \u00e9 pouco prov\u00e1vel que o uso de edif\u00edcios que existiam antes de abril de 2020 em conte\u00fados, etc., seja uma viola\u00e7\u00e3o dos direitos de design.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Direitos_de_gestao_de_instalacoes_e_direitos_de_autor_e_marcas_comerciais_nos_termos_de_uso\"><\/span>Direitos de gest\u00e3o de instala\u00e7\u00f5es e direitos de autor e marcas comerciais nos termos de uso<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Os propriet\u00e1rios e gestores de edif\u00edcios e instala\u00e7\u00f5es t\u00eam o que \u00e9 conhecido como &#8220;direitos de gest\u00e3o de instala\u00e7\u00f5es&#8221; com base na propriedade. Existem restri\u00e7\u00f5es baseadas nestes direitos de gest\u00e3o de instala\u00e7\u00f5es para comportamentos perturbadores e uso de propriedade intelectual dentro das instala\u00e7\u00f5es. No entanto, em instala\u00e7\u00f5es privadas, os direitos de gest\u00e3o de instala\u00e7\u00f5es s\u00e3o reconhecidos sem restri\u00e7\u00f5es espec\u00edficas, por isso \u00e9 poss\u00edvel &#8220;proibir a fotografia dentro das instala\u00e7\u00f5es&#8221; como parte dos direitos de gest\u00e3o de instala\u00e7\u00f5es.<\/p>\n\n\n\n<p>Neste caso, a fotografia n\u00e3o autorizada seria uma viola\u00e7\u00e3o dos direitos de gest\u00e3o de instala\u00e7\u00f5es. Al\u00e9m disso, se os direitos de autor e marcas comerciais forem violados, haver\u00e1 restri\u00e7\u00f5es \u00e0 publica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por exemplo, no site da Tokyo Skytree (Torre do C\u00e9u de T\u00f3quio), diz:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>A propriedade intelectual relacionada \u00e0 Tokyo Skytree (nome, logotipo, design de silhueta, CG de previs\u00e3o de conclus\u00e3o, etc.) \u00e9 protegida pelos direitos de autor e marcas comerciais da Tobu Tower Skytree Co., Ltd. e outras. Para a manuten\u00e7\u00e3o da imagem da Tokyo Skytree, a gest\u00e3o \u00e9 feita pelo Escrit\u00f3rio de Licen\u00e7as da Tokyo Skytree. Estas propriedades intelectuais n\u00e3o podem ser usadas sem a permiss\u00e3o do escrit\u00f3rio. Para consultas sobre o uso da propriedade intelectual da Tokyo Skytree, como a comercializa\u00e7\u00e3o e a utiliza\u00e7\u00e3o em publicidade e promo\u00e7\u00f5es, por favor, contacte o escrit\u00f3rio abaixo.<\/p>\n<cite><a href=\"https:\/\/www.tokyo-skytree.jp\/property\/\">Inqu\u00e9rito sobre o uso da propriedade intelectual da Tokyo Skytree <\/a><\/cite><\/blockquote>\n\n\n\n<p>E no site da Tokyo Tower (Torre de T\u00f3quio), diz:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>Para o planeamento, produ\u00e7\u00e3o e venda de produtos e servi\u00e7os que utilizam a propriedade da Tokyo Tower (*), e para a utiliza\u00e7\u00e3o da propriedade da Tokyo Tower em publicidade e v\u00e1rios meios de comunica\u00e7\u00e3o, \u00e9 necess\u00e1ria a aprova\u00e7\u00e3o da Tokyo Tower Co., Ltd.<\/p>\n\n\n\n<p>Para a utiliza\u00e7\u00e3o da propriedade da Tokyo Tower, por favor, consulte-nos aqui. Entraremos em contacto consigo posteriormente com mais detalhes. A taxa de licen\u00e7a de uso ser\u00e1 determinada de acordo com o conte\u00fado. Al\u00e9m do pagamento da taxa de licen\u00e7a de uso, existem v\u00e1rias condi\u00e7\u00f5es que devem ser cumpridas para manter a imagem da propriedade da Tokyo Tower, mas dependendo do conte\u00fado do uso, pode haver casos em que n\u00e3o podemos aprovar o uso. Por favor, entenda isso com anteced\u00eancia.<\/p>\n\n\n\n<p>* Propriedade da Tokyo Tower<\/p>\n\n\n\n<p>&#8211; Nome (Tokyo Tower, TOKYO TOWER) em japon\u00eas e em l\u00ednguas estrangeiras<\/p>\n\n\n\n<p>&#8211; Logotipo<\/p>\n\n\n\n<p>&#8211; Imagem exterior (forma, cor, ilumina\u00e7\u00e3o, etc. da Tokyo Tower) incluindo fotografias e design<\/p>\n\n\n\n<p>&#8211; Personagem &#8220;Noppon&#8221; * Nome e imagem<\/p>\n<cite><a href=\"https:\/\/www.tokyotower.co.jp\/license\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\"> TOKYO TOWER Licen\u00e7a \/ Sobre filmagens e reportagens [ja]<\/a><\/cite><\/blockquote>\n\n\n\n<p>Portanto, ao utilizar imagens de edif\u00edcios, \u00e9 necess\u00e1rio prestar aten\u00e7\u00e3o a estes direitos de gest\u00e3o de instala\u00e7\u00f5es e termos de uso.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/youtuber-vtuber\/problems-of-uploading-videos-and-voyeur-videos-to-youtube\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/youtuber-vtuber\/problems-of-uploading-videos-and-voyeur-videos-to-youtube[ja]<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resumo\"><\/span>Resumo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Os edif\u00edcios podem gerar v\u00e1rios direitos. Al\u00e9m disso, do ponto de vista da lei de direitos autorais, o alcance do uso pode variar dependendo se se qualifica como &#8220;obra de arquitetura&#8221; ou &#8220;obra de arte&#8221;. Assim, existem muitos problemas complexos a serem resolvidos ao usar imagens de edif\u00edcios. Consulte um advogado experiente.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-\u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09 wp-block-embed-\u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"FNOFNpKK46\"><a href=\"https:\/\/monolith.law\/pt\/general-corporate\/intellectual-property-infringement-risk\">O que s\u00e3o os riscos de viola\u00e7\u00e3o de direitos de propriedade intelectual como patentes, marcas registradas, direitos autorais e suas medidas de prote\u00e7\u00e3o?<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;O que s\u00e3o os riscos de viola\u00e7\u00e3o de direitos de propriedade intelectual como patentes, marcas registradas, direitos autorais e suas medidas de prote\u00e7\u00e3o?&#8221; &#8212; \u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09\" src=\"https:\/\/monolith.law\/pt\/general-corporate\/intellectual-property-infringement-risk\/embed#?secret=pTS3bxOkvu#?secret=FNOFNpKK46\" data-secret=\"FNOFNpKK46\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Fotografias, filmes, animes, jogos, VR (Realidade Virtual) e AR (Realidade Aumentada), bem como mercadorias, s\u00e3o formas atrav\u00e9s das quais os edif\u00edcios t\u00eam vindo a ser utilizados em v\u00e1rios conte\u00fados. O [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":69254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[24,28],"acf":[],"_links":{"self":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58126"}],"collection":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/comments?post=58126"}],"version-history":[{"count":2,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58126\/revisions"}],"predecessor-version":[{"id":69255,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58126\/revisions\/69255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media\/69254"}],"wp:attachment":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media?parent=58126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/categories?post=58126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/tags?post=58126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}