{"id":58159,"date":"2023-10-05T15:30:22","date_gmt":"2023-10-05T06:30:22","guid":{"rendered":"https:\/\/monolith.law\/pt\/?p=58159"},"modified":"2024-04-29T00:43:59","modified_gmt":"2024-04-28T15:43:59","slug":"e-sports-employee-ban","status":"publish","type":"post","link":"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban","title":{"rendered":"Ganhar pr\u00e9mios em dinheiro em e-sports \u00e9 considerado um trabalho secund\u00e1rio? Explica\u00e7\u00e3o incluindo a classifica\u00e7\u00e3o de rendimentos"},"content":{"rendered":"\n<p>O e-Sports refere-se \u00e0 considera\u00e7\u00e3o de competi\u00e7\u00f5es usando jogos de computador ou videojogos como desportos. A ind\u00fastria de e-Sports tem ganho popularidade nos \u00faltimos anos, com muitos torneios a oferecer pr\u00e9mios monet\u00e1rios. Existem at\u00e9 profissionais que ganham a vida com os pr\u00e9mios dos jogos.<\/p>\n\n\n\n<p>Ent\u00e3o, se estiver a ganhar dinheiro com e-Sports, ser\u00e1 considerado um trabalho secund\u00e1rio e proibido pelas regras de emprego? Neste artigo, vamos explicar para aqueles que est\u00e3o preocupados com este ponto.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#O_que_sao_os_eSports\" title=\"O que s\u00e3o os eSports\">O que s\u00e3o os eSports<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Considera-se_um_segundo_emprego_ganhar_premios_em_competicoes_de_e-sports\" title=\"Considera-se um segundo emprego ganhar pr\u00e9mios em competi\u00e7\u00f5es de e-sports?\">Considera-se um segundo emprego ganhar pr\u00e9mios em competi\u00e7\u00f5es de e-sports?<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Se_declarar_o_premio_como_renda_temporaria\" title=\"Se declarar o pr\u00e9mio como renda tempor\u00e1ria\">Se declarar o pr\u00e9mio como renda tempor\u00e1ria<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Se_declarar_o_premio_como_renda_de_negocios\" title=\"Se declarar o pr\u00e9mio como renda de neg\u00f3cios\">Se declarar o pr\u00e9mio como renda de neg\u00f3cios<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Eficacia_da_proibicao_de_trabalho_secundario_nas_regras_de_emprego\" title=\"Efic\u00e1cia da proibi\u00e7\u00e3o de trabalho secund\u00e1rio nas regras de emprego\">Efic\u00e1cia da proibi\u00e7\u00e3o de trabalho secund\u00e1rio nas regras de emprego<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Criterios_para_determinar_se_os_e-sports_sao_considerados_trabalho_secundario_proibido_pelas_regras_de_emprego_da_empresa\" title=\"Crit\u00e9rios para determinar se os e-sports s\u00e3o considerados trabalho secund\u00e1rio proibido pelas regras de emprego da empresa\">Crit\u00e9rios para determinar se os e-sports s\u00e3o considerados trabalho secund\u00e1rio proibido pelas regras de emprego da empresa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Criterios_para_determinar_se_os_e-sports_sao_considerados_trabalho_secundario_para_funcionarios_publicos\" title=\"Crit\u00e9rios para determinar se os e-sports s\u00e3o considerados trabalho secund\u00e1rio para funcion\u00e1rios p\u00fablicos\">Crit\u00e9rios para determinar se os e-sports s\u00e3o considerados trabalho secund\u00e1rio para funcion\u00e1rios p\u00fablicos<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Receber_o_premio_de_eSports_como_remuneracao_do_trabalho\" title=\"Receber o pr\u00e9mio de eSports como remunera\u00e7\u00e3o do trabalho\">Receber o pr\u00e9mio de eSports como remunera\u00e7\u00e3o do trabalho<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Ganhar_premios_em_competicoes_de_e-sports_no_estrangeiro\" title=\"Ganhar pr\u00e9mios em competi\u00e7\u00f5es de e-sports no estrangeiro\">Ganhar pr\u00e9mios em competi\u00e7\u00f5es de e-sports no estrangeiro<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Resumo_Consulte_um_advogado_sobre_questoes_de_premios_de_eSports\" title=\"Resumo: Consulte um advogado sobre quest\u00f5es de pr\u00e9mios de eSports\">Resumo: Consulte um advogado sobre quest\u00f5es de pr\u00e9mios de eSports<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/monolith.law\/pt\/general-corporate\/e-sports-employee-ban\/#Apresentacao_das_medidas_tomadas_pelo_nosso_escritorio\" title=\"Apresenta\u00e7\u00e3o das medidas tomadas pelo nosso escrit\u00f3rio\">Apresenta\u00e7\u00e3o das medidas tomadas pelo nosso escrit\u00f3rio<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_sao_os_eSports\"><\/span>O que s\u00e3o os eSports<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2022\/06\/https___Monolith-law.jp_wordpress_wp-admin_post.php_post44615actionedit_rewrite2.jpg\" alt=\"\" class=\"wp-image-45902\" \/><\/figure>\n\n\n\n<p>Os eSports, de forma simples, s\u00e3o a competi\u00e7\u00e3o de videojogos considerada como um desporto. Em fevereiro de 2018, a Associa\u00e7\u00e3o Japonesa de eSports (JeSU) foi estabelecida e o &#8220;Sistema de Licen\u00e7a Profissional Reconhecido pela JeSU&#8221; foi criado, promovendo o desenvolvimento dos eSports.<\/p>\n\n\n\n<p>Um dos motivos para a cria\u00e7\u00e3o do &#8220;Sistema de Licen\u00e7a Profissional Reconhecido pela JeSU&#8221; foi o risco de os pr\u00e9mios dos torneios de eSports serem sujeitos \u00e0 regulamenta\u00e7\u00e3o da Lei Japonesa de Exibi\u00e7\u00e3o de Pr\u00e9mios.<\/p>\n\n\n\n<p>Se o pr\u00e9mio for oferecido como &#8220;remunera\u00e7\u00e3o por participa\u00e7\u00e3o no torneio&#8221;, n\u00e3o ser\u00e1 sujeito \u00e0 regulamenta\u00e7\u00e3o da Lei de Exibi\u00e7\u00e3o de Pr\u00e9mios.<\/p>\n\n\n\n<p>Assim, o &#8220;Sistema de Licen\u00e7a Profissional Reconhecido pela JeSU&#8221; foi estabelecido para definir os crit\u00e9rios para quando os pr\u00e9mios dos torneios de eSports s\u00e3o reconhecidos como &#8220;remunera\u00e7\u00e3o&#8221;.<\/p>\n\n\n\n<p>Devido a este sistema, o risco de os torneios com pr\u00e9mios serem sujeitos \u00e0 regulamenta\u00e7\u00e3o da Lei de Exibi\u00e7\u00e3o de Pr\u00e9mios diminuiu, tornando mais f\u00e1cil a realiza\u00e7\u00e3o destes torneios.<\/p>\n\n\n\n<p>Al\u00e9m disso, muitos torneios nacionais e internacionais est\u00e3o a ser realizados, e espera-se que o n\u00famero de participantes em eSports continue a aumentar no futuro.<\/p>\n\n\n\n<p>Refer\u00eancia: <a href=\"https:\/\/jesu.or.jp\/contents\/license_system\/\" target=\"_blank\" rel=\"noreferrer noopener\">Licen\u00e7a | Site Oficial da Associa\u00e7\u00e3o Japonesa de eSports[ja]<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Considera-se_um_segundo_emprego_ganhar_premios_em_competicoes_de_e-sports\"><\/span>Considera-se um segundo emprego ganhar pr\u00e9mios em competi\u00e7\u00f5es de e-sports?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/12\/e-sports-employee-ban2.jpg\" alt=\"Considera-se um segundo emprego ganhar pr\u00e9mios em competi\u00e7\u00f5es de e-sports?\" class=\"wp-image-26085\" \/><\/figure>\n\n\n\n<p>Se est\u00e1 a ganhar pr\u00e9mios em competi\u00e7\u00f5es de e-sports, ser\u00e1 que isso se considera um segundo emprego? Mesmo que esteja a ganhar pr\u00e9mios em e-sports, a realidade varia bastante.<\/p>\n\n\n\n<p>\u00c9 necess\u00e1rio avaliar se isso se enquadra como um segundo emprego com base na realidade, mas, em primeiro lugar, n\u00e3o existe uma defini\u00e7\u00e3o clara de &#8220;segundo emprego&#8221;.<\/p>\n\n\n\n<p>Como ser\u00e1 explicado em detalhe mais adiante, no caso de um empregado de uma empresa, n\u00e3o h\u00e1 proibi\u00e7\u00e3o legal de ter um segundo emprego, mas pode haver problemas se o regulamento interno da empresa proibir um segundo emprego.<\/p>\n\n\n\n<p>A decis\u00e3o sobre o que \u00e9 considerado um segundo emprego varia, mas a classifica\u00e7\u00e3o de renda parece ser um crit\u00e9rio de julgamento.<\/p>\n\n\n\n<p>Os pr\u00e9mios ganhos em competi\u00e7\u00f5es de e-sports s\u00e3o tributados e \u00e9 necess\u00e1rio fazer uma declara\u00e7\u00e3o de imposto de renda. Nesse momento, se a classifica\u00e7\u00e3o de renda \u00e9 &#8220;renda tempor\u00e1ria&#8221; ou &#8220;renda de neg\u00f3cios&#8221; pode ser um dos crit\u00e9rios para determinar se \u00e9 um segundo emprego.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Se_declarar_o_premio_como_renda_temporaria\"><\/span>Se declarar o pr\u00e9mio como renda tempor\u00e1ria<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Se voc\u00ea joga jogos online como um hobby, sem o objetivo de lucro, e ocasionalmente ganha um pr\u00e9mio ao participar de um torneio nos fins de semana, \u00e9 prov\u00e1vel que isso seja considerado renda tempor\u00e1ria. Se o pr\u00e9mio do torneio for superior a 200.000 ienes por ano, ser\u00e1 necess\u00e1rio declarar o imposto de renda.<\/p>\n\n\n\n<p>Se declarar o pr\u00e9mio como renda tempor\u00e1ria, \u00e9 prov\u00e1vel que seja considerado apenas um hobby e n\u00e3o um segundo emprego.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Se_declarar_o_premio_como_renda_de_negocios\"><\/span>Se declarar o pr\u00e9mio como renda de neg\u00f3cios<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Se voc\u00ea est\u00e1 ganhando pr\u00e9mios de forma cont\u00ednua em torneios ou tem uma licen\u00e7a profissional, \u00e9 prov\u00e1vel que isso seja considerado renda de neg\u00f3cios. Se ganhar mais de 480.000 ienes por ano em pr\u00e9mios de torneios, ser\u00e1 necess\u00e1rio declarar o imposto de renda.<\/p>\n\n\n\n<p>Se um empregado de uma empresa est\u00e1 ganhando pr\u00e9mios de forma cont\u00ednua desta maneira, ou ganhando pr\u00e9mios como um jogador profissional, dependendo do n\u00famero de vezes, \u00e9 prov\u00e1vel que seja considerado um segundo emprego.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Eficacia_da_proibicao_de_trabalho_secundario_nas_regras_de_emprego\"><\/span>Efic\u00e1cia da proibi\u00e7\u00e3o de trabalho secund\u00e1rio nas regras de emprego<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Em primeiro lugar, existe alguma base legal para a proibi\u00e7\u00e3o de trabalho secund\u00e1rio nas regras de emprego?<\/p>\n\n\n\n<p>Na verdade, n\u00e3o h\u00e1 disposi\u00e7\u00f5es que pro\u00edbam o trabalho secund\u00e1rio nas leis relacionadas ao trabalho, como a lei laboral e o c\u00f3digo civil. No entanto, pode haver casos em que \u00e9 proibido ou limitado pelas &#8220;regras de emprego&#8221; da empresa.<\/p>\n\n\n\n<p>Al\u00e9m disso, no caso dos funcion\u00e1rios p\u00fablicos, \u00e9 proibido pela &#8220;lei&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/12\/e-sports-employee-ban3.jpg\" alt=\"Efic\u00e1cia da proibi\u00e7\u00e3o de trabalho secund\u00e1rio nas regras de emprego\" class=\"wp-image-26086\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Criterios_para_determinar_se_os_e-sports_sao_considerados_trabalho_secundario_proibido_pelas_regras_de_emprego_da_empresa\"><\/span>Crit\u00e9rios para determinar se os e-sports s\u00e3o considerados trabalho secund\u00e1rio proibido pelas regras de emprego da empresa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>De acordo com a jurisprud\u00eancia, como os trabalhadores passam o seu tempo fora do hor\u00e1rio de trabalho \u00e9 basicamente uma quest\u00e3o de liberdade pessoal, e as empresas n\u00e3o t\u00eam permiss\u00e3o para restringir essa liberdade.<\/p>\n\n\n\n<p>Quanto \u00e0 proibi\u00e7\u00e3o geral do trabalho secund\u00e1rio, o caso Ogawa Construction (decis\u00e3o do Tribunal Distrital de T\u00f3quio, 19 de novembro de 1982 (Showa 57), cole\u00e7\u00e3o de casos de trabalho civil, volume 33, n\u00famero 6, p\u00e1gina 1028) tamb\u00e9m afirmou que &#8220;a proibi\u00e7\u00e3o total do trabalho secund\u00e1rio nas regras de emprego \u00e9 irracional, exceto em casos especiais, uma vez que o tempo fora do hor\u00e1rio de trabalho \u00e9 basicamente uma quest\u00e3o de liberdade para os trabalhadores&#8221;.<\/p>\n\n\n\n<p>Ent\u00e3o, em que circunst\u00e2ncias \u00e9 considerado uma viola\u00e7\u00e3o das regras de emprego? De acordo com a jurisprud\u00eancia, foi reconhecido como uma viola\u00e7\u00e3o das regras de emprego nos seguintes casos:<\/p>\n\n\n\n<ul>\n<li>Quando causa uma interfer\u00eancia clara no trabalho principal (por exemplo, quando o tempo dedicado ao trabalho secund\u00e1rio \u00e9 longo e se estende at\u00e9 tarde da noite todos os dias)<\/li>\n\n\n\n<li>Quando segredos comerciais s\u00e3o vazados, constituindo uma viola\u00e7\u00e3o do dever de confidencialidade (por exemplo, quando se trabalha em uma empresa concorrente)<\/li>\n\n\n\n<li>Quando prejudica a reputa\u00e7\u00e3o da empresa ou destr\u00f3i a rela\u00e7\u00e3o de confian\u00e7a (por exemplo, quando se envolve em trabalho secund\u00e1rio com for\u00e7as antisociais)<\/li>\n\n\n\n<li>Quando prejudica a empresa por meio de concorr\u00eancia (por exemplo, quando se envolve em um neg\u00f3cio do mesmo tipo que o trabalho principal como trabalho secund\u00e1rio)<\/li>\n<\/ul>\n\n\n\n<p>Portanto, mesmo que voc\u00ea ganhe dinheiro com e-sports, a probabilidade de ser sujeito a san\u00e7\u00f5es disciplinares aplicando a proibi\u00e7\u00e3o de trabalho secund\u00e1rio \u00e9 baixa, a menos que se enquadre nos casos acima.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Criterios_para_determinar_se_os_e-sports_sao_considerados_trabalho_secundario_para_funcionarios_publicos\"><\/span>Crit\u00e9rios para determinar se os e-sports s\u00e3o considerados trabalho secund\u00e1rio para funcion\u00e1rios p\u00fablicos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Como mencionado anteriormente, o trabalho secund\u00e1rio para funcion\u00e1rios p\u00fablicos \u00e9 proibido por &#8220;lei&#8221;. Isso ocorre porque os funcion\u00e1rios p\u00fablicos s\u00e3o servidores de todos os cidad\u00e3os e s\u00e3o exigidos a serem justos e imparciais em seus deveres. Para os funcion\u00e1rios p\u00fablicos nacionais, a Lei dos Funcion\u00e1rios P\u00fablicos Nacionais estipula que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>Os funcion\u00e1rios n\u00e3o devem servir como diretores, consultores ou conselheiros de empresas que visam a condu\u00e7\u00e3o de neg\u00f3cios comerciais, industriais ou financeiros ou outras empresas privadas com fins lucrativos (doravante referidas como &#8220;empresas com fins lucrativos&#8221;), nem devem conduzir tais empresas por si mesmos.<\/p>\n<cite>Artigo 103, par\u00e1grafo 1, da Lei dos Funcion\u00e1rios P\u00fablicos Nacionais<\/cite><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>Os funcion\u00e1rios que recebem remunera\u00e7\u00e3o por servir como diretores, consultores ou conselheiros de organiza\u00e7\u00f5es que n\u00e3o s\u00e3o empresas com fins lucrativos, ou que se envolvem em qualquer outro neg\u00f3cio ou realizam qualquer outro trabalho, devem obter a permiss\u00e3o do Primeiro-Ministro e do chefe do \u00f3rg\u00e3o ao qual o funcion\u00e1rio pertence.<\/p>\n<cite>Artigo 104 da Lei dos Funcion\u00e1rios P\u00fablicos Nacionais<\/cite><\/blockquote>\n\n\n\n<p>Portanto, o trabalho secund\u00e1rio n\u00e3o \u00e9 permitido sem permiss\u00e3o.<\/p>\n\n\n\n<p>Quanto aos funcion\u00e1rios p\u00fablicos locais, \u00e9 estipulado que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>Os funcion\u00e1rios n\u00e3o devem, sem a permiss\u00e3o da autoridade de nomea\u00e7\u00e3o, servir como diretores ou ocupar outras posi\u00e7\u00f5es determinadas pelas regras da Comiss\u00e3o de Pessoal (ou pelas regras da entidade p\u00fablica local onde n\u00e3o h\u00e1 Comiss\u00e3o de Pessoal) de uma empresa que visa a condu\u00e7\u00e3o de neg\u00f3cios comerciais, industriais ou financeiros ou outras empresas privadas com fins lucrativos (doravante referidas como &#8220;empresas com fins lucrativos&#8221; neste par\u00e1grafo e no par\u00e1grafo 1 do pr\u00f3ximo artigo), nem devem conduzir tais empresas por si mesmos, nem devem se envolver em qualquer neg\u00f3cio ou trabalho para remunera\u00e7\u00e3o. No entanto, isso n\u00e3o se aplica aos funcion\u00e1rios em tempo parcial (excluindo os funcion\u00e1rios que ocupam cargos de trabalho de curta dura\u00e7\u00e3o e os funcion\u00e1rios listados no item 2 do par\u00e1grafo 1 do Artigo 22-2).<\/p>\n<cite>Artigo 38, par\u00e1grafo 1, da Lei dos Funcion\u00e1rios P\u00fablicos Locais<\/cite><\/blockquote>\n\n\n\n<p>Portanto, os funcion\u00e1rios p\u00fablicos est\u00e3o sujeitos a restri\u00e7\u00f5es mais rigorosas sobre o trabalho secund\u00e1rio do que os funcion\u00e1rios de empresas privadas.<\/p>\n\n\n\n<p>Ent\u00e3o, os e-sports s\u00e3o considerados trabalho secund\u00e1rio?<\/p>\n\n\n\n<p>Para repetir, n\u00e3o h\u00e1 crit\u00e9rio claro para determinar se ganhar dinheiro em torneios de e-sports \u00e9 considerado trabalho secund\u00e1rio.<\/p>\n\n\n\n<p>Ter\u00e1 de ser julgado de forma abrangente, considerando o valor do pr\u00e9mio, se o pr\u00e9mio \u00e9 recebido de forma repetida e cont\u00ednua, a classifica\u00e7\u00e3o de renda do pr\u00e9mio (renda \u00fanica ou renda de neg\u00f3cios), etc.<\/p>\n\n\n\n<p>Em geral, provavelmente n\u00e3o ser\u00e1 considerado trabalho secund\u00e1rio se voc\u00ea n\u00e3o tiver uma licen\u00e7a profissional e tiver recebido um pr\u00e9mio apenas uma vez.<\/p>\n\n\n\n<p>Como ainda n\u00e3o h\u00e1 precedentes sobre se as atividades como jogador de e-sports s\u00e3o consideradas trabalho secund\u00e1rio, ser\u00e1 necess\u00e1rio prestar aten\u00e7\u00e3o ao que tipo de julgamento os tribunais far\u00e3o no futuro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Receber_o_premio_de_eSports_como_remuneracao_do_trabalho\"><\/span>Receber o pr\u00e9mio de eSports como remunera\u00e7\u00e3o do trabalho<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Como mencionado anteriormente, quando um jogador com licen\u00e7a profissional ganha um pr\u00e9mio num torneio, esse pr\u00e9mio \u00e9 reconhecido como &#8220;remunera\u00e7\u00e3o do trabalho&#8221;, etc.<\/p>\n\n\n\n<p>Um dos objetivos do sistema de licen\u00e7as profissionais reconhecidas pela JeSU (Japanese eSports Union) \u00e9 clarificar que os jogadores de eSports s\u00e3o profissionais. Portanto, os jogadores que possuem uma licen\u00e7a profissional reconhecida pela JeSU s\u00e3o considerados profissionais de eSports.<\/p>\n\n\n\n<p>Assim, se possuir uma licen\u00e7a profissional reconhecida pela JeSU, o pr\u00e9mio ganho num torneio de eSports \u00e9 considerado rendimento empresarial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ganhar_premios_em_competicoes_de_e-sports_no_estrangeiro\"><\/span>Ganhar pr\u00e9mios em competi\u00e7\u00f5es de e-sports no estrangeiro<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2022\/08\/e-sports-employee-ban-rewrite1.png\" alt=\"Ganhar pr\u00e9mios em competi\u00e7\u00f5es de e-sports no estrangeiro\" class=\"wp-image-49696\" \/><\/figure>\n\n\n\n<p>Nos \u00faltimos anos, tem-se tornado cada vez mais comum a realiza\u00e7\u00e3o de competi\u00e7\u00f5es de e-sports no estrangeiro. Neste artigo, explicaremos como funciona o sistema de tributa\u00e7\u00e3o caso ganhe um pr\u00e9mio numa dessas competi\u00e7\u00f5es.<\/p>\n\n\n\n<p>\u00c9 f\u00e1cil entender que, se ganhar um pr\u00e9mio numa competi\u00e7\u00e3o de e-sports no Jap\u00e3o, ser\u00e1 tributado no Jap\u00e3o. Mas o que acontece se ganhar um pr\u00e9mio numa competi\u00e7\u00e3o no estrangeiro?<\/p>\n\n\n\n<p>De acordo com o Artigo 5, Par\u00e1grafo 1, da Lei do Imposto sobre o Rendimento (Lei do Imposto sobre o Rendimento Japonesa), os residentes no Jap\u00e3o t\u00eam a obriga\u00e7\u00e3o de pagar imposto sobre o rendimento, independentemente de o rendimento ter sido obtido no Jap\u00e3o ou no estrangeiro. Portanto, todos os rendimentos s\u00e3o tributados no Jap\u00e3o.<\/p>\n\n\n\n<p>No entanto, se ganhar um pr\u00e9mio numa competi\u00e7\u00e3o de e-sports no estrangeiro, pode acontecer que tamb\u00e9m seja tributado no pa\u00eds onde ganhou o pr\u00e9mio, de acordo com as leis desse pa\u00eds. Isto \u00e9 o que se chama dupla tributa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para evitar isso, o Artigo 95 da Lei do Imposto sobre o Rendimento (Lei do Imposto sobre o Rendimento Japonesa) estabelece um sistema chamado &#8220;dedu\u00e7\u00e3o do imposto estrangeiro&#8221;.<\/p>\n\n\n\n<p>Este sistema permite que, se pagou um imposto equivalente ao imposto sobre o rendimento num pa\u00eds estrangeiro durante um determinado ano, possa deduzir o montante desse imposto do seu imposto sobre o rendimento no Jap\u00e3o para esse ano, at\u00e9 um determinado limite.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resumo_Consulte_um_advogado_sobre_questoes_de_premios_de_eSports\"><\/span>Resumo: Consulte um advogado sobre quest\u00f5es de pr\u00e9mios de eSports<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Se estiver a receber pr\u00e9mios em torneios de eSports, a quantia do pr\u00e9mio e a categoria de rendimento na declara\u00e7\u00e3o de impostos ser\u00e3o consideradas para determinar se isso constitui um trabalho secund\u00e1rio.<\/p>\n\n\n\n<p>Para aqueles que t\u00eam a oportunidade de ganhar pr\u00e9mios em torneios de eSports al\u00e9m do seu trabalho principal, \u00e9 recomend\u00e1vel consultar um advogado com anteced\u00eancia para garantir que isso n\u00e3o se torne um problema como um trabalho secund\u00e1rio.<\/p>\n\n\n\n<p>Artigo relacionado: <a href=\"https:\/\/monolith.law\/corporate\/esports-jobs-check-point\" target=\"_blank\" rel=\"noreferrer noopener\">Pontos a considerar ao assinar um contrato de trabalho no crescente campo dos eSports[ja]<\/a><\/p>\n\n\n\n<p>Artigo relacionado: <a href=\"https:\/\/monolith.law\/corporate\/points-e-sports-contract\" target=\"_blank\" rel=\"noreferrer noopener\">Pontos a verificar no contrato de um jogador profissional de eSports[ja]<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Apresentacao_das_medidas_tomadas_pelo_nosso_escritorio\"><\/span>Apresenta\u00e7\u00e3o das medidas tomadas pelo nosso escrit\u00f3rio<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O escrit\u00f3rio de advocacia Monolis \u00e9 especializado em IT, particularmente na intersec\u00e7\u00e3o entre a Internet e a lei. No nosso escrit\u00f3rio, lidamos com a cria\u00e7\u00e3o e revis\u00e3o de contratos para uma variedade de casos, desde empresas cotadas na Bolsa de Valores de T\u00f3quio at\u00e9 startups. Se tiver problemas com contratos, por favor consulte o artigo abaixo.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/contractcreation\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/contractcreation[ja]<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O e-Sports refere-se \u00e0 considera\u00e7\u00e3o de competi\u00e7\u00f5es usando jogos de computador ou videojogos como desportos. A ind\u00fastria de e-Sports tem ganho popularidade nos \u00faltimos anos, com muitos torneios a ofere [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":69311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[25,24],"acf":[],"_links":{"self":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58159"}],"collection":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/comments?post=58159"}],"version-history":[{"count":2,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58159\/revisions"}],"predecessor-version":[{"id":69312,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58159\/revisions\/69312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media\/69311"}],"wp:attachment":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media?parent=58159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/categories?post=58159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/tags?post=58159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}