{"id":58181,"date":"2023-10-05T15:30:23","date_gmt":"2023-10-05T06:30:23","guid":{"rendered":"https:\/\/monolith.law\/pt\/?p=58181"},"modified":"2024-05-01T11:54:59","modified_gmt":"2024-05-01T02:54:59","slug":"sing-song-copyright-youtube","status":"publish","type":"post","link":"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube","title":{"rendered":"Explica\u00e7\u00e3o dos casos em que a publica\u00e7\u00e3o no YouTube de &#8216;Tentei Cantar&#8217; constitui uma viola\u00e7\u00e3o dos direitos de autor"},"content":{"rendered":"\n<p>Em sites de v\u00eddeos como o YouTube e o Nico Nico Douga, existe um g\u00e9nero popular chamado &#8220;Tentei Cantar&#8221;.<\/p>\n\n\n\n<p>&#8220;Tentei Cantar&#8221; \u00e9 um g\u00e9nero onde pessoas, conhecidas como &#8220;cantores&#8221;, ou amadores, cantam m\u00fasicas populares de J-POP, Vocaloid, entre outros, e postam os v\u00eddeos. Existem cantores que s\u00e3o t\u00e3o populares quanto os \u00eddolos, e o n\u00famero de visualiza\u00e7\u00f5es dos v\u00eddeos &#8220;Tentei Cantar&#8221; est\u00e1 a aumentar. No entanto, ser\u00e1 que n\u00e3o surgem problemas legais ao usar m\u00fasicas populares?<\/p>\n\n\n\n<p>Neste artigo, explicaremos os riscos legais que voc\u00ea deve conhecer ao postar v\u00eddeos &#8220;Tentei Cantar&#8221;.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Leis_relacionadas_com_%E2%80%9CTentei_Cantar%E2%80%9D\" title=\"Leis relacionadas com &#8220;Tentei Cantar&#8221;\">Leis relacionadas com &#8220;Tentei Cantar&#8221;<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Direitos_Autorais\" title=\"Direitos Autorais\">Direitos Autorais<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Direitos_Conexos\" title=\"Direitos Conexos\">Direitos Conexos<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#O_que_e_uma_entidade_de_gestao_coletiva_de_direitos_autorais\" title=\"O que \u00e9 uma entidade de gest\u00e3o coletiva de direitos autorais\">O que \u00e9 uma entidade de gest\u00e3o coletiva de direitos autorais<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Exemplos_de_entidades_de_gestao_coletiva_de_direitos_autorais\" title=\"Exemplos de entidades de gest\u00e3o coletiva de direitos autorais\">Exemplos de entidades de gest\u00e3o coletiva de direitos autorais<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Entidades_com_as_quais_os_sites_de_video_tem_contratos_abrangentes\" title=\"Entidades com as quais os sites de v\u00eddeo t\u00eam contratos abrangentes\">Entidades com as quais os sites de v\u00eddeo t\u00eam contratos abrangentes<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Casos_em_que_%E2%80%9CCantar_uma_Cancao%E2%80%9D_constitui_uma_violacao_dos_direitos_de_autor_e_dos_direitos_conexos\" title=\"Casos em que &#8220;Cantar uma Can\u00e7\u00e3o&#8221; constitui uma viola\u00e7\u00e3o dos direitos de autor e dos direitos conexos\">Casos em que &#8220;Cantar uma Can\u00e7\u00e3o&#8221; constitui uma viola\u00e7\u00e3o dos direitos de autor e dos direitos conexos<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Uso_de_uma_musica_que_nao_e_gerida_por_uma_organizacao_de_gestao_de_direitos_de_autor_e_para_a_qual_nao_foi_obtida_a_permissao_do_titular_dos_direitos_de_autor\" title=\"Uso de uma m\u00fasica que n\u00e3o \u00e9 gerida por uma organiza\u00e7\u00e3o de gest\u00e3o de direitos de autor e para a qual n\u00e3o foi obtida a permiss\u00e3o do titular dos direitos de autor\">Uso de uma m\u00fasica que n\u00e3o \u00e9 gerida por uma organiza\u00e7\u00e3o de gest\u00e3o de direitos de autor e para a qual n\u00e3o foi obtida a permiss\u00e3o do titular dos direitos de autor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Musicas_de_CDs_ou_servicos_de_streaming_de_musica_pagos\" title=\"M\u00fasicas de CDs ou servi\u00e7os de streaming de m\u00fasica pagos\">M\u00fasicas de CDs ou servi\u00e7os de streaming de m\u00fasica pagos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Musicas_filmadas_em_karaoke\" title=\"M\u00fasicas filmadas em karaok\u00ea\">M\u00fasicas filmadas em karaok\u00ea<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Como_publicar_%E2%80%9CTentei_Cantar%E2%80%9D_sem_infringir_a_lei_de_direitos_autorais\" title=\"Como publicar &#8220;Tentei Cantar&#8221; sem infringir a lei de direitos autorais\">Como publicar &#8220;Tentei Cantar&#8221; sem infringir a lei de direitos autorais<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Como_usar_musicas_fora_da_gestao_das_entidades_de_gestao_coletiva_de_direitos_autorais\" title=\"Como usar m\u00fasicas fora da gest\u00e3o das entidades de gest\u00e3o coletiva de direitos autorais\">Como usar m\u00fasicas fora da gest\u00e3o das entidades de gest\u00e3o coletiva de direitos autorais<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Riscos_legais_de_arranjos_e_versoes_de_%E2%80%9CTentei_Cantar%E2%80%9D\" title=\"Riscos legais de arranjos e vers\u00f5es de &#8220;Tentei Cantar&#8221;\">Riscos legais de arranjos e vers\u00f5es de &#8220;Tentei Cantar&#8221;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/monolith.law\/pt\/internet\/sing-song-copyright-youtube\/#Resumo_Tenha_cuidado_com_a_violacao_de_direitos_autorais_ao_%E2%80%9CCantar_para_Experimentar%E2%80%9D\" title=\"Resumo: Tenha cuidado com a viola\u00e7\u00e3o de direitos autorais ao &#8220;Cantar para Experimentar&#8221;\">Resumo: Tenha cuidado com a viola\u00e7\u00e3o de direitos autorais ao &#8220;Cantar para Experimentar&#8221;<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Leis_relacionadas_com_%E2%80%9CTentei_Cantar%E2%80%9D\"><\/span>Leis relacionadas com &#8220;Tentei Cantar&#8221;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/09\/sing-song-copyright-youtube2.jpg\" alt=\"Deusa da Justi\u00e7a\" class=\"wp-image-18935\" style=\"width:840px;height:560px\" \/><\/figure>\n\n\n\n<p>Existem dois direitos que devem ser considerados ao postar v\u00eddeos de &#8220;Tentei Cantar&#8221;: direitos autorais e direitos conexos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Direitos_Autorais\"><\/span>Direitos Autorais<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Os direitos autorais s\u00e3o direitos que protegem as obras. As obras s\u00e3o definidas na lei de direitos autorais japonesa da seguinte maneira:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>(Defini\u00e7\u00e3o)<br>Artigo 2, par\u00e1grafo 1, item 1 &#8211; Obras: refere-se a express\u00f5es criativas de pensamentos ou sentimentos que pertencem ao dom\u00ednio da literatura, academia, arte ou m\u00fasica.<\/p>\n<\/blockquote>\n\n\n\n<p>Com base nesta defini\u00e7\u00e3o, para ser reconhecido como uma obra, s\u00e3o necess\u00e1rios os seguintes quatro requisitos:<\/p>\n\n\n\n<ul>\n<li>Express\u00e3o criativa de<\/li>\n\n\n\n<li>pensamentos ou sentimentos que<\/li>\n\n\n\n<li>pertencem ao dom\u00ednio da<\/li>\n\n\n\n<li>literatura, academia, arte ou m\u00fasica<\/li>\n<\/ul>\n\n\n\n<p>Os direitos autorais surgem automaticamente quando uma obra \u00e9 criada. Ao contr\u00e1rio de direitos como patentes e marcas registradas, os direitos autorais s\u00e3o caracterizados pelo fato de que n\u00e3o \u00e9 necess\u00e1rio nenhum procedimento de aplica\u00e7\u00e3o para a gera\u00e7\u00e3o de direitos.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-\u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09 wp-block-embed-\u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"mqHdBwpZZf\"><a href=\"https:\/\/monolith.law\/pt\/general-corporate\/intellectual-property-infringement-risk\">O que s\u00e3o os riscos de viola\u00e7\u00e3o de direitos de propriedade intelectual como patentes, marcas registradas, direitos autorais e suas medidas de prote\u00e7\u00e3o?<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;O que s\u00e3o os riscos de viola\u00e7\u00e3o de direitos de propriedade intelectual como patentes, marcas registradas, direitos autorais e suas medidas de prote\u00e7\u00e3o?&#8221; &#8212; \u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09\" src=\"https:\/\/monolith.law\/pt\/general-corporate\/intellectual-property-infringement-risk\/embed#?secret=1E4H9jKgWp#?secret=mqHdBwpZZf\" data-secret=\"mqHdBwpZZf\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Direitos_Conexos\"><\/span>Direitos Conexos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Os direitos conexos s\u00e3o direitos concedidos a artistas e produtores de discos, entre outros.<\/p>\n\n\n\n<p>N\u00e3o importa qu\u00e3o maravilhosas sejam as m\u00fasicas e letras, se n\u00e3o houver quem as transmita, elas n\u00e3o ser\u00e3o transmitidas a outros. Portanto, a lei de direitos autorais japonesa concede direitos conexos a artistas e produtores de discos para incentivar a transmiss\u00e3o.<\/p>\n\n\n\n<p>O termo &#8220;artista&#8221; aqui se refere a cantores e m\u00fasicos, entre outros, que realizam obras. Al\u00e9m disso, um &#8220;produtor de discos&#8221; \u00e9 aquele que fez o primeiro disco mestre (master record) a partir da performance ao vivo de um artista. Os direitos conexos surgem automaticamente quando tais atos como cantar e criar um disco mestre s\u00e3o realizados por essas pessoas.<\/p>\n\n\n\n<p>Portanto, ao postar v\u00eddeos de &#8220;Tentei Cantar&#8221;, \u00e9 necess\u00e1rio prestar aten\u00e7\u00e3o n\u00e3o apenas aos direitos autorais das m\u00fasicas e letras, mas tamb\u00e9m aos direitos conexos dos artistas e produtores de discos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_e_uma_entidade_de_gestao_coletiva_de_direitos_autorais\"><\/span>O que \u00e9 uma entidade de gest\u00e3o coletiva de direitos autorais<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/09\/sing-song-copyright-youtube3.jpg\" alt=\"\u00c1lbuns de CD \u00e0 venda numa loja\" class=\"wp-image-18937\" style=\"width:839px;height:559px\" \/><\/figure>\n\n\n\n<p>Existem in\u00fameros g\u00e9neros musicais, can\u00e7\u00f5es e letras no mundo.<\/p>\n\n\n\n<p>Quando se pretende obter a permiss\u00e3o para usar estas obras, \u00e9 necess\u00e1rio negociar com uma entidade de gest\u00e3o coletiva de direitos autorais (organiza\u00e7\u00e3o de cobran\u00e7a de direitos autorais).<\/p>\n\n\n\n<p>Uma entidade de gest\u00e3o coletiva de direitos autorais \u00e9 uma organiza\u00e7\u00e3o que atua em nome dos titulares de direitos autorais, cobrando taxas de uso de direitos autorais daqueles que desejam usar as obras. Se receber a permiss\u00e3o para usar uma obra musical de uma entidade de gest\u00e3o coletiva de direitos autorais, poder\u00e1 usar a m\u00fasica sem ter que obter permiss\u00e3o individual do titular dos direitos autorais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Exemplos_de_entidades_de_gestao_coletiva_de_direitos_autorais\"><\/span>Exemplos de entidades de gest\u00e3o coletiva de direitos autorais<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>As seguintes organiza\u00e7\u00f5es s\u00e3o representativas:<\/p>\n\n\n\n<ul>\n<li>Associa\u00e7\u00e3o Japonesa de Direitos Autorais Musicais (JASRAC)<\/li>\n\n\n\n<li>Organiza\u00e7\u00e3o Japonesa de Direitos Autorais de Arte &#8211; Associa\u00e7\u00e3o de Direitos Autorais de Arte<\/li>\n\n\n\n<li>NexTone<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Entidades_com_as_quais_os_sites_de_video_tem_contratos_abrangentes\"><\/span>Entidades com as quais os sites de v\u00eddeo t\u00eam contratos abrangentes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Em sites de partilha de v\u00eddeos onde s\u00e3o postados v\u00eddeos de &#8220;Tentei Cantar&#8221;, \u00e9 comum terem um contrato de licen\u00e7a de uso abrangente com uma entidade de gest\u00e3o coletiva de direitos autorais. E se tal contrato abrangente estiver em vigor, o remetente pode postar um v\u00eddeo de &#8220;Tentei Cantar&#8221; sem ter que obter permiss\u00e3o individual do titular dos direitos autorais ou da entidade de gest\u00e3o coletiva de direitos autorais.<\/p>\n\n\n\n<p>YouTube e NicoNico Video t\u00eam contratos abrangentes com a JASRAC e a NexTone. Se estiver a usar outros sites, certifique-se de verificar a entidade de gest\u00e3o coletiva de direitos autorais com a qual t\u00eam um contrato abrangente.<\/p>\n\n\n\n<p>No entanto, as entidades de gest\u00e3o coletiva de direitos autorais gerem apenas os &#8220;direitos autorais&#8221;, e n\u00e3o gerem os direitos conexos dos artistas int\u00e9rpretes ou executantes ou dos produtores de discos. Portanto, mesmo que exista um contrato abrangente, ainda \u00e9 necess\u00e1rio ter cuidado com os direitos conexos, como ser\u00e1 explicado posteriormente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Casos_em_que_%E2%80%9CCantar_uma_Cancao%E2%80%9D_constitui_uma_violacao_dos_direitos_de_autor_e_dos_direitos_conexos\"><\/span>Casos em que &#8220;Cantar uma Can\u00e7\u00e3o&#8221; constitui uma viola\u00e7\u00e3o dos direitos de autor e dos direitos conexos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2022\/05\/shutterstock_1606120423.jpg\" alt=\"Mulher a pesquisar direitos de autor no PC\" class=\"wp-image-44933\" \/><\/figure>\n\n\n\n<p>Em que circunst\u00e2ncias um v\u00eddeo de &#8220;Cantar uma Can\u00e7\u00e3o&#8221; pode constituir uma viola\u00e7\u00e3o dos direitos de autor?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Uso_de_uma_musica_que_nao_e_gerida_por_uma_organizacao_de_gestao_de_direitos_de_autor_e_para_a_qual_nao_foi_obtida_a_permissao_do_titular_dos_direitos_de_autor\"><\/span>Uso de uma m\u00fasica que n\u00e3o \u00e9 gerida por uma organiza\u00e7\u00e3o de gest\u00e3o de direitos de autor e para a qual n\u00e3o foi obtida a permiss\u00e3o do titular dos direitos de autor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>No caso de uma m\u00fasica que n\u00e3o \u00e9 gerida por uma organiza\u00e7\u00e3o de gest\u00e3o de direitos de autor, se n\u00e3o tiver sido obtida a permiss\u00e3o do titular dos direitos de autor para a sua utiliza\u00e7\u00e3o, isso constituir\u00e1 uma viola\u00e7\u00e3o dos direitos de autor.<\/p>\n\n\n\n<p>Concretamente, a a\u00e7\u00e3o de filmar o ato de cantar com uma c\u00e2mara de v\u00eddeo, por exemplo, infringe o direito de reprodu\u00e7\u00e3o, e a a\u00e7\u00e3o de carregar o v\u00eddeo filmado no YouTube ou similar infringe o direito de transmiss\u00e3o ao p\u00fablico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Musicas_de_CDs_ou_servicos_de_streaming_de_musica_pagos\"><\/span>M\u00fasicas de CDs ou servi\u00e7os de streaming de m\u00fasica pagos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Se tiver sido obtida a permiss\u00e3o do titular dos direitos de autor ou da organiza\u00e7\u00e3o de gest\u00e3o de direitos de autor para a sua utiliza\u00e7\u00e3o, em princ\u00edpio, n\u00e3o constituir\u00e1 uma viola\u00e7\u00e3o dos direitos de autor.<\/p>\n\n\n\n<p>No entanto, o uso de m\u00fasicas de CDs ou servi\u00e7os de streaming de m\u00fasica, etc., em v\u00eddeos sem a permiss\u00e3o do int\u00e9rprete ou do produtor do disco, constitui uma viola\u00e7\u00e3o dos direitos conexos.<\/p>\n\n\n\n<p>Concretamente, a a\u00e7\u00e3o de filmar o ato de cantar usando a m\u00fasica infringe o direito de grava\u00e7\u00e3o do int\u00e9rprete e o direito de reprodu\u00e7\u00e3o do produtor do disco. Al\u00e9m disso, a a\u00e7\u00e3o de carregar o v\u00eddeo filmado infringe o direito de disponibiliza\u00e7\u00e3o ao p\u00fablico do int\u00e9rprete e do produtor do disco.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Musicas_filmadas_em_karaoke\"><\/span>M\u00fasicas filmadas em karaok\u00ea<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Postar um v\u00eddeo de si mesmo cantando em karaok\u00ea no YouTube, etc., n\u00e3o constitui uma viola\u00e7\u00e3o dos direitos de autor, desde que tenha sido obtida a permiss\u00e3o do titular dos direitos de autor ou da organiza\u00e7\u00e3o de gest\u00e3o de direitos de autor para a sua utiliza\u00e7\u00e3o.<\/p>\n\n\n\n<p>No entanto, as m\u00fasicas que s\u00e3o tocadas em karaok\u00ea, como as do DAM, s\u00e3o detidas pelo produtor da m\u00fasica de karaok\u00ea como produtor do disco. Portanto, se a m\u00fasica de karaok\u00ea estiver inclu\u00edda no v\u00eddeo filmado em karaok\u00ea, isso infringe os direitos conexos do produtor do disco, como o direito de reprodu\u00e7\u00e3o e o direito de disponibiliza\u00e7\u00e3o ao p\u00fablico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_publicar_%E2%80%9CTentei_Cantar%E2%80%9D_sem_infringir_a_lei_de_direitos_autorais\"><\/span>Como publicar &#8220;Tentei Cantar&#8221; sem infringir a lei de direitos autorais<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Que m\u00e9todos existem para criar v\u00eddeos de &#8220;Tentei Cantar&#8221; sem infringir a lei de direitos autorais?<\/p>\n\n\n\n<p>Primeiramente, se voc\u00ea est\u00e1 a postar no YouTube ou no Nico Nico Douga, se a m\u00fasica ou a letra \u00e9 gerida pela JASRAC ou pela NexTone, com as quais tem um contrato abrangente, em princ\u00edpio, pode postar v\u00eddeos de &#8220;Tentei Cantar&#8221; sem obter permiss\u00e3o individual de uso, sem infringir os direitos autorais.<\/p>\n\n\n\n<p>Pode verificar se a m\u00fasica \u00e9 gerida pesquisando no &#8220;Servi\u00e7o de Pesquisa de Base de Dados de Obras da JASRAC&#8221; ou na &#8220;Base de Dados de Pesquisa de Obras da NexTone&#8221;.<\/p>\n\n\n\n<p>No entanto, mesmo que a m\u00fasica seja gerida por uma organiza\u00e7\u00e3o de gest\u00e3o de direitos autorais, \u00e9 necess\u00e1rio ter cuidado, pois o tipo de direitos autorais geridos e a forma como a obra \u00e9 usada podem ser limitados.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/10\/j-wid-1024x470.png\" alt=\"Captura de ecr\u00e3 dos termos de uso da base de dados de pesquisa de obras\" class=\"wp-image-19087\" \/><figcaption class=\"wp-element-caption\"><a href=\"http:\/\/J-WID http:\/\/www2.jasrac.or.jp\/eJwid\/\" target=\"_blank\" rel=\"noreferrer noopener\">J-WID Servi\u00e7o de Pesquisa de Base de Dados de Obras &#8211; Ecr\u00e3 de Aceita\u00e7\u00e3o [ja]<\/a><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/10\/nextone.png\" alt=\"\" class=\"wp-image-19088\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/search.nex-tone.co.jp\/terms?1\" target=\"_blank\" rel=\"noreferrer noopener\"> NexTone Base de Dados de Pesquisa de Obras &#8211; Termos de Uso[ja]<\/a><\/figcaption><\/figure>\n\n\n\n<p>Contudo, o que \u00e9 gerido pela organiza\u00e7\u00e3o de gest\u00e3o de direitos autorais \u00e9 apenas o &#8220;direito autoral&#8221;. Portanto, o uso n\u00e3o autorizado de grava\u00e7\u00f5es de CDs, etc., infringe os direitos conexos.<\/p>\n\n\n\n<p>Portanto, se quiser usar uma grava\u00e7\u00e3o em &#8220;Tentei Cantar&#8221;, precisar\u00e1 obter permiss\u00e3o separada do int\u00e9rprete ou do produtor do disco. Normalmente, os artistas transferem os seus direitos conexos para os produtores de discos atrav\u00e9s de contratos de desempenho exclusivo. Portanto, normalmente \u00e9 suficiente obter permiss\u00e3o do produtor do disco.<\/p>\n\n\n\n<p>Al\u00e9m disso, se for dif\u00edcil negociar a permiss\u00e3o para usar a grava\u00e7\u00e3o, pode procurar grava\u00e7\u00f5es instrumentais ou grava\u00e7\u00f5es instrumentais de obras derivadas que tenham permiss\u00e3o para uso, ou pode criar a sua pr\u00f3pria grava\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_usar_musicas_fora_da_gestao_das_entidades_de_gestao_coletiva_de_direitos_autorais\"><\/span>Como usar m\u00fasicas fora da gest\u00e3o das entidades de gest\u00e3o coletiva de direitos autorais<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/09\/sing-song-copyright-youtube4.jpg\" alt=\"Est\u00fadio de m\u00fasica\" class=\"wp-image-18939\" style=\"width:840px;height:560px\" \/><\/figure>\n\n\n\n<p>Se deseja usar m\u00fasicas que n\u00e3o est\u00e3o sob a gest\u00e3o das entidades de gest\u00e3o coletiva de direitos autorais, pode faz\u00ea-lo obtendo permiss\u00e3o individualmente do detentor dos direitos autorais.<\/p>\n\n\n\n<p>Recomendamos que pesquise na Internet com anteced\u00eancia, pois, dependendo da m\u00fasica, o detentor dos direitos autorais pode ter disponibilizado a faixa para v\u00eddeos de &#8220;cante junto&#8221; no seu site.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Riscos_legais_de_arranjos_e_versoes_de_%E2%80%9CTentei_Cantar%E2%80%9D\"><\/span>Riscos legais de arranjos e vers\u00f5es de &#8220;Tentei Cantar&#8221;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2022\/05\/shutterstock_2051931419.jpg\" alt=\"Mulher com headphones\" class=\"wp-image-44438\" style=\"width:838px;height:559px\" \/><\/figure>\n\n\n\n<p>Quando se faz um arranjo ou uma vers\u00e3o de uma m\u00fasica, \u00e9 comum adicionar algum tipo de altera\u00e7\u00e3o sem perder a forma original da m\u00fasica. Nesse caso, pode haver uma viola\u00e7\u00e3o dos direitos de arranjo e adapta\u00e7\u00e3o, que s\u00e3o um dos direitos autorais.<\/p>\n\n\n\n<p>No entanto, a JASRAC (Sociedade Japonesa de Direitos de Autor, Compositores e Editores) n\u00e3o recebeu a transfer\u00eancia dos direitos de arranjo e adapta\u00e7\u00e3o dos detentores dos direitos autorais. Portanto, mesmo que o YouTube e outros tenham um contrato abrangente com a JASRAC, se voc\u00ea fizer um arranjo ou uma vers\u00e3o de uma m\u00fasica sem permiss\u00e3o, isso ser\u00e1 uma viola\u00e7\u00e3o dos direitos autorais. Portanto, \u00e9 necess\u00e1rio obter permiss\u00e3o individual do detentor dos direitos autorais para o arranjo ou vers\u00e3o da m\u00fasica.<\/p>\n\n\n\n<p>Al\u00e9m disso, ao fazer um arranjo ou uma vers\u00e3o de uma m\u00fasica, \u00e9 necess\u00e1rio prestar aten\u00e7\u00e3o aos direitos morais do autor, que protegem os interesses pessoais do autor, al\u00e9m dos direitos autorais e dos direitos conexos.<\/p>\n\n\n\n<p>\u00c9 comum que o ambiente da m\u00fasica mude drasticamente devido ao arranjo ou \u00e0 vers\u00e3o, e que os compositores e letristas fiquem insatisfeitos. Nesses casos, os compositores e letristas podem alegar a viola\u00e7\u00e3o do direito de manter a integridade, que \u00e9 um dos direitos morais do autor. Portanto, \u00e9 importante obter permiss\u00e3o do autor para o arranjo ou vers\u00e3o da m\u00fasica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resumo_Tenha_cuidado_com_a_violacao_de_direitos_autorais_ao_%E2%80%9CCantar_para_Experimentar%E2%80%9D\"><\/span>Resumo: Tenha cuidado com a viola\u00e7\u00e3o de direitos autorais ao &#8220;Cantar para Experimentar&#8221;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2022\/05\/shutterstock_1600645747.jpg\" alt=\"Mulher a ouvir m\u00fasica num tablet\" class=\"wp-image-44439\" style=\"width:839px;height:559px\" \/><\/figure>\n\n\n\n<p>Se est\u00e1 a pensar em publicar um v\u00eddeo de &#8220;Cantar para Experimentar&#8221;, \u00e9 necess\u00e1rio entender completamente as rela\u00e7\u00f5es legais de direitos autorais, direitos conexos e direitos morais do autor.<br>Publica\u00e7\u00f5es sem a permiss\u00e3o do detentor dos direitos autorais podem resultar em a\u00e7\u00f5es judiciais por atos il\u00edcitos, por isso \u00e9 necess\u00e1rio ter muito cuidado.<\/p>\n\n\n\n<p>Se tiver alguma d\u00favida, consulte um advogado especializado em propriedade intelectual antes de publicar um v\u00eddeo de &#8220;Cantar para Experimentar&#8221;.<\/p>\n\n\n\n<p>Se quiser saber o conte\u00fado deste artigo em v\u00eddeo, veja o v\u00eddeo no nosso canal do YouTube.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u300c\u6b4c\u3063\u3066\u307f\u305f\u300d\u52d5\u753b\u3092\u8457\u4f5c\u6a29\u4fb5\u5bb3\u306b\u306a\u3089\u305a\u306b\u64ae\u308b\u65b9\u6cd5\u3068\u306f\uff1f\u3010\u6b4c\u3044\u624b\u30fbVtuber\u306a\u3069\u306b\u5411\u3051\u3066\u308f\u304b\u308a\u3084\u3059\u304f\u89e3\u8aac\u3011\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/rKuB44pUvp8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio\"><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em sites de v\u00eddeos como o YouTube e o Nico Nico Douga, existe um g\u00e9nero popular chamado &#8220;Tentei Cantar&#8221;. &#8220;Tentei Cantar&#8221; \u00e9 um g\u00e9nero onde pessoas, conhecidas como &#8220;cantor [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":69420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[21,22],"acf":[],"_links":{"self":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58181"}],"collection":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/comments?post=58181"}],"version-history":[{"count":2,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58181\/revisions"}],"predecessor-version":[{"id":69421,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58181\/revisions\/69421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media\/69420"}],"wp:attachment":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media?parent=58181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/categories?post=58181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/tags?post=58181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}