{"id":58520,"date":"2023-11-10T19:14:32","date_gmt":"2023-11-10T10:14:32","guid":{"rendered":"https:\/\/monolith.law\/pt\/?p=58520"},"modified":"2023-11-29T22:36:50","modified_gmt":"2023-11-29T13:36:50","slug":"legal-liability-for-using-non-free-material-images","status":"publish","type":"post","link":"https:\/\/monolith.law\/pt\/internet\/legal-liability-for-using-non-free-material-images","title":{"rendered":"Responsabilidade legal ao usar imagens que se acredita serem de uso livre, mas que n\u00e3o s\u00e3o"},"content":{"rendered":"\n<p>Acredito que possa haver ocasi\u00f5es em que se utilizem materiais gratuitos, como bot\u00f5es ou \u00edcones, nos websites que criam internamente. Nesses casos, pode-se pesquisar em motores de busca por termos como &#8220;material gratuito imagem&#8221; ou &#8220;imagem sem direitos de autor&#8221;, e usar as imagens que aparecem nos resultados.<\/p>\n\n\n\n<p>Contudo, \u00e9 perigoso assumir que uma imagem que aparece nos resultados de um motor de busca \u00e9 material gratuito e us\u00e1-la nos seus bot\u00f5es ou \u00edcones. Isto porque nem todas as imagens que aparecem nos resultados de um motor de busca s\u00e3o necessariamente materiais gratuitos. Algumas podem requerer permiss\u00e3o para serem utilizadas. Al\u00e9m disso, pode haver casos em que imagens que n\u00e3o s\u00e3o materiais gratuitos se infiltram em sites que apresentam materiais gratuitos. Neste artigo, explicaremos a responsabilidade legal que pode surgir ao usar imagens que se acredita serem materiais gratuitos, mas que na realidade n\u00e3o o s\u00e3o.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/corporate\/points-of-using-free-materials\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/corporate\/points-of-using-free-materials[ja]<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/corporate\/quote-text-and-images-without-infringing-copyright\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/corporate\/quote-text-and-images-without-infringing-copyright[ja]<\/a><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-liability-for-using-non-free-material-images\/#Responsabilidade_legal_potencial_por_usar_imagens_acreditando_serem_de_uso_livre_quando_na_verdade_nao_sao\" title=\"Responsabilidade legal potencial por usar imagens, acreditando serem de uso livre, quando na verdade n\u00e3o s\u00e3o\">Responsabilidade legal potencial por usar imagens, acreditando serem de uso livre, quando na verdade n\u00e3o s\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-liability-for-using-non-free-material-images\/#Responsabilidade_por_danos_com_base_em_atos_ilicitos_%E2%91%A0\" title=\"Responsabilidade por danos com base em atos il\u00edcitos \u2460\">Responsabilidade por danos com base em atos il\u00edcitos \u2460<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-liability-for-using-non-free-material-images\/#Resumo_do_caso\" title=\"Resumo do caso\">Resumo do caso<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-liability-for-using-non-free-material-images\/#Argumentos_do_reu\" title=\"Argumentos do r\u00e9u\">Argumentos do r\u00e9u<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-liability-for-using-non-free-material-images\/#Decisao_do_tribunal\" title=\"Decis\u00e3o do tribunal\">Decis\u00e3o do tribunal<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-liability-for-using-non-free-material-images\/#Pedido_de_cessacao_de_atos_de_infracao_etc_%E2%91%A1\" title=\"Pedido de cessa\u00e7\u00e3o de atos de infra\u00e7\u00e3o, etc. \u2461\">Pedido de cessa\u00e7\u00e3o de atos de infra\u00e7\u00e3o, etc. \u2461<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-liability-for-using-non-free-material-images\/#Diferenca_entre_%E2%91%A0_e_%E2%91%A1_Necessidade_de_intencao_ou_negligencia\" title=\"Diferen\u00e7a entre \u2460 e \u2461: Necessidade de inten\u00e7\u00e3o ou neglig\u00eancia\">Diferen\u00e7a entre \u2460 e \u2461: Necessidade de inten\u00e7\u00e3o ou neglig\u00eancia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-liability-for-using-non-free-material-images\/#Resumo\" title=\"Resumo\">Resumo<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Responsabilidade_legal_potencial_por_usar_imagens_acreditando_serem_de_uso_livre_quando_na_verdade_nao_sao\"><\/span>Responsabilidade legal potencial por usar imagens, acreditando serem de uso livre, quando na verdade n\u00e3o s\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2019\/11\/shutterstock_569701894-1024x683.jpg\" alt=\"\" class=\"wp-image-5670\" \/><figcaption class=\"wp-element-caption\">Explicamos um caso judicial que envolve o uso de materiais que se acreditava serem de uso livre, mas que na verdade n\u00e3o eram.<\/figcaption><\/figure>\n\n\n\n<p>Se usar imagens ou outros materiais acreditando serem de uso livre, quando na verdade n\u00e3o s\u00e3o, pode estar a infringir os direitos de autor e, como tal, pode ser alvo das seguintes reivindica\u00e7\u00f5es por parte do titular dos direitos:<\/p>\n\n\n\n<ol>\n<li>Responsabilidade por danos com base em atos il\u00edcitos (Artigo 709 do C\u00f3digo Civil Japon\u00eas)<\/li>\n\n\n\n<li>Pedido de cessa\u00e7\u00e3o de atos de infra\u00e7\u00e3o, etc. (Artigo 112 da Lei de Direitos Autorais Japonesa)<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Responsabilidade_por_danos_com_base_em_atos_ilicitos_%E2%91%A0\"><\/span>Responsabilidade por danos com base em atos il\u00edcitos \u2460<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O artigo 709 do C\u00f3digo Civil Japon\u00eas estabelece que &#8220;qualquer pessoa que viole os direitos ou interesses de outrem protegidos por lei, por dolo ou neglig\u00eancia, \u00e9 respons\u00e1vel pela repara\u00e7\u00e3o dos danos causados&#8221;. Se usar uma imagem que acreditava ser de uso livre, mas que na verdade n\u00e3o \u00e9, pode-se dizer que violou os &#8220;direitos de outrem&#8221;, neste caso, os direitos de autor. Al\u00e9m disso, se a obra for usada sem permiss\u00e3o, n\u00e3o poder\u00e1 receber royalties, o que tamb\u00e9m pode ser considerado um &#8220;dano&#8221;. Quanto aos danos causados pela viola\u00e7\u00e3o dos direitos de autor, o c\u00e1lculo \u00e9 dif\u00edcil, por isso o artigo 114 da Lei dos Direitos de Autor Japonesa estabelece as quest\u00f5es relacionadas ao c\u00e1lculo do montante dos danos.<\/p>\n\n\n\n<p>Contudo, se estiver na posi\u00e7\u00e3o de algu\u00e9m que usou uma imagem que acreditava ser de uso livre, mas que na verdade n\u00e3o \u00e9, pode querer argumentar que &#8220;n\u00e3o houve dolo ou neglig\u00eancia, pois acreditava que era de uso livre&#8221;. Na verdade, h\u00e1 um caso judicial semelhante (decis\u00e3o do Tribunal Distrital de T\u00f3quio de 15 de abril do ano 27 da era Heisei (2015), caso n\u00ba 24391 do ano 26 da era Heisei (2014)), onde foi reconhecida a obriga\u00e7\u00e3o de indemniza\u00e7\u00e3o de cerca de 200.000 ienes para a pessoa que usou uma imagem que acreditava ser de uso livre, mas que na verdade n\u00e3o era.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resumo_do_caso\"><\/span>Resumo do caso<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Neste caso, o r\u00e9u publicou uma fotografia no seu site entre 5 de julho do ano 25 da era Heisei (2013) e 15 de janeiro do ano 26 da era Heisei (2014). Os autores, que alegam ser os detentores dos direitos de autor, dos direitos de uso exclusivo ou os autores da fotografia em quest\u00e3o, pediram uma indemniza\u00e7\u00e3o por ato il\u00edcito e, seletivamente, a devolu\u00e7\u00e3o de lucros indevidos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Argumentos_do_reu\"><\/span>Argumentos do r\u00e9u<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Em resposta \u00e0 reivindica\u00e7\u00e3o do autor, o r\u00e9u fez as seguintes alega\u00e7\u00f5es:<\/p>\n\n\n\n<ul>\n<li>Um empregado do r\u00e9u publicou a fotografia ao criar o site do r\u00e9u, mas acredita-se que ele estava sob a falsa impress\u00e3o de que era &#8220;de uso livre&#8221;.<\/li>\n\n\n\n<li>N\u00e3o se lembra de como obteve os dados, mas nunca copiou e coletou fotografias a partir de miniaturas exibidas como resultado de pesquisas de imagens no Yahoo ou Google.<\/li>\n\n\n\n<li>N\u00e3o h\u00e1 informa\u00e7\u00f5es na fotografia que indiquem que \u00e9 uma obra do autor, e como n\u00e3o h\u00e1 consci\u00eancia de que \u00e9 uma obra do autor, a neglig\u00eancia n\u00e3o pode ser reconhecida.<\/li>\n\n\n\n<li>Em geral, n\u00e3o \u00e9 proibido usar material de uso livre, e se for avisado de que \u00e9 uma viola\u00e7\u00e3o dos direitos de autor, tem a obriga\u00e7\u00e3o de remover a fotografia, e o r\u00e9u fez isso, removendo as fotografias em quest\u00e3o do site do r\u00e9u imediatamente ap\u00f3s ser notificado pelos autores.<\/li>\n<\/ul>\n\n\n\n<p>Em outras palavras, o r\u00e9u argumentou que, como obteve as fotografias de forma adequada como material de uso livre e n\u00e3o pode ser identificado como obra de quem a partir das fotografias, a neglig\u00eancia n\u00e3o pode ser reconhecida.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Decisao_do_tribunal\"><\/span>Decis\u00e3o do tribunal<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Em resposta aos argumentos do r\u00e9u, o Tribunal Distrital de T\u00f3quio decidiu da seguinte forma, reconhecendo a obriga\u00e7\u00e3o do r\u00e9u de pagar cerca de 200.000 ienes.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>O r\u00e9u argumenta que, ao obter fotografias de sites de uso livre, se for necess\u00e1rio investigar a rela\u00e7\u00e3o de direitos para obras sem informa\u00e7\u00f5es de identifica\u00e7\u00e3o, a liberdade de express\u00e3o (Artigo 21 da Constitui\u00e7\u00e3o) ser\u00e1 prejudicada, e que basta remover a fotografia ap\u00f3s ser avisado.<\/p>\n\n\n\n<p>Contudo, <u>mesmo que o empregado do r\u00e9u (E) tenha obtido a fotografia em quest\u00e3o de um site de uso livre, \u00e9 \u00f3bvio que deve evitar usar obras cujas informa\u00e7\u00f5es de identifica\u00e7\u00e3o e rela\u00e7\u00e3o de direitos s\u00e3o desconhecidas, pois h\u00e1 a possibilidade de violar os direitos de autor, etc., e n\u00e3o h\u00e1 raz\u00e3o para entender que a responsabilidade \u00e9 imediatamente evitada apenas por ter removido a fotografia ap\u00f3s ser avisado.<\/u> Os argumentos do r\u00e9u, baseados em sua pr\u00f3pria vis\u00e3o, n\u00e3o podem ser aceitos.<\/p>\n<\/blockquote>\n\n\n\n<p>Em outras palavras, mesmo que tenha obtido a fotografia de um site de uso livre, se usar uma fotografia cuja origem \u00e9 desconhecida, pode prever que pode violar os direitos de autor, etc., por isso n\u00e3o pode evitar a responsabilidade. Mesmo que use uma imagem que acreditava ser de uso livre, mas que na verdade n\u00e3o \u00e9, e argumente que &#8220;pensava que era de uso livre&#8221;, pode ser reconhecida a obriga\u00e7\u00e3o de indemniza\u00e7\u00e3o, por isso \u00e9 necess\u00e1rio ter cuidado.<\/p>\n\n\n\n<p>Contudo, mesmo que use uma imagem que acreditava ser de uso livre, mas que na verdade n\u00e3o \u00e9, teoricamente, se for reconhecida uma circunst\u00e2ncia especial em que o dolo ou a neglig\u00eancia n\u00e3o podem ser reconhecidos, a obriga\u00e7\u00e3o de indemniza\u00e7\u00e3o pode ser negada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pedido_de_cessacao_de_atos_de_infracao_etc_%E2%91%A1\"><\/span>Pedido de cessa\u00e7\u00e3o de atos de infra\u00e7\u00e3o, etc. \u2461<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2019\/11\/shutterstock_1509219434-1-1024x509.jpg\" alt=\"\" class=\"wp-image-5673\" \/><figcaption class=\"wp-element-caption\">O pedido de cessa\u00e7\u00e3o de atos de infra\u00e7\u00e3o \u00e9 para fazer cessar a pr\u00f3pria viola\u00e7\u00e3o de direitos como os direitos autorais.<\/figcaption><\/figure>\n\n\n\n<p>O Artigo 112 da Lei dos Direitos Autorais Japonesa estabelece os seguintes pedidos:<\/p>\n\n\n\n<ul>\n<li>Pedido de cessa\u00e7\u00e3o de infra\u00e7\u00e3o contra quem comete o ato de infra\u00e7\u00e3o (Artigo 112, par\u00e1grafo 1, da Lei dos Direitos Autorais Japonesa)<\/li>\n\n\n\n<li>Pedido de preven\u00e7\u00e3o de infra\u00e7\u00e3o contra quem comete o ato de infra\u00e7\u00e3o (Artigo 112, par\u00e1grafo 1, da Lei dos Direitos Autorais Japonesa)<\/li>\n\n\n\n<li>Pedido de medidas necess\u00e1rias para a cessa\u00e7\u00e3o ou preven\u00e7\u00e3o da infra\u00e7\u00e3o, incluindo a destrui\u00e7\u00e3o de objetos que constituem o ato de infra\u00e7\u00e3o, objetos criados pelo ato de infra\u00e7\u00e3o, ou m\u00e1quinas ou instrumentos usados exclusivamente para o ato de infra\u00e7\u00e3o (Artigo 112, par\u00e1grafo 2, da Lei dos Direitos Autorais Japonesa, este pedido s\u00f3 pode ser feito em conjunto com um dos pedidos acima.)<\/li>\n<\/ul>\n\n\n\n<p>O pedido \u2460 \u00e9 para compensar os danos sofridos por quem teve seus direitos autorais violados, enquanto o pedido \u2461 \u00e9 para fazer cessar a pr\u00f3pria viola\u00e7\u00e3o de direitos como os direitos autorais. Portanto, h\u00e1 uma diferen\u00e7a no conte\u00fado dos pedidos \u2460 e \u2461.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Diferenca_entre_%E2%91%A0_e_%E2%91%A1_Necessidade_de_intencao_ou_negligencia\"><\/span>Diferen\u00e7a entre \u2460 e \u2461: Necessidade de inten\u00e7\u00e3o ou neglig\u00eancia<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Teoricamente, \u00e9 poss\u00edvel distinguir entre \u2460 e \u2461 do ponto de vista da necessidade de inten\u00e7\u00e3o ou neglig\u00eancia. Como mencionado anteriormente, para que o pedido \u2460 seja aceite, era necess\u00e1rio haver &#8220;inten\u00e7\u00e3o ou neglig\u00eancia&#8221;.<\/p>\n\n\n\n<p>Por outro lado, para o pedido \u2461, n\u00e3o \u00e9 necess\u00e1rio que o infrator tenha inten\u00e7\u00e3o ou neglig\u00eancia em rela\u00e7\u00e3o \u00e0 infra\u00e7\u00e3o. Assim, \u00e9 poss\u00edvel distinguir entre os pedidos \u2460 e \u2461 do ponto de vista da necessidade de inten\u00e7\u00e3o ou neglig\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resumo\"><\/span>Resumo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Acima, explicamos a responsabilidade legal que pode surgir ao usar imagens que acreditamos serem de uso livre, mas que na verdade n\u00e3o s\u00e3o. Mesmo que n\u00e3o saiba que uma imagem, bot\u00e3o ou \u00edcone n\u00e3o \u00e9 de uso livre, pode ser responsabilizado legalmente se a usar. Portanto, se est\u00e1 a pensar em usar imagens, bot\u00f5es ou \u00edcones fornecidos por terceiros e n\u00e3o tem certeza se s\u00e3o de uso livre, \u00e9 melhor n\u00e3o os usar. S\u00f3 deve usar imagens, bot\u00f5es ou \u00edcones fornecidos por terceiros quando tiver certeza objetiva de que s\u00e3o de uso livre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acredito que possa haver ocasi\u00f5es em que se utilizem materiais gratuitos, como bot\u00f5es ou \u00edcones, nos websites que criam internamente. Nesses casos, pode-se pesquisar em motores de busca por termos com [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":59460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[21,41],"acf":[],"_links":{"self":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58520"}],"collection":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/comments?post=58520"}],"version-history":[{"count":1,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58520\/revisions"}],"predecessor-version":[{"id":59461,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58520\/revisions\/59461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media\/59460"}],"wp:attachment":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media?parent=58520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/categories?post=58520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/tags?post=58520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}