{"id":58539,"date":"2023-11-10T19:14:33","date_gmt":"2023-11-10T10:14:33","guid":{"rendered":"https:\/\/monolith.law\/pt\/?p=58539"},"modified":"2023-11-29T16:12:57","modified_gmt":"2023-11-29T07:12:57","slug":"deletion-of-comments-of-livedoor-blog","status":"publish","type":"post","link":"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog","title":{"rendered":"Como eliminar coment\u00e1rios no blog da Livedoor"},"content":{"rendered":"\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#O_que_e_o_Livedoor_Blog\" title=\"O que \u00e9 o Livedoor Blog\">O que \u00e9 o Livedoor Blog<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#O_que_sao_as_criticas_negativas_publicadas_no_LiveDoor_Blog\" title=\"O que s\u00e3o as cr\u00edticas negativas publicadas no LiveDoor Blog\">O que s\u00e3o as cr\u00edticas negativas publicadas no LiveDoor Blog<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Difamacao_no_artigo_pelo_autor_do_blog\" title=\"Difama\u00e7\u00e3o no artigo pelo autor do blog\">Difama\u00e7\u00e3o no artigo pelo autor do blog<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Informacoes_pessoais_que_podem_identificar_o_individuo_sao_publicadas_no_site_de_resumo\" title=\"Informa\u00e7\u00f5es pessoais que podem identificar o indiv\u00edduo s\u00e3o publicadas no site de resumo\">Informa\u00e7\u00f5es pessoais que podem identificar o indiv\u00edduo s\u00e3o publicadas no site de resumo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Difamacao_e_violacao_de_privacidade_contidas_nos_comentarios\" title=\"Difama\u00e7\u00e3o e viola\u00e7\u00e3o de privacidade contidas nos coment\u00e1rios\">Difama\u00e7\u00e3o e viola\u00e7\u00e3o de privacidade contidas nos coment\u00e1rios<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Como_solicitar_a_remocao_por_violacao_dos_termos_de_uso\" title=\"Como solicitar a remo\u00e7\u00e3o por viola\u00e7\u00e3o dos termos de uso\">Como solicitar a remo\u00e7\u00e3o por viola\u00e7\u00e3o dos termos de uso<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Termos_de_Uso_do_Livedoor\" title=\"Termos de Uso do Livedoor\">Termos de Uso do Livedoor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Como_solicitar_a_remocao\" title=\"Como solicitar a remo\u00e7\u00e3o\">Como solicitar a remo\u00e7\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Exemplo_de_pedido_de_remocao_por_violacao_dos_termos_de_uso\" title=\"Exemplo de pedido de remo\u00e7\u00e3o por viola\u00e7\u00e3o dos termos de uso\">Exemplo de pedido de remo\u00e7\u00e3o por viola\u00e7\u00e3o dos termos de uso<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Politica_de_Remocao_da_Livedoor\" title=\"Pol\u00edtica de Remo\u00e7\u00e3o da Livedoor\">Pol\u00edtica de Remo\u00e7\u00e3o da Livedoor<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Quando_solicitar_a_remocao_por_ser_ilegal\" title=\"Quando solicitar a remo\u00e7\u00e3o por ser ilegal\">Quando solicitar a remo\u00e7\u00e3o por ser ilegal<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Medidas_legais_possiveis\" title=\"Medidas legais poss\u00edveis\">Medidas legais poss\u00edveis<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Conteudo_a_ser_alegado_legalmente\" title=\"Conte\u00fado a ser alegado legalmente\">Conte\u00fado a ser alegado legalmente<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Remocao_atraves_do_metodo_judicial_medida_provisoria\" title=\"Remo\u00e7\u00e3o atrav\u00e9s do m\u00e9todo judicial (medida provis\u00f3ria)\">Remo\u00e7\u00e3o atrav\u00e9s do m\u00e9todo judicial (medida provis\u00f3ria)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Identificacao_do_autor_atraves_de_medidas_provisorias\" title=\"Identifica\u00e7\u00e3o do autor atrav\u00e9s de medidas provis\u00f3rias\">Identifica\u00e7\u00e3o do autor atrav\u00e9s de medidas provis\u00f3rias<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/monolith.law\/pt\/internet\/deletion-of-comments-of-livedoor-blog\/#Resumo\" title=\"Resumo\">Resumo<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_e_o_Livedoor_Blog\"><\/span>O que \u00e9 o Livedoor Blog<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O Livedoor Blog \u00e9 um dos principais servi\u00e7os de blog no Jap\u00e3o, operado pela LINE Corporation, uma subsidi\u00e1ria da empresa de TI coreana Naver. Milh\u00f5es de blogs foram criados. No Livedoor Blog, indiv\u00edduos comuns, celebridades e empresas escrevem blogs de v\u00e1rias categorias (di\u00e1rios ilustrados, gourmet, hobbies, neg\u00f3cios, pol\u00edtica, desportos, etc.), e existem muitos blogs, incluindo sites de resumo como o 5chan (antigo 2chan). Entre eles, existem blogs na categoria adulta (para adultos), e uma das caracter\u00edsticas \u00e9 a alta liberdade de postagem.<\/p>\n\n\n\n<p>Como existem v\u00e1rios conte\u00fados no Livedoor Blog, se voc\u00ea pesquisar palavras em motores de busca como o Google, \u00e9 prov\u00e1vel que sejam exibidos blogs do Livedoor que cont\u00eam conte\u00fado pr\u00f3ximo ao que voc\u00ea deseja pesquisar. Al\u00e9m disso, voc\u00ea pode ler blogs populares a partir das not\u00edcias do Livedoor, por isso muitas pessoas o utilizam como fonte de informa\u00e7\u00e3o para not\u00edcias.<\/p>\n\n\n\n<p>Por outro lado, como qualquer pessoa pode se registrar gratuitamente e escrever um blog no Livedoor Blog, existe uma grande possibilidade de que artigos de blog contendo informa\u00e7\u00f5es incertas ou conte\u00fado difamat\u00f3rio e difamat\u00f3rio sejam publicados. Neste ponto, o Livedoor Blog tem uma alta liberdade de postagem e n\u00e3o h\u00e1 medidas de exclus\u00e3o ativas ou sistema de monitoramento do lado do Livedoor. Na verdade, \u00e9 uma realidade que existem artigos e blogs que cont\u00eam conte\u00fado discriminat\u00f3rio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_sao_as_criticas_negativas_publicadas_no_LiveDoor_Blog\"><\/span>O que s\u00e3o as cr\u00edticas negativas publicadas no LiveDoor Blog<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/01\/shutterstock_610747262-1024x683.jpg\" alt=\"\" class=\"wp-image-6562\" \/><figcaption class=\"wp-element-caption\">O LiveDoor Blog permite a qualquer pessoa registar-se gratuitamente e escrever um blog, o que pode levar \u00e0 publica\u00e7\u00e3o de artigos negativos, incluindo difama\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>O LiveDoor Blog \u00e9 um servi\u00e7o de blog que qualquer pessoa pode criar, e por isso existem artigos que cont\u00eam descri\u00e7\u00f5es e express\u00f5es indesej\u00e1veis. O LiveDoor Blog abrange uma ampla gama de categorias e padr\u00f5es previstos, mas vamos apresentar um exemplo de um artigo negativo previsto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Difamacao_no_artigo_pelo_autor_do_blog\"><\/span>Difama\u00e7\u00e3o no artigo pelo autor do blog<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Por exemplo, vamos supor que um artigo foi publicado com a mensagem &#8220;A empresa de vendas Monolith \u00e9 lixo! Odeio! O pior!&#8221;. Se voc\u00ea estiver do lado da empresa de vendas Monolith, isso n\u00e3o \u00e9 nada mais do que uma postagem que interfere nos neg\u00f3cios. Pode-se dizer que \u00e9 uma postagem que deve ser imediatamente removida como difama\u00e7\u00e3o.<\/p>\n\n\n\n<p>No entanto, a pol\u00edtica de remo\u00e7\u00e3o do LiveDoor Blog afirma que &#8220;1. Conte\u00fado que n\u00e3o podemos julgar como viola\u00e7\u00e3o de direitos em nossa empresa&#8221; n\u00e3o pode ser removido imediatamente. E esta postagem, do ponto de vista do LiveDoor Blog, n\u00e3o se sabe se &#8220;Monolith Sales Company&#8221; se refere \u00e0 Monolith Sales Company ou a uma empresa completamente diferente. Al\u00e9m disso, n\u00e3o \u00e9 f\u00e1cil julgar se este artigo \u00e9 apenas uma opini\u00e3o ou difama\u00e7\u00e3o. Portanto, pode-se dizer que \u00e9 um tipo que se enquadra no mesmo 1 e torna dif\u00edcil solicitar a remo\u00e7\u00e3o imediatamente. Por favor, consulte a descri\u00e7\u00e3o detalhada abaixo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Informacoes_pessoais_que_podem_identificar_o_individuo_sao_publicadas_no_site_de_resumo\"><\/span>Informa\u00e7\u00f5es pessoais que podem identificar o indiv\u00edduo s\u00e3o publicadas no site de resumo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Artigos que cont\u00eam informa\u00e7\u00f5es pessoais podem ser indesej\u00e1veis, dependendo do conte\u00fado, da percep\u00e7\u00e3o do indiv\u00edduo e do impacto social, e podem violar a privacidade. Uma vez que tais postagens s\u00e3o feitas, pode ser imposs\u00edvel recuperar a privacidade, por isso pode-se dizer que \u00e9 um conte\u00fado que deve ser imediatamente removido. Para solicitar a remo\u00e7\u00e3o, existem dois m\u00e9todos: solicitar diretamente ao operador do blog do site de resumo, ou solicitar a remo\u00e7\u00e3o ao LiveDoor Blog.<\/p>\n\n\n\n<p>Al\u00e9m disso, os blogs de sites de resumo s\u00e3o originalmente postagens que foram republicadas de outros sites como 2chan e 5chan, ent\u00e3o, para remover completamente da internet, n\u00e3o basta apenas remover a postagem do site de resumo, mas tamb\u00e9m \u00e9 necess\u00e1rio remover a postagem original. Para mais detalhes, consulte o artigo abaixo.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/deletionrequest-for-2chand5ch\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/deletionrequest-for-2chand5ch[ja]<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Difamacao_e_violacao_de_privacidade_contidas_nos_comentarios\"><\/span>Difama\u00e7\u00e3o e viola\u00e7\u00e3o de privacidade contidas nos coment\u00e1rios<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Por exemplo, suponha que um artigo de um blogueiro gourmet foi publicado com um relato de visita \u00e0 &#8220;Confeitaria A&#8221;. Mesmo que o pr\u00f3prio artigo seja de conte\u00fado positivo e n\u00e3o haja problema, suponha que um coment\u00e1rio negativo foi deixado na se\u00e7\u00e3o de coment\u00e1rios, como &#8220;O bolo aqui \u00e9 veneno. H\u00e1 rumores de que eles usam ingredientes vencidos. Ningu\u00e9m na vizinhan\u00e7a come.&#8221; Mesmo neste caso, pode levar a danos \u00e0 reputa\u00e7\u00e3o, por isso pode-se dizer que \u00e9 um conte\u00fado que a confeitaria gostaria de remover.<\/p>\n\n\n\n<p>No entanto, a pessoa que escreveu o coment\u00e1rio \u00e9, obviamente, algu\u00e9m que n\u00e3o \u00e9 o administrador do blog e n\u00e3o pode ser facilmente identificada, ent\u00e3o a remo\u00e7\u00e3o pode parecer dif\u00edcil. Neste ponto, de acordo com as diretrizes, os direitos e obriga\u00e7\u00f5es do coment\u00e1rio pertencem ao administrador do blog. Portanto, pode-se dizer que a remo\u00e7\u00e3o pode ser feita solicitando ao administrador do blog ou ao LiveDoor Blog, assim como para a solicita\u00e7\u00e3o de remo\u00e7\u00e3o do texto do blog.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/01\/a3fd8221d564d043b11cac13c9dcf576.jpg\" alt=\"\" class=\"wp-image-6548\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_solicitar_a_remocao_por_violacao_dos_termos_de_uso\"><\/span>Como solicitar a remo\u00e7\u00e3o por viola\u00e7\u00e3o dos termos de uso<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Termos_de_Uso_do_Livedoor\"><\/span>Termos de Uso do Livedoor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Os Termos de Uso do Livedoor, na sec\u00e7\u00e3o &#8220;1.4 Atos Proibidos&#8221;, enumeram v\u00e1rias proibi\u00e7\u00f5es. Se a revis\u00e3o que deseja remover se enquadrar em qualquer um destes itens, poder\u00e1 ser eleg\u00edvel para remo\u00e7\u00e3o. Al\u00e9m disso, a sec\u00e7\u00e3o 1.4.2 estabelece as consequ\u00eancias de violar estas proibi\u00e7\u00f5es. Isto pode resultar em medidas como a suspens\u00e3o do uso do blog ou a implementa\u00e7\u00e3o de medidas para prevenir o envio (remo\u00e7\u00e3o).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/01\/80f93ae3dcbd1b96ee67fb220211919f.jpg\" alt=\"\" class=\"wp-image-6549\" \/><figcaption class=\"wp-element-caption\">Imagem dos Termos de Uso do Livedoor &#8220;1.4 Atos Proibidos&#8221;<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/01\/34548202149963192723c24b8568dbe7.jpg\" alt=\"\" class=\"wp-image-6550\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_solicitar_a_remocao\"><\/span>Como solicitar a remo\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A Livedoor oferece um alto grau de liberdade nos seus servi\u00e7os e os crit\u00e9rios para remo\u00e7\u00e3o s\u00e3o rigorosos, como ser\u00e1 mencionado posteriormente. Se desejar acelerar o processo, pode ser mais r\u00e1pido solicitar diretamente ao administrador do blog para remover o conte\u00fado. No entanto, se n\u00e3o houver resposta do administrador do blog ou se a identidade do mesmo for desconhecida, ter\u00e1 de solicitar a remo\u00e7\u00e3o \u00e0 Livedoor. A Livedoor disponibiliza um formul\u00e1rio de contacto para todos os servi\u00e7os, incluindo o blog Livedoor. Pode usar este formul\u00e1rio para solicitar a remo\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/01\/3927dee3dc2ea956fe1f0bebae925feb.jpg\" alt=\"\" class=\"wp-image-6551\" \/><figcaption class=\"wp-element-caption\">Ecr\u00e3 do formul\u00e1rio de contacto<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Exemplo_de_pedido_de_remocao_por_violacao_dos_termos_de_uso\"><\/span>Exemplo de pedido de remo\u00e7\u00e3o por viola\u00e7\u00e3o dos termos de uso<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O conte\u00fado da sua consulta deve seguir este formul\u00e1rio, indicando especificamente a que blog se refere, para facilitar a identifica\u00e7\u00e3o por parte do blog Livedoor. No formul\u00e1rio de contato do Livedoor, \u00e9 recomendado o uso de capturas de tela sempre que poss\u00edvel. Seria \u00fatil anexar uma captura de tela do artigo que viola os termos de uso ou infringe direitos, juntamente com o URL.<\/p>\n\n\n\n<p>Quanto \u00e0 escolha da categoria, deve-se escolher entre &#8220;Reclama\u00e7\u00e3o de viola\u00e7\u00e3o de direitos&#8221; e &#8220;Relat\u00f3rio de viola\u00e7\u00e3o dos termos de uso&#8221;. A principal diferen\u00e7a entre estes dois \u00e9 que o primeiro se aplica quando os seus direitos legais, como viola\u00e7\u00e3o de privacidade, difama\u00e7\u00e3o e viola\u00e7\u00e3o de direitos autorais, s\u00e3o infringidos, enquanto o \u00faltimo se aplica a outras viola\u00e7\u00f5es dos termos de uso. Ao solicitar a remo\u00e7\u00e3o, pense sobre o argumento que vai fazer e escolha a categoria apropriada.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/01\/940876a28fcdf5012d6123d97a102d4b.jpg\" alt=\"\" class=\"wp-image-6552\" \/><figcaption class=\"wp-element-caption\">Formul\u00e1rio quando se escolhe &#8220;Relat\u00f3rio de viola\u00e7\u00e3o dos termos de uso&#8221;<\/figcaption><\/figure>\n\n\n\n<p>Neste caso, vamos tomar como exemplo a situa\u00e7\u00e3o em que se deseja remover um artigo que cont\u00e9m express\u00f5es difamat\u00f3rias como &#8220;Lixo!&#8221; contra a &#8220;Monolith Sales Corporation&#8221;, como mencionado no exemplo anterior. Primeiro, selecione a categoria &#8220;Relat\u00f3rio de viola\u00e7\u00e3o dos termos de uso&#8221; e &#8220;Outros&#8221;, e anexe o URL do artigo em quest\u00e3o e uma captura de tela. Aqui est\u00e1 uma boa maneira de escrever o problema com o URL em quest\u00e3o.<\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background\">Agradecemos a sua aten\u00e7\u00e3o. Somos o Departamento de Rela\u00e7\u00f5es P\u00fablicas da Monolith Sales Corporation. Solicitamos a remo\u00e7\u00e3o deste artigo. A partir da terceira linha desta revis\u00e3o, est\u00e1 escrito algo como &#8220;Monolith Sales Corporation \u00e9 lixo! Odeio! O pior!&#8221;<br>Acreditamos que a Monolith Sales Corporation se refere \u00e0 nossa empresa. E &#8220;Lixo! Odeio! O pior!&#8221; \u00e9 uma express\u00e3o difamat\u00f3ria, que viola o artigo 1.4.1.3 dos termos de uso, que pro\u00edbe &#8220;atos de discrimina\u00e7\u00e3o ou difama\u00e7\u00e3o contra outros&#8221;. Tamb\u00e9m constitui uma viola\u00e7\u00e3o dos direitos de honra. Este tipo de postagem tem um impacto negativo nas vendas e atividades comerciais dos nossos produtos, por isso gostar\u00edamos de solicitar a sua remo\u00e7\u00e3o. Agradecemos a sua coopera\u00e7\u00e3o. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Politica_de_Remocao_da_Livedoor\"><\/span>Pol\u00edtica de Remo\u00e7\u00e3o da Livedoor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Anteriormente, explic\u00e1mos como solicitar a remo\u00e7\u00e3o de conte\u00fado. No entanto, a Livedoor tem uma pol\u00edtica p\u00fablica adicional \u00e0s suas condi\u00e7\u00f5es de uso, chamada &#8220;Pol\u00edtica de Remo\u00e7\u00e3o&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/01\/bc5a47130605eeb55711373609004f24.jpg\" alt=\"\" class=\"wp-image-6553\" \/><figcaption class=\"wp-element-caption\"> <br>Da p\u00e1gina de explica\u00e7\u00e3o sobre a Pol\u00edtica de Remo\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/01\/b12c8b7e401505670006e9aa6ee0e2d0.jpg\" alt=\"\" class=\"wp-image-6554\" \/><figcaption class=\"wp-element-caption\"> Sobre a publica\u00e7\u00e3o relacionada com &#8220;Infringimento de Direitos&#8221;<br><\/figcaption><\/figure>\n\n\n\n<p>Em termos simples, &#8220;2. Conte\u00fado publicado que \u00e9 considerado como potencialmente infringindo direitos ou violando a lei&#8221; ser\u00e1 prontamente removido. No entanto, &#8220;1. Conte\u00fado publicado que a nossa empresa n\u00e3o pode determinar como uma infrac\u00e7\u00e3o de direitos&#8221; ser\u00e1 primeiro verificado com o administrador do blog para obter consentimento para a remo\u00e7\u00e3o. Se o consentimento n\u00e3o for obtido, o conte\u00fado ser\u00e1 removido se violar os termos de uso, mas n\u00e3o poder\u00e1 ser removido se n\u00e3o violar os termos de uso.<\/p>\n\n\n\n<p>No exemplo anterior, se \u00e9 dif\u00edcil determinar se o conte\u00fado viola os termos de uso ou se h\u00e1 uma possibilidade de infrac\u00e7\u00e3o de direitos, ele se enquadra na categoria &#8220;1&#8221;. Isso pode levar tempo e h\u00e1 uma grande possibilidade de que o conte\u00fado n\u00e3o seja removido. Se o conte\u00fado n\u00e3o for removido, voc\u00ea ter\u00e1 que recorrer a medidas legais alegando que \u00e9 ilegal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quando_solicitar_a_remocao_por_ser_ilegal\"><\/span>Quando solicitar a remo\u00e7\u00e3o por ser ilegal<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/01\/shutterstock_1043246170-1024x478.jpg\" alt=\"\" class=\"wp-image-6565\" \/><figcaption class=\"wp-element-caption\">Na Livedoor, os crit\u00e9rios para a remo\u00e7\u00e3o de artigos s\u00e3o rigorosos. Que medidas podem ser tomadas quando \u00e9 dif\u00edcil provar a ilegalidade?<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Medidas_legais_possiveis\"><\/span>Medidas legais poss\u00edveis<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Se o conte\u00fado violar a lei, como a viola\u00e7\u00e3o de direitos, \u00e9 poss\u00edvel contestar a remo\u00e7\u00e3o atrav\u00e9s de um advogado em tribunal. Primeiramente, as medidas legais poss\u00edveis relacionadas com a gest\u00e3o de danos \u00e0 reputa\u00e7\u00e3o na Internet incluem, em grande parte:<\/p>\n\n\n\n<ul>\n<li>Pedido de remo\u00e7\u00e3o volunt\u00e1ria atrav\u00e9s de uma solicita\u00e7\u00e3o de medida de preven\u00e7\u00e3o de envio<\/li>\n\n\n\n<li>Pedido de remo\u00e7\u00e3o de postagem e apresenta\u00e7\u00e3o de medidas provis\u00f3rias<\/li>\n\n\n\n<li>Solicita\u00e7\u00e3o de divulga\u00e7\u00e3o de informa\u00e7\u00f5es do remetente (solicita\u00e7\u00e3o de divulga\u00e7\u00e3o de endere\u00e7o IP, solicita\u00e7\u00e3o de divulga\u00e7\u00e3o de nome e endere\u00e7o)<\/li>\n\n\n\n<li>Reivindica\u00e7\u00e3o de compensa\u00e7\u00e3o por danos (reivindica\u00e7\u00e3o de compensa\u00e7\u00e3o por danos ap\u00f3s a identifica\u00e7\u00e3o do autor da postagem)<\/li>\n<\/ul>\n\n\n\n<p>Entre estes, os pedidos diretamente relacionados \u00e0 remo\u00e7\u00e3o s\u00e3o a solicita\u00e7\u00e3o de medida de preven\u00e7\u00e3o de envio ou o pedido de remo\u00e7\u00e3o de postagem e a apresenta\u00e7\u00e3o de medidas provis\u00f3rias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conteudo_a_ser_alegado_legalmente\"><\/span>Conte\u00fado a ser alegado legalmente<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ent\u00e3o, ao solicitar a remo\u00e7\u00e3o legalmente, a primeira coisa a considerar \u00e9 alegar &#8220;difama\u00e7\u00e3o&#8221;. A difama\u00e7\u00e3o \u00e9 estabelecida quando:<\/p>\n\n\n\n<ul>\n<li>&#8220;Publicamente&#8221;<\/li>\n\n\n\n<li>&#8220;Apontando um fato&#8221;<\/li>\n\n\n\n<li>&#8220;Difamando a honra de algu\u00e9m&#8221;<\/li>\n<\/ul>\n\n\n\n<p>Existem fatos que correspondem a todos estes.<\/p>\n\n\n\n<p>Por exemplo, se um coment\u00e1rio baseado em conte\u00fado falso como &#8220;O bolo da pastelaria A \u00e9 venenoso. H\u00e1 rumores de que eles usam ingredientes vencidos. Ningu\u00e9m na vizinhan\u00e7a come l\u00e1.&#8221; for postado, vamos ver se ele atende aos requisitos de 1 a 3. Primeiramente, postagens na Internet como em blogs da Livedoor, que podem ser visualizadas por um n\u00famero indeterminado de pessoas na Internet, podem ser consideradas &#8220;publicamente&#8221;.<\/p>\n\n\n\n<p>Em seguida, &#8220;apontar um fato&#8221; significa revelar um fato concreto que \u00e9 suficiente para diminuir a avalia\u00e7\u00e3o social de algu\u00e9m, independentemente de ser verdadeiro ou falso. Neste caso, a informa\u00e7\u00e3o de que eles est\u00e3o usando ingredientes vencidos \u00e9 um coment\u00e1rio que indica um fato de viola\u00e7\u00e3o da lei de higiene alimentar, que \u00e9 suficiente para diminuir a avalia\u00e7\u00e3o social.<\/p>\n\n\n\n<p>Finalmente, para &#8220;difamar&#8221;, mesmo que a avalia\u00e7\u00e3o social n\u00e3o tenha sido realmente prejudicada, basta que exista o risco abstrato disso, e n\u00e3o \u00e9 necess\u00e1rio que a honra tenha sido realmente violada. N\u00e3o \u00e9 necess\u00e1rio provar que a postagem em quest\u00e3o foi vista por um n\u00famero indeterminado de pessoas em not\u00edcias online e redes sociais, e que houve uma enxurrada de cr\u00edticas e protestos contra a pastelaria. Basta que exista o risco objetivo disso. Para mais detalhes sobre os requisitos para a difama\u00e7\u00e3o, consulte o artigo abaixo.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/defamation\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/defamation[ja]<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Remocao_atraves_do_metodo_judicial_medida_provisoria\"><\/span>Remo\u00e7\u00e3o atrav\u00e9s do m\u00e9todo judicial (medida provis\u00f3ria)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para solicitar a remo\u00e7\u00e3o devido a viola\u00e7\u00f5es legais, como difama\u00e7\u00e3o, o m\u00e9todo usual \u00e9 primeiro solicitar uma medida de preven\u00e7\u00e3o de transmiss\u00e3o. No entanto, a solicita\u00e7\u00e3o de medida de preven\u00e7\u00e3o de transmiss\u00e3o \u00e9 um m\u00e9todo de solicita\u00e7\u00e3o de remo\u00e7\u00e3o que n\u00e3o passa pelo tribunal, solicitando a remo\u00e7\u00e3o volunt\u00e1ria pelo provedor (LiveDoor Blog). No LiveDoor Blog, \u00e9 claramente indicado nos termos de uso que pode haver casos em que \u00e9 legalmente poss\u00edvel remover, por isso \u00e9 prov\u00e1vel que seja removido por este m\u00e9todo. No entanto, como \u00e9 um meio opcional, dependendo do julgamento, a remo\u00e7\u00e3o pode n\u00e3o ser realizada.<\/p>\n\n\n\n<p>Em contraste, no procedimento atrav\u00e9s do tribunal, se a remo\u00e7\u00e3o for permitida no julgamento, a for\u00e7a vinculativa da decis\u00e3o ocorrer\u00e1, ent\u00e3o o provedor (LiveDoor Blog) ter\u00e1 que remover for\u00e7osamente. Portanto, se a medida de preven\u00e7\u00e3o de transmiss\u00e3o n\u00e3o for permitida, ser\u00e1 eficaz passar para o procedimento judicial. A medida provis\u00f3ria \u00e9 um m\u00e9todo estipulado na Lei de Preserva\u00e7\u00e3o Civil Japonesa, e \u00e9 algo que solicita uma medida tempor\u00e1ria antes de obter uma decis\u00e3o final atrav\u00e9s de um processo formal quando uma resolu\u00e7\u00e3o r\u00e1pida \u00e9 necess\u00e1ria. Em casos como este, onde h\u00e1 muita probabilidade de danos irrecuper\u00e1veis ocorrerem se difama\u00e7\u00f5es e cr\u00edticas se espalharem, \u00e9 eficaz usar o sistema de medidas provis\u00f3rias para solicitar a remo\u00e7\u00e3o das informa\u00e7\u00f5es o mais r\u00e1pido poss\u00edvel. Quando uma ordem de medida provis\u00f3ria \u00e9 emitida, o tribunal ordena \u00e0 outra parte que remova a postagem, ent\u00e3o a outra parte ter\u00e1 que remover.<\/p>\n\n\n\n<p>No caso de uma medida provis\u00f3ria, se voc\u00ea consultar um advogado com conhecimento em gest\u00e3o de danos \u00e0 reputa\u00e7\u00e3o, em muitos casos, a remo\u00e7\u00e3o pode ser realizada em cerca de 2-3 meses a partir do pedido, o que pode ser dito ser um meio eficaz. A remo\u00e7\u00e3o do artigo em quest\u00e3o no caso de difama\u00e7\u00e3o ou danos \u00e0 reputa\u00e7\u00e3o, e o procedimento de medida provis\u00f3ria s\u00e3o explicados em detalhes no artigo abaixo.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/provisional-disposition\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/provisional-disposition[ja]<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Identificacao_do_autor_atraves_de_medidas_provisorias\"><\/span>Identifica\u00e7\u00e3o do autor atrav\u00e9s de medidas provis\u00f3rias<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0 identifica\u00e7\u00e3o do autor atrav\u00e9s de medidas provis\u00f3rias, se solicitar a um advogado, \u00e9 poss\u00edvel que ele revele informa\u00e7\u00f5es como o endere\u00e7o IP do autor atrav\u00e9s do chamado pedido de divulga\u00e7\u00e3o de informa\u00e7\u00f5es do remetente, possibilitando a identifica\u00e7\u00e3o do autor. Ao fazer isso, torna-se poss\u00edvel solicitar uma reivindica\u00e7\u00e3o de compensa\u00e7\u00e3o por danos ao remetente identificado, devido a postagens difamat\u00f3rias. Os detalhes deste processo est\u00e3o explicados nos artigos abaixo.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/disclosure-of-the-senders-information\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/disclosure-of-the-senders-information[ja]<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/livedoor-blog-footprint-specific\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/livedoor-blog-footprint-specific[ja]<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resumo\"><\/span>Resumo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O blog Livedoor \u00e9 um site extremamente \u00fatil, pois possui artigos e blogs de v\u00e1rias categorias, de onde se pode obter v\u00e1rias informa\u00e7\u00f5es, ideias e opini\u00f5es. No entanto, devido \u00e0 sua alta liberdade de express\u00e3o e descri\u00e7\u00e3o, \u00e9 poss\u00edvel prever v\u00e1rios danos \u00e0 reputa\u00e7\u00e3o e viola\u00e7\u00f5es de direitos.<\/p>\n\n\n\n<p>Os crit\u00e9rios para a remo\u00e7\u00e3o de artigos no Livedoor s\u00e3o rigorosos, tornando dif\u00edcil provar a ilegalidade. Como envolve conte\u00fado e m\u00e9todos especializados, \u00e9 dif\u00edcil para um indiv\u00edduo realizar essa tarefa, e como se trata de um ato legal, a ajuda de um advogado \u00e9 necess\u00e1ria. Primeiro, consulte um advogado para determinar se a revis\u00e3o em quest\u00e3o constitui uma viola\u00e7\u00e3o de direitos ou se viola a lei.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 o Livedoor Blog O Livedoor Blog \u00e9 um dos principais servi\u00e7os de blog no Jap\u00e3o, operado pela LINE Corporation, uma subsidi\u00e1ria da empresa de TI coreana Naver. Milh\u00f5es de blogs foram criados. No [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":59418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[39,21],"acf":[],"_links":{"self":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58539"}],"collection":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/comments?post=58539"}],"version-history":[{"count":1,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58539\/revisions"}],"predecessor-version":[{"id":59419,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58539\/revisions\/59419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media\/59418"}],"wp:attachment":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media?parent=58539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/categories?post=58539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/tags?post=58539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}