{"id":58737,"date":"2023-11-10T19:14:39","date_gmt":"2023-11-10T10:14:39","guid":{"rendered":"https:\/\/monolith.law\/pt\/?p=58737"},"modified":"2023-11-20T15:19:07","modified_gmt":"2023-11-20T06:19:07","slug":"legal-risk-reward-orthopedic-review-contributors","status":"publish","type":"post","link":"https:\/\/monolith.law\/pt\/internet\/legal-risk-reward-orthopedic-review-contributors","title":{"rendered":"Riscos legais de pagar recompensas aos autores de avalia\u00e7\u00f5es em sites de coment\u00e1rios de cirurgia est\u00e9tica"},"content":{"rendered":"\n<p>Em sites de avalia\u00e7\u00f5es de cirurgia est\u00e9tica, s\u00e3o publicadas avalia\u00e7\u00f5es dos pacientes.<br>Em alguns casos, o site pode pagar uma recompensa ao paciente por essas avalia\u00e7\u00f5es.<\/p>\n\n\n\n<p>Questiona-se se o ato do site de avalia\u00e7\u00f5es pagar uma recompensa aos autores das avalia\u00e7\u00f5es para as recolher \u00e9 ou n\u00e3o contr\u00e1rio \u00e0 lei. Explicaremos os problemas e as precau\u00e7\u00f5es relacionadas com esta pr\u00e1tica.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_53 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-risk-reward-orthopedic-review-contributors\/#Problemas_com_o_pagamento_de_recompensas\" title=\"Problemas com o pagamento de recompensas\">Problemas com o pagamento de recompensas<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-risk-reward-orthopedic-review-contributors\/#%E2%80%9CProibicao_de_taxas_de_referencia%E2%80%9D\" title=\"&#8220;Proibi\u00e7\u00e3o de taxas de refer\u00eancia&#8221;\">&#8220;Proibi\u00e7\u00e3o de taxas de refer\u00eancia&#8221;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-risk-reward-orthopedic-review-contributors\/#Investigacao_por_agencias_governamentais\" title=\"Investiga\u00e7\u00e3o por ag\u00eancias governamentais\">Investiga\u00e7\u00e3o por ag\u00eancias governamentais<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-risk-reward-orthopedic-review-contributors\/#Comparacao_com_outros_sites_de_saude\" title=\"Compara\u00e7\u00e3o com outros sites de sa\u00fade\">Compara\u00e7\u00e3o com outros sites de sa\u00fade<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-risk-reward-orthopedic-review-contributors\/#Tratamento_na_Plaza_de_Comentarios_de_Medicina_Estetica_Beleza\" title=\"Tratamento na Plaza de Coment\u00e1rios de Medicina Est\u00e9tica (Beleza)\">Tratamento na Plaza de Coment\u00e1rios de Medicina Est\u00e9tica (Beleza)<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-risk-reward-orthopedic-review-contributors\/#Pontos_de_Operacao\" title=\"Pontos de Opera\u00e7\u00e3o\">Pontos de Opera\u00e7\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/monolith.law\/pt\/internet\/legal-risk-reward-orthopedic-review-contributors\/#Resumo\" title=\"Resumo\">Resumo<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Problemas_com_o_pagamento_de_recompensas\"><\/span>Problemas com o pagamento de recompensas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Quando um site de avalia\u00e7\u00f5es de cirurgia est\u00e9tica paga recompensas por avalia\u00e7\u00f5es de pacientes, \u00e9 necess\u00e1rio cumprir uma regra chamada Regulamento de Responsabilidade M\u00e9dica (Regra de Responsabilidade M\u00e9dica). Esta regra \u00e9 originalmente destinada a ser cumprida por institui\u00e7\u00f5es m\u00e9dicas que fornecem cuidados m\u00e9dicos segurados. No entanto, como o site de avalia\u00e7\u00f5es apresenta avalia\u00e7\u00f5es de institui\u00e7\u00f5es m\u00e9dicas, o site tamb\u00e9m precisa cumprir esta regra.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E2%80%9CProibicao_de_taxas_de_referencia%E2%80%9D\"><\/span>&#8220;Proibi\u00e7\u00e3o de taxas de refer\u00eancia&#8221;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>No Artigo 2-4-2 do Regulamento de Responsabilidade M\u00e9dica e de Cuidados M\u00e9dicos Segurados (Regra de Responsabilidade M\u00e9dica), \u00e9 proibido que as institui\u00e7\u00f5es m\u00e9dicas seguradas atraiam pacientes oferecendo benef\u00edcios econ\u00f3micos, como descontos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>As institui\u00e7\u00f5es m\u00e9dicas seguradas n\u00e3o devem atrair pacientes para receber tratamento nas suas pr\u00f3prias institui\u00e7\u00f5es m\u00e9dicas seguradas, oferecendo benef\u00edcios econ\u00f3micos que possam prejudicar a gest\u00e3o saud\u00e1vel do neg\u00f3cio de seguro de sa\u00fade, como dar descontos no valor dos bens relacionados com o neg\u00f3cio de lucro realizado pela institui\u00e7\u00e3o m\u00e9dica segurada de acordo com o valor das despesas recebidas de acordo com o Artigo 5.<\/p>\n<cite><a href=\"https:\/\/elaws.e-gov.go.jp\/document?lawid=332M50000100015\" data-type=\"link\" data-id=\"https:\/\/elaws.e-gov.go.jp\/document?lawid=332M50000100015#:~:text=%E8%AA%98%E5%BC%95%E3%81%AE%E7%A6%81%E6%AD%A2%EF%BC%89-,%E7%AC%AC%E4%BA%8C%E6%9D%A1%E3%81%AE%E5%9B%9B%E3%81%AE%E4%BA%8C,-%E4%BF%9D%E9%99%BA%E5%8C%BB%E7%99%82%E6%A9%9F%E9%96%A2\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/elaws.e-gov.go.jp\/document?lawid=332M50000100015[ja]<\/a><\/cite><\/blockquote>\n\n\n\n<p>Em termos simples, a disposi\u00e7\u00e3o acima pro\u00edbe os kickbacks. Portanto, parece que um acordo entre um paciente e uma institui\u00e7\u00e3o m\u00e9dica para &#8220;reduzir os custos em troca de postar uma avalia\u00e7\u00e3o no site de avalia\u00e7\u00f5es&#8221; seria uma viola\u00e7\u00e3o da proibi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m disso, h\u00e1 um caso em que uma cl\u00ednica dent\u00e1ria que concedeu pontos em vez de dinheiro se tornou um problema em rela\u00e7\u00e3o a esta regra, por isso \u00e9 necess\u00e1rio entender que conceder pontos tamb\u00e9m pode violar a regra.<\/p>\n\n\n\n<p>Al\u00e9m disso, a disposi\u00e7\u00e3o acima se aplica apenas a &#8220;institui\u00e7\u00f5es m\u00e9dicas seguradas&#8221;. Alguns podem pensar que as cl\u00ednicas que fornecem servi\u00e7os de cirurgia est\u00e9tica, que n\u00e3o s\u00e3o cobertos pelo seguro, n\u00e3o s\u00e3o institui\u00e7\u00f5es m\u00e9dicas seguradas.<\/p>\n\n\n\n<p>No entanto, \u00e9 poss\u00edvel que tais institui\u00e7\u00f5es m\u00e9dicas tamb\u00e9m realizem tratamentos segurados e sejam designadas como institui\u00e7\u00f5es m\u00e9dicas seguradas. Al\u00e9m disso, embora a cirurgia est\u00e9tica seja geralmente um tratamento auto-pago, se houver um diagn\u00f3stico formal de seguro m\u00e9dico e um procedimento de seguro correspondente, ele cai sob o tratamento segurado.<\/p>\n\n\n\n<p>Com base no acima exposto, ao operar um site de avalia\u00e7\u00f5es de cirurgia est\u00e9tica, deve-se assumir que as cl\u00ednicas listadas est\u00e3o sujeitas \u00e0 Regra de Responsabilidade M\u00e9dica e considerar o sistema.<\/p>\n\n\n\n<p>A linguagem da Regra de Responsabilidade M\u00e9dica acima n\u00e3o lista especificamente as a\u00e7\u00f5es proibidas. Portanto, se uma a\u00e7\u00e3o se qualifica como uma a\u00e7\u00e3o proibida \u00e9 determinada pela realidade, e \u00e9 necess\u00e1rio consultar um especialista.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Investigacao_por_agencias_governamentais\"><\/span>Investiga\u00e7\u00e3o por ag\u00eancias governamentais<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/08\/legal-risk-reward-orthopedic-review-contributors2.jpg\" alt=\"\" class=\"wp-image-16284\" \/><\/figure>\n\n\n\n<p>Os departamentos de sa\u00fade e o Minist\u00e9rio do Trabalho, Sa\u00fade e Bem-Estar verificam se h\u00e1 algum problema com o conte\u00fado das transa\u00e7\u00f5es das institui\u00e7\u00f5es m\u00e9dicas. Portanto, as institui\u00e7\u00f5es m\u00e9dicas e os sites de avalia\u00e7\u00f5es n\u00e3o devem celebrar contratos que possam ser interpretados como kickbacks para pacientes.<\/p>\n\n\n\n<p>Al\u00e9m disso, se o site de avalia\u00e7\u00f5es menciona em seu site que paga uma recompensa de acordo com o valor do tratamento ao recrutar pacientes (contribuintes), \u00e9 prov\u00e1vel que isso seja visto como um problema.<\/p>\n\n\n\n<p>No entanto, \u00e9 diferente se n\u00e3o houver correla\u00e7\u00e3o entre a recompensa recebida da institui\u00e7\u00e3o m\u00e9dica e a recompensa paga pela postagem no site de avalia\u00e7\u00f5es, e se n\u00e3o houver correla\u00e7\u00e3o entre o valor do tratamento e o valor da recompensa. Por exemplo, o ato de um site de avalia\u00e7\u00f5es pagar uma recompensa como pagamento por uma postagem de avalia\u00e7\u00e3o pode ser considerado um contrato que \u00e9 conclu\u00eddo entre o site de avalia\u00e7\u00f5es e o paciente.<\/p>\n\n\n\n<p>Se voc\u00ea deseja introduzir um sistema de recompensas para incentivar as postagens dos pacientes, \u00e9 necess\u00e1rio construir um sistema que possa ser julgado como o site de avalia\u00e7\u00f5es pagando a recompensa para o seu pr\u00f3prio benef\u00edcio, n\u00e3o para o benef\u00edcio da institui\u00e7\u00e3o m\u00e9dica.<\/p>\n\n\n\n<p>Por exemplo, se o site de avalia\u00e7\u00f5es contratar pacientes para postar avalia\u00e7\u00f5es para enriquecer o conte\u00fado e aumentar o n\u00famero de visualiza\u00e7\u00f5es do site, e pagar uma recompensa como pagamento por isso, o risco de violar a Regra de Responsabilidade M\u00e9dica \u00e9 baixo.<\/p>\n\n\n\n<p>De qualquer forma, como \u00e9 um caso dif\u00edcil de julgar, recomendamos que voc\u00ea consulte um advogado com amplo conhecimento especializado.<\/p>\n\n\n\n<p>Al\u00e9m disso, h\u00e1 uma quest\u00e3o de se \u00e9 legal para um site de avalia\u00e7\u00f5es de beleza receber uma recompensa do hospital em troca de postar uma avalia\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para mais detalhes sobre este assunto, consulte o artigo abaixo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-\u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09 wp-block-embed-\u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"H5UpZ9JCIQ\"><a href=\"https:\/\/monolith.law\/pt\/internet\/medical-institution-reward-law\">\u00c9 aceit\u00e1vel oferecer recompensas por coment\u00e1rios de cirurgia est\u00e9tica? Riscos legais ocultos na gest\u00e3o de sites<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;\u00c9 aceit\u00e1vel oferecer recompensas por coment\u00e1rios de cirurgia est\u00e9tica? Riscos legais ocultos na gest\u00e3o de sites&#8221; &#8212; \u30b3\u30fc\u30dd\u30ec\u30fc\u30c8\u30b5\u30a4\u30c8\uff08\u30dd\u30eb\u30c8\u30ac\u30eb\u8a9e\uff09\" src=\"https:\/\/monolith.law\/pt\/internet\/medical-institution-reward-law\/embed#?secret=UfKQhSPdRm#?secret=H5UpZ9JCIQ\" data-secret=\"H5UpZ9JCIQ\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Comparacao_com_outros_sites_de_saude\"><\/span>Compara\u00e7\u00e3o com outros sites de sa\u00fade<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Em sites de sa\u00fade, os seguintes tr\u00eas sites oferecem recompensas aos revisores:<\/p>\n\n\n\n<ul>\n<li>Plaza de Coment\u00e1rios de Medicina Est\u00e9tica (Beleza) (<a href=\"https:\/\/clinic.e-kuchikomi.info\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/clinic.e-kuchikomi.info\/[ja]<\/a>)<\/li>\n\n\n\n<li>caloo (<a href=\"https:\/\/caloo.jp\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/caloo.jp\/[ja]<\/a>)<\/li>\n\n\n\n<li>QLIFE (<a href=\"https:\/\/www.qlife.jp\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.qlife.jp\/[ja]<\/a>)<\/li>\n<\/ul>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0 rela\u00e7\u00e3o entre o site e as institui\u00e7\u00f5es m\u00e9dicas, tanto o &#8220;caloo&#8221; como o &#8220;QLIFE&#8221; aceitam o registo gratuito das institui\u00e7\u00f5es m\u00e9dicas. Por outro lado, a &#8220;Plaza de Coment\u00e1rios de Medicina Est\u00e9tica (Beleza)&#8221; tem um formul\u00e1rio de contacto, mas n\u00e3o menciona se h\u00e1 uma taxa de registo.<\/p>\n\n\n\n<p>Quanto \u00e0s recompensas, tanto o &#8220;caloo&#8221; como o &#8220;QLIFE&#8221; atribuem pontos fixos uniformemente para o registo de utilizadores, publica\u00e7\u00e3o de coment\u00e1rios, postagem de informa\u00e7\u00f5es de visita, etc. Como as recompensas s\u00e3o as mesmas, \u00e9 claro que s\u00e3o recompensas que n\u00e3o correspondem ao conte\u00fado do tratamento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tratamento_na_Plaza_de_Comentarios_de_Medicina_Estetica_Beleza\"><\/span>Tratamento na Plaza de Coment\u00e1rios de Medicina Est\u00e9tica (Beleza)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A &#8220;Plaza de Coment\u00e1rios de Medicina Est\u00e9tica (Beleza)&#8221; parece determinar o n\u00famero de pontos ap\u00f3s receber informa\u00e7\u00f5es sobre o conte\u00fado do tratamento. Portanto, neste site, a quantidade da recompensa pode variar dependendo do valor do tratamento.<\/p>\n\n\n\n<p>No entanto, na &#8220;Plaza de Coment\u00e1rios de Medicina Est\u00e9tica (Beleza)&#8221;, existe uma regra que n\u00e3o permite receber recompensas por postagens sobre tratamento m\u00e9dico coberto pelo seguro.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p>Q10. Recebo pontos independentemente do tratamento que recebo?<br>A. Receber\u00e1 um cashback de pontos se receber um dos tratamentos listados na Plaza de Coment\u00e1rios. *Os valores relacionados ao tratamento m\u00e9dico coberto pelo seguro n\u00e3o s\u00e3o eleg\u00edveis para cashback de pontos.<br><\/p>\n<cite><a href=\"https:\/\/report.clinic\/info\/faq#open\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/report.clinic\/info\/faq#open[ja]<\/a><\/cite><\/blockquote>\n\n\n\n<p>Repetindo, as regras de tratamento m\u00e9dico pro\u00edbem as institui\u00e7\u00f5es m\u00e9dicas seguradas de adotar um sistema de kickback. Mesmo para pacientes que receberam tratamento m\u00e9dico privado em uma institui\u00e7\u00e3o m\u00e9dica segurada, n\u00e3o \u00e9 permitido pagar uma taxa de refer\u00eancia. Se pontos proporcionais ao valor do tratamento est\u00e3o sendo fornecidos a pacientes que receberam tratamento m\u00e9dico privado, isso pode violar as regras.<\/p>\n\n\n\n<p>Considerando essas circunst\u00e2ncias, na pr\u00e1tica, pode haver um tratamento diferente que n\u00e3o paga recompensas para tratamentos recebidos em institui\u00e7\u00f5es m\u00e9dicas seguradas, em vez de tratamento m\u00e9dico coberto pelo seguro.<\/p>\n\n\n\n<p>Normalmente, os pacientes em geral n\u00e3o conseguem distinguir entre institui\u00e7\u00f5es m\u00e9dicas seguradas e institui\u00e7\u00f5es m\u00e9dicas que oferecem apenas tratamento m\u00e9dico privado. Considerando a falta de conhecimento do paciente, \u00e9 poss\u00edvel que a linguagem de isen\u00e7\u00e3o esteja limitada ao tratamento m\u00e9dico coberto pelo seguro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pontos_de_Operacao\"><\/span>Pontos de Opera\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monolith.law\/wp-content\/uploads\/2020\/08\/legal-risk-reward-orthopedic-review-contributors3.jpg\" alt=\"\" class=\"wp-image-16286\" \/><\/figure>\n\n\n\n<p>Com base nas considera\u00e7\u00f5es anteriores, recomendamos que, quando um site de avalia\u00e7\u00f5es de beleza paga uma recompensa pela avalia\u00e7\u00e3o, considere a opera\u00e7\u00e3o de pagar uma gratifica\u00e7\u00e3o apenas para os tratamentos recebidos em institui\u00e7\u00f5es m\u00e9dicas que n\u00e3o s\u00e3o institui\u00e7\u00f5es m\u00e9dicas de seguros. Em resumo, tenha em aten\u00e7\u00e3o os seguintes dois pontos ao operar.<\/p>\n\n\n\n<ol>\n<li>O sistema de gratifica\u00e7\u00e3o para os pacientes n\u00e3o deve corresponder ao valor do tratamento<\/li>\n\n\n\n<li>Se for uma institui\u00e7\u00e3o m\u00e9dica de seguros, aplica-se a regra de responsabilidade pelo tratamento, mesmo para tratamentos fora do seguro<\/li>\n<\/ol>\n\n\n\n<p>O ato de enviar uma gratifica\u00e7\u00e3o em si n\u00e3o \u00e9 proibido. No entanto, para n\u00e3o violar a regra de responsabilidade pelo tratamento, \u00e9 essencial ter um sistema que n\u00e3o corresponda ao valor do tratamento. Al\u00e9m disso, se for uma institui\u00e7\u00e3o m\u00e9dica de seguros, tenha em aten\u00e7\u00e3o que a revis\u00e3o do tratamento fora do seguro tamb\u00e9m est\u00e1 sujeita \u00e0 regula\u00e7\u00e3o da regra de responsabilidade pelo tratamento.<\/p>\n\n\n\n<p>O conte\u00fado das avalia\u00e7\u00f5es nem sempre \u00e9 bom. \u00c0s vezes, coment\u00e1rios difamat\u00f3rios podem ser postados. Se quiser apagar uma postagem do &#8220;F\u00f3rum de Avalia\u00e7\u00f5es de Cirurgia Est\u00e9tica&#8221;, consulte este artigo.<\/p>\n\n\n\n<p><a href=\"https:\/\/monolith.law\/reputation\/reviews-deletion-of-cosmetic-medicine-forum\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/monolith.law\/reputation\/reviews-deletion-of-cosmetic-medicine-forum[ja]<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resumo\"><\/span>Resumo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Resumimos os riscos legais associados aos sites de revis\u00e3o de cirurgia est\u00e9tica que pagam aos pacientes em troca de avalia\u00e7\u00f5es. A quest\u00e3o em discuss\u00e3o \u00e9 se isso viola a proibi\u00e7\u00e3o de taxas de refer\u00eancia na &#8216;Regra de Responsabilidade M\u00e9dica Japonesa&#8217;.<\/p>\n\n\n\n<p>A proibi\u00e7\u00e3o de taxas de refer\u00eancia inclui &#8220;fazer um desconto no valor do pre\u00e7o dos bens relacionados ao neg\u00f3cio lucrativo que a institui\u00e7\u00e3o m\u00e9dica segurada realiza de acordo com o valor da taxa recebida&#8221;. Em outras palavras, h\u00e1 uma alta probabilidade de viola\u00e7\u00e3o se um sistema de kickback for adotado.<\/p>\n\n\n\n<p>A administra\u00e7\u00e3o verifica o conte\u00fado das transa\u00e7\u00f5es entre as institui\u00e7\u00f5es m\u00e9dicas e os sites de revis\u00e3o, portanto, n\u00e3o deve incluir uma cl\u00e1usula no contrato entre as duas partes que permita a verifica\u00e7\u00e3o de kickbacks para os pacientes.<\/p>\n\n\n\n<p>Outro ponto importante \u00e9 eliminar a rela\u00e7\u00e3o entre o tratamento que o paciente recebe e a recompensa que o paciente recebe. \u00c9 perigoso adotar um sistema em que a recompensa do site de revis\u00e3o aumenta ou diminui de acordo com o valor do tratamento.<\/p>\n\n\n\n<p>Recomendamos consultar um advogado para construir um sistema adequado, pois pode ser dif\u00edcil sem conhecimento jur\u00eddico. O escrit\u00f3rio de advocacia Monolith tem advogados especializados em internet, por isso, n\u00e3o hesite em nos consultar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em sites de avalia\u00e7\u00f5es de cirurgia est\u00e9tica, s\u00e3o publicadas avalia\u00e7\u00f5es dos pacientes.Em alguns casos, o site pode pagar uma recompensa ao paciente por essas avalia\u00e7\u00f5es. Questiona-se se o ato do site d [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":59023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[21,41],"acf":[],"_links":{"self":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58737"}],"collection":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/comments?post=58737"}],"version-history":[{"count":1,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58737\/revisions"}],"predecessor-version":[{"id":59024,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/posts\/58737\/revisions\/59024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media\/59023"}],"wp:attachment":[{"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/media?parent=58737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/categories?post=58737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monolith.law\/pt\/wp-json\/wp\/v2\/tags?post=58737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}